{"id":106245,"date":"2019-02-27T20:16:39","date_gmt":"2019-02-27T19:16:39","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/omicidio-di-leo-fortuna-assolto-in-appello\/"},"modified":"2023-01-16T18:23:29","modified_gmt":"2023-01-16T17:23:29","slug":"279939-omicidio-di-leo-fortuna-assolto-in-appello","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/279939-omicidio-di-leo-fortuna-assolto-in-appello\/","title":{"rendered":"Omicidio Di Leo, Fortuna assolto in appello"},"content":{"rendered":"<h4>In primo grado era stato condannato a 30 anni di carcere. La sentenza dei giudici in appello a Catanzaro riguarda l&#8217;omicidio del 2004<!--more--><\/h4>\n<p>CATANZARO &#8211; La Corte d&#8217;assise d&#8217;appello di Catanzaro ha assolto, per non avere commesso il fatto, Francesco Fortuna, di 38 anni, imputato dell&#8217;omicidio di Domenico Di Leo, di 47 anni, avvenuto nel luglio del 2004 a Sant&#8217;Onofrio, nel vibonese. La sentenza di secondo grado ribalta totalmente la decisione emessa dal Gup di Catanzaro nel luglio 2017 con cui Fortuna era stato condannato a 30 anni. L&#8217;accusa era aggravata delle modalit\u00e0 mafiose perch\u00e9 l&#8217;imputato avrebbe agito per conto della cosca di &#8216;ndrangheta dei Bonavota.<\/p>\n<p>Le prove a carico di Fortuna non erano poche: oltre alle dichiarazioni del collaboratore di giustizia Andrea Mantella, che aveva confessato di avere partecipato all&#8217;agguato nel ruolo di autista, c&#8217;era il Dna che sarebbe stato trovato in un guanto di lattice sul luogo del delitto e, secondo l&#8217;accusa, appartenente all&#8217;imputato. Una traccia molto piccola che aveva permesso di &#8220;incastrare&#8221; Fortuna, ritenuto un killer cos\u00ec attento da nascondere in tasca perfino i mozziconi delle sigarette che fumava.<\/p>\n<p>I giudici della Corte d&#8217;assise d&#8217;appello hanno per\u00f2 ritenuto credibili le tesi dei difensori di Di Leo, gli avvocati Sergio Rotundo e Salvatore Staiano, che avevano messo in dubbio sia le dichiarazioni di Mantella che la correttezza nel trattamento del reperto contenente la particella con il Dna. Secondo l&#8217;accusa, l&#8217;omicidio di Di Leo era maturato all&#8217;interno della cosca Bonavota perch\u00e9, stando alle dichiarazioni di Mantella, la vittima aveva tentato di crearsi uno spazio autonomo all&#8217;interno del gruppo criminale. Lo stesso Di Leo, inoltre, aveva avuto incomprensioni con uno dei Bonavota per una relazione sentimentale con una parente dello stesso imputato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In primo grado era stato condannato a 30 anni di carcere. La sentenza dei giudici in appello a Catanzaro riguarda l&#8217;omicidio del 2004<\/p>\n","protected":false},"author":44,"featured_media":106246,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-106245","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/106245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=106245"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/106245\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/106246"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=106245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=106245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=106245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}