{"id":106259,"date":"2019-02-28T09:53:54","date_gmt":"2019-02-28T08:53:54","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/senzatetto-a-rischio-sgombero-sul-tetto-del-comune-di-cosenza\/"},"modified":"2023-01-16T18:23:29","modified_gmt":"2023-01-16T17:23:29","slug":"280044-senzatetto-a-rischio-sgombero-sul-tetto-del-comune-di-cosenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/280044-senzatetto-a-rischio-sgombero-sul-tetto-del-comune-di-cosenza\/","title":{"rendered":"Senzatetto a rischio sgombero sul tetto del Comune di Cosenza"},"content":{"rendered":"<h4>Palazzo dei Bruzi assediato dagli occupanti oggi minacciati di finire in strada dopo aver bonificato due strutture abbandonate<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Hanno diritto ad una casa, ma i soldi per loro non ci sono. Questa, in sintesi, \u00e8 ad oggi la risposta che hanno ricevuto dalle istituzioni gli oltre cento<span style=\"color: #0000ff;\"> <a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/6034\" target=\"_blank\" rel=\"noopener\"><em><strong>senzatetto<\/strong><\/em><\/a><\/span> minacciati di sgombero. Con la loro buona volont\u00e0 sono riusciti a bonificare stabili da anni abbandonati all&#8217;incuria e al degrado. Li hanno ripuliti e trasformati in abitazioni, trasformati in alloggi popolari che a Cosenza non vengono da anni assegnati a chi ne ha realmente bisogno. Nonostante le corruttele nella gestione dell&#8217;edilizia sociale segnalate dalla magistratura, nessuna soluzione \u00e8 stata data all&#8217;emergenza abitativa che dopo la crisi economica ha investito diverse famiglie. Chi si \u00e8 ritrovato a vivere in strada, in macchina, ospite da amici ha quindi deciso di riprendersi ci\u00f2 che gli spetta autonomamente.<strong> Le persone che vivono nell&#8217;ex sede Aterp (ente che ha il compito di garantire un tetto ai bisognosi) di via Savoia e nell&#8217;hotel Centrale di Viale Giacomo Mancini vivono in queste ore con l&#8217;incubo della minaccia di essere allontanate. <\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Uno sgombero coatto al quale per\u00f2 non seguir\u00e0 alcun tipo di ospitalit\u00e0 da parte degli enti pubblici. Per questo motivo gli occupanti insieme agli attivisti del comitato <a href=\"https:\/\/quicosenza.it\/news\/6035\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\"><em><strong>Prendocasa<\/strong> <\/em><\/span><\/a>questa mattina hanno assediato Palazzo dei Bruzi &#8216;occupando&#8217; simbolicamente il tetto della sede del Comune di Cosenza. \u00abNon usciremo fin quando non si far\u00e0 marcia indietro sugli sgomberi, gi\u00e0 programmati. Pretendiamo soluzioni dignitose, reali, concrete per tutti e non temporanee. Rimarremo ad oltranza &#8211; scrivono i manifestanti &#8211; vogliamo risposte in merito alla situazione abitativa di chi vive nell&#8217;Hotel Centrale e nello stabile di via Savoia. Le istituzioni hanno definito il piano degli sgomberi coatti ma non hanno fatto i conti con la nostra determinazione. Se Galeone,Occhiuto e Oliverio pensano di poter deportare e mettere in strada oltre cento persone, come se fossimo rifiuti, si sbagliano.\u00a0<strong>Le istituzioni sanno cosa significa dormire per strada ed essere privati di un tetto sulla testa?\u00bb.<\/strong><\/p>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-280046\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/02\/WhatsApp-Image-2019-02-28-at-10.17.11-373x280.jpeg\" alt=\"\" width=\"373\" height=\"280\" title=\"\"><\/p>\n<p style=\"text-align: center;\">\u00a0<img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-280047\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/02\/WhatsApp-Image-2019-02-28-at-10.17.15-373x280.jpeg\" alt=\"\" width=\"373\" height=\"280\" title=\"\"><\/p>\n<p style=\"text-align: right;\">Foto: Giacomo Greco<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Palazzo dei Bruzi assediato dagli occupanti oggi minacciati di finire in strada dopo aver bonificato due strutture abbandonate<\/p>\n","protected":false},"author":43,"featured_media":106260,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-106259","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/106259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=106259"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/106259\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/106260"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=106259"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=106259"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=106259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}