{"id":106261,"date":"2019-02-28T10:45:43","date_gmt":"2019-02-28T09:45:43","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/reddito-di-cittadinanza-pubblicato-sul-sito-dellinps-il-modulo-per-fare-richiesta\/"},"modified":"2023-01-16T18:23:29","modified_gmt":"2023-01-16T17:23:29","slug":"280059-reddito-di-cittadinanza-pubblicato-sul-sito-dellinps-il-modulo-per-fare-richiesta","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/280059-reddito-di-cittadinanza-pubblicato-sul-sito-dellinps-il-modulo-per-fare-richiesta\/","title":{"rendered":"Reddito di cittadinanza. Pubblicato sul sito dell&#8217;INPS il modulo per fare richiesta"},"content":{"rendered":"<h4>A partire da mercoled\u00ec 6 marzo, potr\u00e0 essere presentato il\u00a0modulo per richiedere il reddito o la pensione di cittadinanza direttamente sul sito dell&#8217;INPS, alle Poste o tramite CAF<!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>ROMA &#8211;\u00a0 <strong>Sul sito Internet dell&#8217;INPS<\/strong>\u00a0\u00e8 disponibile il modulo da compilare per la richiesta del <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/6036\" target=\"_blank\" rel=\"noopener\"><strong>reddito di cittadinanza<\/strong><\/a><\/span>.\u00a0Nella sezione &#8220;<strong>Prestazione e servizi\/ Tutti i Moduli<\/strong>&#8221; del portale in realt\u00e0 sono presenti\u00a0 tre moduli siglati\u00a0<strong><em>SR180, SR181 e SR182<\/em><\/strong>\u00a0che richiamano nel loro contenuto tutte le norme del decreto. Dei tre documenti resi disponibili, in particolare<strong> \u00e8 il modello SR180 a contenere la domanda vera e propria<\/strong> che d\u00e0 diritto al sussidio economico introdotto dal Governo che potr\u00e0 essere inviato dal 6 marzo per avere poi i primi accrediti sulle card a partire poi dal mese di Aprile.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-280063\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/02\/Inps-modulo-reddito-di-cittadinanza.jpg\" alt=\"\" width=\"559\" height=\"288\" title=\"\"><\/p>\n<p>I requisti per poter accedere al redditto di cittadina prevedono la <strong>cittadinanza italiana, europea o lungo soggiornante<\/strong> e <strong>risiedere in Italia da almeno 10 anni<\/strong>, di cui gli <strong>ultimi 2 in via continuativa<\/strong>, avere un <strong>ISEE <\/strong>(Indicatore di Situazione Economica Equivalente) <strong>aggiornato e inferiore a 9.360 euro annui<\/strong>. Esclusa la prima casa nel <strong>patrimonio immobiliare posseduto non deve superare i 30.000 euro<\/strong>. Avere un<strong> patrimonio finanziario non superiore a 6.000 euro<\/strong> che pu\u00f2 essere incrementato in funzione del numero dei componenti del nucleo familiare e delle eventuali disabilit\u00e0 presenti nello stesso. Avere un r<strong>eddito familiare inferiore a 6.000 euro annui<\/strong> moltiplicato per la scala di equivalenza. <strong>La soglia del reddito \u00e8 elevata a 9.360 euro nei casi in cui il nucleo familiare risieda in una abitazione in affitto<\/strong>.<\/p>\n<p>Per aprile sono attesi i test per la selezione dei <strong><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/5900\" target=\"_blank\" rel=\"noopener\">navigator<\/a> <\/span><\/strong>che dovranno guidare i cittadini che hanno usufruito del Reddito di Cittadinanza all&#8217;inserimento nel mondo del lavoro.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A partire da mercoled\u00ec 6 marzo, potr\u00e0 essere presentato il\u00a0modulo per richiedere il reddito o la pensione di cittadinanza direttamente sul sito dell&#8217;INPS, alle Poste o tramite CAF<\/p>\n","protected":false},"author":22,"featured_media":106262,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-106261","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/106261","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=106261"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/106261\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/106262"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=106261"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=106261"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=106261"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}