{"id":106346,"date":"2019-03-01T16:40:32","date_gmt":"2019-03-01T15:40:32","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/incendio-gomme-e-rifiuti-nel-campo-nomadi-pericolo-di-intossicazione\/"},"modified":"2023-01-16T18:23:35","modified_gmt":"2023-01-16T17:23:35","slug":"280418-incendio-gomme-e-rifiuti-nel-campo-nomadi-pericolo-di-intossicazione","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/280418-incendio-gomme-e-rifiuti-nel-campo-nomadi-pericolo-di-intossicazione\/","title":{"rendered":"Incendio gomme e rifiuti nel campo nomadi: Pericolo di intossicazione"},"content":{"rendered":"<h4>Ennesimo incendio nel campo nomadi in localit\u00e0 Scordovillo nel territorio di Lamezia Terme, ha coinvolto pneumatici e rifiuti di vario tipo\u00a0<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>LAMEZIA TERME (CS) &#8211; Squadre dei vigili del fuoco del distaccamento di Lamezia Terme e della sede Centrale di Catanzaro con il supporto di autobotte sono impegnate in Localit\u00e0 Scordovillo presso accampamento nomadi per l&#8217;ennesimo incendio di cataste di gomme e quintali di rifiuti solidi di vario genere. La grossa fumata nera visibile anche a chilometri di distanza ha subito creato disagi al vicino ospedale ed alle abitazioni della zona.<\/p>\n<p>Numerose sono state le chiamate giunte presso la Sala Operativa del comando provinciale dei vigili del fuoco. Attualmente non si registrano persone ferite o intossicati.<br \/>\nSul posto i carabinieri e polizia locale hanno scortato all&#8217;entrata dell&#8217;accampamento le squadre del 115 permettendo l&#8217;espletarsi dell&#8217;intervento in totale sicurezza. Attualmente oltre 15 unit\u00e0 dei vigili del fuoco e 4 automezzi sono all&#8217;opera per le operazioni di spegnimento<\/p>\n<p>In supporto ai vigili del fuoco, per agevolare l&#8217;opera di spegnimento, \u00e8 giunto sul posto un mezzo meccanico da cantiere (messo a disposizione dalla Cooperativa Sociale Malgrado Tutto di Lamezia Terme) per lo smassamento delle cataste di rifiuti.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-280430\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/03\/ceaf582e-32d7-41ab-b816-da3314b90d66.jpg\" alt=\"\" width=\"900\" height=\"675\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-280431\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/03\/f9321ecf-6815-4bc8-95b4-5717f4009548.jpg\" alt=\"\" width=\"756\" height=\"1290\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-280429\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/03\/c3ad100e-93bc-4c3c-97b4-42ef67efabb0.jpg\" alt=\"\" width=\"900\" height=\"1199\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-280428\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/03\/bdf38313-e794-4322-b1bc-d6a89e29faeb.jpg\" alt=\"\" width=\"900\" height=\"1200\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-280427\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/03\/3992fe06-e544-40d5-bb0a-c72ca7b6a3eb.jpg\" alt=\"\" width=\"900\" height=\"674\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-280426\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/03\/3403ab5c-40b6-453f-9025-6f812dd19c1a.jpg\" alt=\"\" width=\"1600\" height=\"898\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ennesimo incendio nel campo nomadi in localit\u00e0 Scordovillo nel territorio di Lamezia Terme, ha coinvolto pneumatici e rifiuti di vario tipo\u00a0<\/p>\n","protected":false},"author":44,"featured_media":106347,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-106346","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/106346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=106346"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/106346\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/106347"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=106346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=106346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=106346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}