{"id":106364,"date":"2019-03-02T07:00:00","date_gmt":"2019-03-02T06:00:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/ce-intesa-sulla-trasversale-del-tirreno-pollino\/"},"modified":"2023-01-16T18:23:36","modified_gmt":"2023-01-16T17:23:36","slug":"280475-ce-intesa-sulla-trasversale-del-tirreno-pollino","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/280475-ce-intesa-sulla-trasversale-del-tirreno-pollino\/","title":{"rendered":"C\u2019\u00e8 intesa sulla trasversale del Tirreno &#8211; Pollino"},"content":{"rendered":"<h4>Firmato il protocollo d\u2019intesa tra Mormanno ed Orsomarso per la trasversale del Tirreno &#8211; Pollino<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>MORMANNO &#8211; Il vicesindaco di Mormanno,<strong> Paolo Pappaterra<\/strong>, ed il sindaco di Orsomarso, <strong>Antonio De Caprio<\/strong>, hanno siglato le intenzioni programmatiche per la realizzazione dell&#8217;arteria di collegamento tra <strong>Tirreno e Pollino<\/strong>. \u00abUn sogno che inizia a prendere forma\u00bb ed al quale nei prossimi giorni si unir\u00e0 uno studio di fattibilit\u00e0 da presentare agli organi competenti per trovare le risorse necessarie perch\u00e9 presto si trasformi in realt\u00e0.\u00a0\u00ab\u00c8 un&#8217;opera strategica per il turismo &#8211; ha dichiarato Paolo Pappaterra, vicesindaco di Mormanno &#8211; il collegamento delle aree interne con due bacini importanti della Calabria settentrionale, c\u2019\u00e8 la volont\u00e0 di costruire un quadro d&#8217;insieme di sviluppo e mobilit\u00e0 che arriva dal basso, ascoltando le esigenze dei territori che siamo chiamati a rappresentare e la loro voglia di strutturare percorsi nuovi che abbiano la capacit\u00e0 di guardare oltre i confini campanilistici\u00bb. Ora il progetto avr\u00e0 bisogno di essere costruito e strutturato con uno studio di fattibilit\u00e0 che lo possa candidare ai finanziamenti pubblici con la forza propositiva che merita.\u00a0 \u00abAmministrare la cosa pubblica &#8211; ha commentato Pappaterra &#8211; ci pone davanti alla necessit\u00e0 di pensare a grandi sogni da realizzare da lasciare in eredit\u00e0 alle prossime generazioni. Da una stretta di mano di qualche settimana fa, siamo passati in breve tempo alla firma del Protocollo d\u2019Intesa per la grande trasversale <strong>Tirreno \u2013 Pollino<\/strong>\u00bb. Un\u2019opera infrastrutturale che punta alla riqualificazione della rete stradale, alla messa in sicurezza, alla grande possibilit\u00e0 di sviluppo economico che potr\u00e0 interessare tutto l\u2019Alto Tirreno Cosentino ed il Pollino.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Firmato il protocollo d\u2019intesa tra Mormanno ed Orsomarso per la trasversale del Tirreno &#8211; Pollino<\/p>\n","protected":false},"author":47,"featured_media":106365,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-106364","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/106364","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/47"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=106364"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/106364\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/106365"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=106364"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=106364"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=106364"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}