{"id":106458,"date":"2019-03-04T16:00:53","date_gmt":"2019-03-04T15:00:53","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/colori-e-maschere-a-san-lucido-per-il-carnevale-estivo\/"},"modified":"2023-01-16T18:23:42","modified_gmt":"2023-01-16T17:23:42","slug":"280839-colori-e-maschere-a-san-lucido-per-il-carnevale-estivo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/280839-colori-e-maschere-a-san-lucido-per-il-carnevale-estivo\/","title":{"rendered":"Colori e maschere a San Lucido per il Carnevale"},"content":{"rendered":"<h4>Successo per il Carnevale di San Lucido. Nel piccolo centro tirrenico cosentino una domenica tra colori e maschere.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>SAN LUCIDO (CS) &#8211; Domenica di Carnevale colorata e ricca di emozioni quella di ieri a San Lucido dove si \u00e8 svolto il \u201cCarnevale\u201d. L\u2019evento ha registrato un buon successo con la partecipazione di molte persone provenienti non solo da paesi vicini, ma anche da altre province della Calabria. Nel corso del Carnevale hanno sfilato <strong>7 carri<\/strong> allegorici, realizzati dalle varie associazioni e gruppi delle principali zone del paese tra cui il comitato 2003, il gruppo di Acquabianca, il gruppo del Varco, il gruppo di San Giovanni.<\/p>\n<p>Il tutto accompagnato dalle coreografie delle scuole di danza del centro tirrenico come Dancing Stars Academy, L\u2019ecole de la vie, e delle associazioni\/ludoteche di San Lucido, &#8220;Alla ricerca di Nemo&#8221;, &#8220;Hakuna matata. Grande successo e partecipazione per lo spettacolo musicale di \u201cAntonio Grosso School &amp; Francesco Gullo\u201d. Soddisfazione \u00e8 stata espressa dall&#8217;assessore comunale allo sport, turismo e spettacolo Emy Ambrosi.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-280849 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/03\/carnevale-san-lucido-03.jpg\" alt=\"\" width=\"626\" height=\"387\" title=\"\"><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-280848 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/03\/carnevale-san-lucido-02.jpg\" alt=\"\" width=\"620\" height=\"374\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Successo per il Carnevale di San Lucido. Nel piccolo centro tirrenico cosentino una domenica tra colori e maschere.<\/p>\n","protected":false},"author":42,"featured_media":106459,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28,576],"tags":[],"class_list":["post-106458","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","category-tirreno"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/106458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=106458"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/106458\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/106459"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=106458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=106458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=106458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}