{"id":106518,"date":"2019-03-05T15:26:45","date_gmt":"2019-03-05T14:26:45","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/protezione-civile-vertice-con-borrelli-alla-base-prevenzione-e-informazione\/"},"modified":"2023-01-16T18:23:45","modified_gmt":"2023-01-16T17:23:45","slug":"281036-protezione-civile-vertice-con-borrelli-alla-base-prevenzione-e-informazione","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/281036-protezione-civile-vertice-con-borrelli-alla-base-prevenzione-e-informazione\/","title":{"rendered":"Protezione civile, vertice con Borrelli: &#8220;sedi strutturate, prevenzione e informazione&#8221;"},"content":{"rendered":"<h4>Il capo della Protezione Civile nazionale, Angelo Borrelli, questa mattina, ha presieduto nella prefettura di Catanzaro, un vertice sulla proposta di rivisitazione dei Centri operativi misti.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>CATANZARO &#8211; Al vertice hanno partecipato, tra gli altri, i prefetti delle cinque province della Regione: Francesca Ferrandino (Catanzaro), Paola Galeone (Cosenza), Fernando Guida (Crotone), Michele di Bari (Reggio Calabria) e Giuseppe Gualtieri (Vibo Valentia); il vicepresidente della Regione, Francesco Russo, il direttore generale della Protezione civile regionale, Domenico Pallaria, e il direttore regionale dei Vigili del fuoco, Marco Ghimenti. Borrelli \u00e8 intervenuti in primo luogo sulle sedi di protezione civile: &#8220;Avere <strong>sedi<\/strong> individuate preventivamente, strutturate e gi\u00e0 operative immediatamente in<strong> caso di emergenza<\/strong> \u00e8 fondamentale per dare una risposta immediata alla popolazione. Siamo partiti dalla Calabria \u2013 ha spiegato Borrelli &#8211; facendo anche un progetto europeo di <strong>standardizzazione della macchina della gestione dei soccorsi e della prevenzione<\/strong>. I Centri operativi misti, ovviamente, saranno i luoghi di coordinamento&#8221;.<\/p>\n<p>&#8220;La scorsa settimana \u00e8 stato varato il piano straordinario dal Governo, che ha stanziato risorse adeguate anche per gi interventi di prevenzione strutturale. Bisogna sempre lavorare \u2013 ha sostenuto il capo della Protezione civile &#8211; sulla prevenzione, bisogna investire sulla manutenzione del territorio e ovviamente lavorare sulla macchina organizzativa, ed \u00e8 quello che stiamo facendo oggi in Calabria. Ringrazio la Regione, i prefetti della Calabria e i Vigili del Fuoco perch\u00e9 \u2013 ha aggiunto Borrelli &#8211; stanno portando avanti in questa regione questa opera di organizzazione e di efficientamento di una macchina che speriamo di non dover mai mettere in campo\u201d.<\/p>\n<p>Secondo il capo della Protezione civile, inoltre, \u201cla condizione per restituire un&#8217;efficace informazione di allerta ai cittadini \u00e8 partire dai Piani comunali di protezione civile, anche se il nostro obiettivo \u00e8 avere piani territoriali e di ambito e di migliorare il sistema di allertamento con una sorta di auto-apprendimento che \u2013 ha affermato Borrelli &#8211; restituisca un\u2019informazione puntuale ai cittadini. Bisogna lavorare sulla <strong>prevenzione<\/strong>, intervenire sulla <strong>manutenzione<\/strong> nel territorio e, ovviamente, impegnarsi<strong> sulla macchina organizzativa&#8221;.<\/strong><\/p>\n<p>Borrelli ha poi spiegato come sia stato &#8220;avviato un percorso per la realizzazione di una piattaforma nazionale di allertamento della popolazione perch\u00e9 molto pu\u00f2 essere fatto a livello centralizzato. Questa \u00e8 una piattaforma che parte dal centro e arriva sulla periferia e d\u00e0 la possibilit\u00e0 anche ai singoli sindaci e a chi gestisce il territorio di poter diramare delle allerta a livello locale. \u00c8 un mix tra un allertamento nazionale e uno locale&#8221;.<\/p>\n<p>&#8220;Stiamo intervenendo anche con un sistema normativo &#8211; ha aggiunto il Capo della Protezione civile nazionale &#8211; per poter modificare il codice delle comunicazioni digitali. Sar\u00e0 un sistema che utilizza la tecnologia dei telefonini perch\u00e9 \u00e8 stato stimato che ci sono 49 milioni di telefonini nel nostro Paese e noi partiremo da l\u00ec dalle celle telefoniche, per mandare messaggi di allertamento, per poi passare a delle app che daranno delle informazioni localizzate proprio nel luogo in cui la persona si trova,<strong> attraverso il gps&#8221;.<\/strong><\/p>\n<p><strong>Importanti sono i Piani comunali di Protezione civile:<\/strong>\u00a0&#8220;La condizione per restituire un&#8217;efficace informazione e allerta ai cittadini &#8211; ha sostenuto Borrelli &#8211; \u00e8 partire da un Piano comunale di Protezione civile. Il presupposto per la nostra piattaforma nazionale di allertamento, e per la app, \u00e8 avere dei Piani comunali di Protezione civile, dei Piani territoriali, dove sono indicati quelli che sono i fenomeni che si sono verificati nel corso del tempo. Perch\u00e9 questo <strong>sistema di allertamento<\/strong> possa migliorare con una sorta di autoapprendimento mandando a reperire le informazioni che ci sono sui Piani comunali di Protezione civile, restituendo una informazione puntuale ai cittadini&#8221;.<\/p>\n<h3>&#8220;Creare accademie di protezione civile&#8221;<\/h3>\n<p>&#8220;A livello nazionale andiamo bene cos\u00ec. Le risorse ci sono, i fondi ci sono, il personale c&#8217;\u00e8. Dobbiamo lavorare su alcuni punti, come l&#8217;allertamento, ma anche sulla diffusione della conoscenza, con la diffusione della cultura di Protezione civile che stiamo portando avanti nelle scuole&#8221;. Lo ha detto il Capo della Protezione civile nazionale Angelo Borrelli. &#8220;Bisogna creare delle accademie di Protezione civile &#8211; ha aggiunto &#8211; dove si possa formare chi lavora nelle Prefetture, nei Comuni e nelle Regioni, ma anche chi studia all&#8217;Universit\u00e0, che potrebbe cos\u00ec avere dei crediti formativi&#8221;.<\/p>\n<h4>Borrelli ringrazia Tansi ma sottolinea: &#8220;nessun problea di operativit\u00e0&#8221;<\/h4>\n<p>Alla Protezione Civile della Regione Calabria \u201cnon ci sono problemi di operativit\u00e0\u201d. Borrelli, ha risposto cos\u00ec ai giornalisti a margine dell&#8217;incontro a Catanzaro ad una domanda sulle recenti polemiche che hanno riguardato il settore a livello regionale, Borrelli ha osservato: \u201cC\u2019\u00e8 una persona di riferimento, il direttore generale Domenico Pallaria, con cui ho gi\u00e0 lavorato in passato e con cui siamo in continuo e costante contatto. Quindi, non ci sono problemi di operativit\u00e0. Carlo Tansi \u00e8 stato un grande direttore, una persona e un funzionario qualificato anche sotto il profilo tecnico. Lo voglio ringraziare \u2013 ha concluso il capo della Protezione civile nazionale &#8211; per l\u2019opera che ha fatto in questo territorio\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il capo della Protezione Civile nazionale, Angelo Borrelli, questa mattina, ha presieduto nella prefettura di Catanzaro, un vertice sulla proposta di rivisitazione dei Centri operativi misti.<\/p>\n","protected":false},"author":42,"featured_media":106519,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-106518","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/106518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=106518"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/106518\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/106519"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=106518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=106518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=106518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}