{"id":106548,"date":"2019-03-06T10:28:32","date_gmt":"2019-03-06T09:28:32","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/boscaioli-clandestini-nel-cosentino-abbattono-oltre-300-piante\/"},"modified":"2023-01-16T18:23:48","modified_gmt":"2023-01-16T17:23:48","slug":"281159-boscaioli-clandestini-nel-cosentino-abbattono-oltre-300-piante","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/281159-boscaioli-clandestini-nel-cosentino-abbattono-oltre-300-piante\/","title":{"rendered":"Boscaioli abusivi nel cosentino abbattono oltre 300 piante"},"content":{"rendered":"<h4>I tre sono stati rintracciati in un bosco del Tirreno cosentino dopo aver gi\u00e0 tagliato decine di alberi<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>SCALEA (CS) &#8211; Tagli selvaggi ed indiscriminati. I boschi del Cosentino continuano ad essere vittima di boscaioli clandestini che danneggiano l&#8217;ambiente a scopo di lucro. Nelle ultime ore sono tre persone denunciate in stato di libert\u00e0 dai carabinieri forestali di Scalea per taglio abusivo aggravato, realizzazione di pista abusiva e furto in area demaniale e privata. I militari, durante un controllo in localit\u00e0 Sant&#8217;Anario di Grisolia, hanno accertato che i lavori di taglio non erano stati eseguiti correttamente. In particolare, <strong>le tre persone che hanno effettuato il taglio avevano sconfinato in altre propriet\u00e0 private e lungo una zona a margine del fiume Abatemarco,<\/strong> area di propriet\u00e0 demaniale e vincolata. Sono state tagliate abusivamente 301 piante di specie di Ontano, Cerro, Orniello e Leccio. Inoltre \u00e8 stata aperta abusivamente una strada per l&#8217;esbosco del materiale legnoso di 400 metri. L&#8217;area \u00e8 stata posta sotto sequestro e sono stati elevati 24.600 euro di sanzione amministrativa.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-281231\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/03\/grisolia1-373x280.jpg\" alt=\"\" width=\"373\" height=\"280\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right;\">\n","protected":false},"excerpt":{"rendered":"<p>I tre sono stati rintracciati in un bosco del Tirreno cosentino dopo aver gi\u00e0 tagliato decine di alberi<\/p>\n","protected":false},"author":43,"featured_media":106549,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28,576],"tags":[],"class_list":["post-106548","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","category-tirreno"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/106548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=106548"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/106548\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/106549"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=106548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=106548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=106548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}