{"id":106570,"date":"2019-03-06T14:25:36","date_gmt":"2019-03-06T13:25:36","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/la-lettera-commerciante-via-rossini-comitati-contro-la-movida-ci-stanno-rovinando\/"},"modified":"2023-01-16T18:23:50","modified_gmt":"2023-01-16T17:23:50","slug":"281260-la-lettera-commerciante-via-rossini-comitati-contro-la-movida-ci-stanno-rovinando","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/281260-la-lettera-commerciante-via-rossini-comitati-contro-la-movida-ci-stanno-rovinando\/","title":{"rendered":"Lo sfogo di una commerciante via Rossini: \u00abvogliono farci chiudere, per favorire chi?\u00bb"},"content":{"rendered":"<h4>Una commerciante ci scrive per manifestare la sua preoccupazione circa l&#8217;opera dei comitati che minano il prosieguo delle attivit\u00e0 commerciali su via Rossini a Rende, un tempo frequentata e vissuta appieno. Oggi ridotta a poche presenze<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>RENDE &#8211; &#8220;Chi scrive lo fa perch\u00e9, ancor prima di iniziare la sua attivit\u00e0 Llavorativa, gi\u00e0 sentiva la pressione di una condizione difficile e difficilmente gestibile poich\u00e9 cozza, non solo con la prepotenza di alcuni cittadini, ma, cosa ben pi\u00f9 grave, con una presa di potere da parte di <strong>presunti comitati<\/strong> che vantano tra le loro fila, rappresentanti delle forze dell\u2019ordine che ostentano questa loro appartenenza, arrivando quasi a minacciare di &#8220;far chiudere&#8221; tutte le attivit\u00e0 di Via Rossini. Una via che doveva essere del commercio e della movida, nata per questo&#8221;.<\/p>\n<p>&#8220;Espongo i fatti e le dovute considerazioni premettendone una: la <strong>responsabilit\u00e0<\/strong> della decadenza di via Rossini <strong>non \u00e8 dovuta a questa amministrazione<\/strong> che \u00e8 stata, con noi esercenti, efficiente e disponibile. La responsabilit\u00e0 del fallimento dell\u2019idea fondante la nascita di questo meraviglioso chilometro \u00e8 di alcuni cittadini evidentemente frustrati e prepotenti che credevano di aver acquistato la loro abitazione in periferia&#8221;.<\/p>\n<p>&#8220;La mia attivit\u00e0 &#8211; prosegue la commerciante &#8211; \u00e8 un punto di ritrovo per i giovani rendesi ed io, previa raccolta delle dovute autorizzazioni, organizzo una, e sottolineo una sola volta a settimana, un momento musicale, all\u2019interno del mio locale e fino ad un orario estremamente conciliabile con gli impegni di una seguente domenica mattina, per offrire ai miei fruitori una piacevole e giusta attrattiva per frequentare ulteriormente il mio locale e, quindi, lavorare. Per<strong> ben sei volte ho gi\u00e0 \u201csubito\u201d l\u2019intervento delle forze dell\u2019ordine<\/strong> che, una volta visionati i permessi in mio possesso, hanno chiaramente, desistito dal compiere ogni azione nei nostri confronti&#8221;.<\/p>\n<h3>I giovani danno fastidio ma i &#8220;centri massaggi&#8221; a luci rosse no!<\/h3>\n<p>&#8220;Ad oggi mi giungono \u201cvoci\u201d e non solo, di <strong>azioni ben pi\u00f9 gravi e lesive<\/strong> che, questi <strong>pseudo comitati<\/strong>, stanno compiendo nei nostri confronti al fine di \u201c<strong>farci chiudere tutti<\/strong>\u201d (cit.) ed a ogni costo. Anche quello di provocare esasperazione e danno economico a chi vuole solo lavorare onestamente in un quartiere creato per accogliere i giovani, la cosiddetta\u201d movida\u201d e che d\u00e0 lavoro a molti rendesi&#8221;.<\/p>\n<p>&#8220;Ora mi chiedo se queste persone avvertano minimamente il peso dell\u2019aver, gi\u00e0 una volta, ammazzato l\u2019economia di via Rossini e di reiterare quell\u2019atteggiamento ricavandone un piacere quasi perverso nel farlo. La <strong>musica<\/strong> e i <strong>giovani<\/strong> che si divertono in modo sano, sembra dargli fastidio, mentre tollerano apparentemente compiaciuti, la presenza di numerosi \u201c<strong>centri massaggi<\/strong>\u201d attivi ad ogni ora del giorno e della notte <strong>negli appartamenti attigui ai loro&#8221;.<\/strong><\/p>\n<p><strong>&#8220;A queste famiglie risulta pi\u00f9 invasiva la pratica del sano divertimento piuttosto che quella del &#8216;mestiere pi\u00f9 antico del mondo&#8217; chiaramente ostacolato dalle 22:00 alle 02:00, dall\u2019afflusso di giovani nei locali della via&#8221;.<\/strong><\/p>\n<h3>Un comitato di esercenti<\/h3>\n<p>&#8220;Preso atto di questa condizione in cui taluni cittadini, stazionano e vivono &#8211; conclude la commerciante di via Rossini &#8211; ho deciso di fondare un <strong>comitato degli esercenti<\/strong> e, con esso, intraprendere ogni via legale possibile per tutelarci. Da oggi non saranno pi\u00f9, dalla sottoscritta, tollerate minacce, insulti e dispetti. Da oggi intendo far valere, in ogni sede deputata, il mio diritto a lavorare, nel rispetto delle regole e del prossimo, pure di quelli che, anche con le mie tasse, percepiscono il loro stipendio&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una commerciante ci scrive per manifestare la sua preoccupazione circa l&#8217;opera dei comitati che minano il prosieguo delle attivit\u00e0 commerciali su via Rossini a Rende, un tempo frequentata e vissuta appieno. Oggi ridotta a poche presenze<\/p>\n","protected":false},"author":21,"featured_media":106571,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[44],"tags":[],"class_list":["post-106570","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/106570","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=106570"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/106570\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/106571"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=106570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=106570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=106570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}