{"id":106586,"date":"2019-03-06T18:16:38","date_gmt":"2019-03-06T17:16:38","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/rende-politica-troppa-confusione-serve-un-confronto-con-i-cittadini\/"},"modified":"2023-01-16T18:23:50","modified_gmt":"2023-01-16T17:23:50","slug":"281335-rende-politica-troppa-confusione-serve-un-confronto-con-i-cittadini","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/281335-rende-politica-troppa-confusione-serve-un-confronto-con-i-cittadini\/","title":{"rendered":"Rende, politica: &#8220;troppa confusione, serve un confronto con i cittadini&#8221;"},"content":{"rendered":"<h4>A seguito dell&#8217;incontro tra i quattro movimenti \u00e8 emersa la comune determinazione di tutta la coalizione di formulare le proposte e, dunque, di sottoporle direttamente alla cittadinanza<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>RENDE (CS) &#8211; \u00abA Rende il quadro politico, almeno ai cittadini, non appare chiaro e anzich\u00e9 fare chiarezza si rischia di alimentare ulteriore confusione. E\u2019 superfluo dire che generare confusione \u00e8 utile ad avvantaggiare qualcuno, non solo tra gli opposti schieramenti di maggioranza e minoranza, ma anche all\u2019interno degli stessi. La confusione, del resto, \u00e8 la condizione migliore in cui possa sperare chi, in politica, sceglie di giocare in difesa, magari sperando di poter poi segnare in contropiede\u00bb. A scrivere \u00e8 la coalizione politica\u00a0Rende cambia Rende, La Terza Rende, Idee in Circolo, Italia del Meridione<\/p>\n<p>\u00abPer generare confusione a Rende si dice una cosa, poi un&#8217;altra, poi si smentisce e poi tutto torna al punto di partenza, si ipotizzano alleanze, poi altre, poi altre ancora, sia da una parte che dall&#8217;altra. Si parla di tutto a Rende, ma si dice ancora poco o nulla di quello che il cittadino, di qualunque appartenenza, avrebbe il diritto di sapere per valutare e per scegliere con consapevolezza e non per tifoseria d\u2019appartenenza.<\/p>\n<p>La politica, dunque, continua a parlare a se stessa soltanto in questi mesi, anche se \u00e8\u00a0 chiaro a tutti che non c&#8217;\u00e8\u00a0 pi\u00f9 tempo. E\u2019 necessario parlare alla gente, certo la cittadinanza vuole anche i nomi dei candidati dei vari schieramenti &#8211; anche questo \u00e8 molto importante &#8211; ma ha soprattutto bisogno di confrontarsi con loro sulla visione che hanno, sulla Rende che vogliono, sul futuro pi\u00f9 che altro. E\u2019 il futuro il terreno del confronto che i cittadini reclamano per scegliere in quale direzione \u00e8 pi\u00f9 giusto andare, \u00e8 ci\u00f2 su cui si pu\u00f2 fare sintesi nell\u2019interesse di Rende che vogliono innanzitutto sapere, poi anche i nomi dei candidati, non per curiosit\u00e0 ma\u00a0 per valutare la credibilit\u00e0 della proposte di cui ognuno si far\u00e0 portatore. E\u2019 evidente che la politica cittadina non pu\u00f2 pi\u00f9 sottrarsi a questo dovere.<\/p>\n<p>Il percorso sarebbe stato pi\u00f9 agevole per tutti se non ci fossero state riserve mentali o esigenze particolari da soddisfare, i passaggi necessari sarebbero stati semplici, prima il progetto di massima, poi eventualmente l\u2019alleanza e poi anche il nome del candidato che di quel progetto e di quella alleanza deve essere interprete ed il garante allo stesso tempo. Per fare questi passaggi cos\u00ec come non ci devono essere pregiudiziali\u00a0 personali, neppure ci devono essere tatticismi dilatori e riserve mentali, occorre un approccio schietto sulla proposta che ciascuno ritiene sia meglio formulare,e poi anche avere il tempo di superare eventuali divergenze e lavorare su ci\u00f2 che pu\u00f2 unire per elaborare una proposta che sia frutto di un apporto paritario e collettivo.<\/p>\n<p>Noi \u00e8 questo il metodo che abbiamo sempre proposto, ed \u00e8 questo il metodo che abbiamo praticato al nostro interno, cos\u00ec facendo abbiamo raccolto la disponibilit\u00e0 al confronto schietto dei nostri quattro movimenti, lavorando insieme ci siamo uniti e facendo sintesi abbiamo creato la nostra coalizione.<\/p>\n<p>Ci siamo scambiati le idee di massima, abbiamo ragionato sulle proposte da formulare a Rende, abbiamo discusso, ci siamo confrontati e pur avendo diverse altrettanto valide alternative, siamo giunti anche all\u2019indicazione del nome da proporre alla cittadinanza, perch\u00e9 si faccia interprete e garante della nostra visione della realt\u00e0 delle cose e del futuro a Rende. C\u2019\u00e8 voluto uno slancio di coraggio evidentemente, ce ne siamo assunti il rischio &#8211; la politica tradizionale \u00e8 evidentemente pi\u00f9 prudente &#8211; ha altri tempi e altri bisogni, ma per quanto ci riguarda abbiamo fatto quello che ci eravamo promessi di fare, confrontarci con tutti per tempo e senza riserve mentali, avendo come unico orizzonte Rende, e Rende rimane.<\/p>\n<p>Sappiamo di aver fatto il possibile non il meglio magari, ma forti di come ci siamo arrivati e sapendo chi siamo, \u00e8 certo che faremo quello che ci siamo impegnati a fare e offriremo alla valutazione dei rendesi la nostra migliore offerta, la nostra visione. Eravamo e siamo convinti che sia questa la pi\u00f9 importante partita per Rende e si vince solo se questa volta sapremmo accettarla a viso aperto &#8211; una volta per tutte e fino in fondo &#8211; la sfida del futuro che abbiamo davanti, tutti quanti\u00bb.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A seguito dell&#8217;incontro tra i quattro movimenti \u00e8 emersa la comune determinazione di tutta la coalizione di formulare le proposte e, dunque, di sottoporle direttamente alla cittadinanza<\/p>\n","protected":false},"author":37,"featured_media":106587,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[44],"tags":[],"class_list":["post-106586","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/106586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=106586"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/106586\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/106587"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=106586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=106586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=106586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}