{"id":106600,"date":"2019-03-07T10:00:02","date_gmt":"2019-03-07T09:00:02","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/festa-della-donna-4-0-a-cosenza-la-salute-al-centro-del-dibattito-programma\/"},"modified":"2023-01-16T18:23:52","modified_gmt":"2023-01-16T17:23:52","slug":"281387-festa-della-donna-4-0-a-cosenza-la-salute-al-centro-del-dibattito-programma","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/281387-festa-della-donna-4-0-a-cosenza-la-salute-al-centro-del-dibattito-programma\/","title":{"rendered":"Festa della donna 4.0 a Cosenza, la salute al centro del dibattito (PROGRAMMA)"},"content":{"rendered":"<h4>Durante l&#8217;incontro, alla presenza della sezione di Cosenza dell&#8217;Associazione Nazionale degli Insigniti al Merito della Repubblica Italiana sar\u00e0 donato un ecografo portatile all&#8217;AVIS<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Festa della donna a Cosenza. Al centro del dibattito la salute femminile protagonista della Festa della Donna 4.0 organizzata grazie alla collaborazione tra Avis Cosenza, liceo scientifico Pitagora di Rende, la sezione di Cosenza dell&#8217;Associazione Nazionale Insigniti al Merito della Repubblica Italiana, la FNISM Federazione Nazionale degli Insegnanti, l&#8217;Asp di Cosenza e l&#8217;Azienda Ospedaliera di Cosenza. Domani mattina, venerd\u00ec 8 marzo 1019, l&#8217;aula magna del liceo scientifico Pitagora Rende in via Pertini ospiter\u00e0 un incontro tra studenti, genitori, docenti, personale scolastico ed esperti sul tema &#8216;L&#8217;importanza della donazione di sangue nell&#8217;ambito della prevenzione delle principali patologie genetiche, tumorali e sessualmente trasmissibili&#8217;. L&#8217;evento sar\u00e0 aperto da Alisia Arturi dirigente scolastico del liceo scientifico Pitagora, mentre fungeranno da moderatori il giornalista Valerio Capparelli e il segretario provinciale dell&#8217;Avis Cosenza Pier Francesco Bruno. Ai microfoni interverranno Ennio Avolio biologo nutrizionista presidente dell&#8217;Associazione Scientifica Biologi Calabresi, Rocco Chiritano presidente regionale Avis, Sisto Milito oncologo dell&#8217;Asp di Cosenza responsabile del progetto screening tumore della mammella dell&#8217;Avis provinciale di Cosenza, Antonio Tavernise presidente provinciale Avis Cosenza e Franco Zinno direttore servizio trasfusionale dell&#8217;Azienda Ospedaliere di Cosenza. <strong>Durante l&#8217;incontro, alla presenza dell&#8217;ufficiale Angelo Cosentino, presidente\u00a0della sezione di Cosenza dell&#8217;Associazione Nazionale degli Insigniti al Merito della Repubblica Italiana, e del portavoce cavaliere Pasquale Giardino, sar\u00e0 donato un ecografo portatile all&#8217;AVIS provinciale.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Il dibattito sulla salute femminile proseguir\u00e0 nel pomeriggio nel Salone degli Specchi del Palazzo della Provincia in piazza XV Marzo a partire dalle 16:00. <strong>Sar\u00e0 un confronto tra professioni e cittadinanza sul &#8216;Percorso diagnostico &#8211; terapeutico &#8211; assistenziale (PDTA) del carcinoma mammario in provincia di Cosenza&#8217;.<\/strong> L&#8217;evento sar\u00e0 introdotto dal presidente della Provincia di Cosenza Franco Iacucci, dal sindaco di Cosenza Mario Occhiuto, la responsabile del settore Rischio Clinico dell&#8217;Azienda Ospedaliera di Cosenza Maria Dolores Vantaggiato, il primario del reparto di Medicina Interna degli Ospedali di Rossano Corigliano Luigi Muraca, il direttore sanitario delle cliniche iGreco Mario Sprovieri, il primario del reparto di Oncologia dell&#8217;Ospedale di Paola e il giornalista Valerio Capparelli che moderer\u00e0 gli interventi. Dalle 16:30 alle 17:30 \u00e8 prevista una tavola rotonda sulla prevenzione e la diagnosi precoce del carcinoma mammario che sar\u00e0 aperta dal primario di Radiologia dell&#8217;Annunziata Alfredo Zanolini seguito dal responsabile del reparto di Oncologia dell&#8217;Ospedale di Cosenza Serafino Conforti, della responsabile degli screening oncologici e del registro tumori dell&#8217;Asp di Cosenza Anna Giorno, di un medico radiologo specialista ambulatoriale dell&#8217;Asp di Cosenza Francesco Lanzone e dallo specialista in Radiologia Giovanni Perri.\u00a0La seconda sessione di lavori avr\u00e0 come oggetto &#8216;Il carcinoma mammario dalla diagnosi al trattamento&#8217; con il dirigente medico della Chirurgia Senologica dell&#8217;Azienda Ospedaliera di Cosenza Andrea Lorenzo Valente che parler\u00e0 della chirurgia onco-plastica dai principi della radicalit\u00e0 oncologica al rispetto della femminilit\u00e0.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Francesco Mollo chirurgo senologo della clinica privata &#8216;La Madonnina&#8217; del gruppo iGreco relazioner\u00e0 sullo stato dell&#8217;arte del percorso diagnostico terapeutico assistenziale della mammella e del linfonodo sentinella. <strong>Alle 18:00 l&#8217;oncologo dell&#8217;Ospedale di Cosenza Rosalbino Biamonte illustrer\u00e0 il percorso diagnostico terapeutico assistenziale del tumore alla mammella seguito all&#8217;Annunziata.\u00a0<\/strong>L&#8217;oncologa dell&#8217;Ospedale di Paola Virginia Olivito spiegher\u00e0 in cosa consiste la terapia adiuvante del tumore alla mammella HER2+. L&#8217;impatto socio economico della malattia tumorale e la rete di assistenza sociale sar\u00e0 discusso a partire dalle riflessione del primario del reparto di Radioterapia del Mariano Santo di Cosenza Luigi Marafioti e dalla dottoressa Monica Loizzo dell&#8217;Azienda Ospedaliera di Cosenza. L&#8217;avvocato civilista del Foro di Cosenza Antonella Tiano spiegher\u00e0 il sistema previdenziale nell&#8217;ambito delle patologie oncologiche, la presidente dell&#8217;associazione Lotta ai Tumori Anna Maria Rende si occuper\u00e0 del lavoro delle associazioni di volontariato nella rete dell&#8217;assistenza dei malati oncologici, mentre la presidente della sezione di Cosenza dell&#8217;associazione Salute Donna relazioner\u00e0 sul ruolo del volontariato a sostegno del percorso senologico. La psicologa psicoterapeuta esperta in Neuropsicologia che opera all&#8217;interno della clinica privata La Madonnina del gruppo iGreco sottolineer\u00e0 l&#8217;importanza della comunicazione nel rapporto tra medico e paziente. A chiudere la giornata dedicata alla salute sala la psicologa e psicoterapeuta Carmen Danila De Luca evidenzier\u00e0 l&#8217;utilit\u00e0 dell&#8217;approccio strategico breve in psiconcologia.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-281396  aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/03\/a2dfea85-5a16-45d4-a87a-f86fa408a43d.jpg\" alt=\"\" width=\"583\" height=\"1035\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante l&#8217;incontro, alla presenza della sezione di Cosenza dell&#8217;Associazione Nazionale degli Insigniti al Merito della Repubblica Italiana sar\u00e0 donato un ecografo portatile all&#8217;AVIS<\/p>\n","protected":false},"author":43,"featured_media":106601,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[538],"class_list":["post-106600","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza","tag-sanita"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/106600","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=106600"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/106600\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/106601"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=106600"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=106600"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=106600"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}