{"id":106665,"date":"2019-03-08T11:18:21","date_gmt":"2019-03-08T10:18:21","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/incidente-su-viale-parco-pedoni-investiti-da-unauto\/"},"modified":"2023-01-16T18:23:55","modified_gmt":"2023-01-16T17:23:55","slug":"281571-incidente-su-viale-parco-pedoni-investiti-da-unauto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/281571-incidente-su-viale-parco-pedoni-investiti-da-unauto\/","title":{"rendered":"Incidente su Viale Parco, pedoni investiti da un&#8217;auto"},"content":{"rendered":"<h4>I due sono stati trasportati d&#8217;urgenza in ospedale per le cure del caso<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Questa mattina intorno alle 11:30 due persone sono state investite a Cosenza, su viale Giacomo Mancini. Si tratta di due anziani, un uomo di 85 anni e una donna 79enne, travolti da un&#8217;autovettura che stava allontanandosi da un parcheggio per immettersi sul viale, all&#8217;altezza del supermercato Md in direzione Cosenza. Il conducente a bordo dell&#8217;Audi A3 che pare sia riuscito a scansare in parte i pedoni, evitando di colpirli in pieno, si \u00e8 fermato per prestare loro soccorso. <strong>Sul posto sono intervenuti i sanitari del 118 con due ambulanze che hanno provveduto a trasportarli d&#8217;urgenza in Ospedale<\/strong>. Le loro condizioni al momento sono stabili e non destano preoccupazione. L&#8217;uomo ha riportato delle contusioni agli arti inferiori, mentre l&#8217;anziana signora ha delle ferite al volto e ad un braccio. La polizia municipale di Cosenza \u00e8 al lavoro per i rilievi del caso e per disciplinare il traffico.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I due sono stati trasportati d&#8217;urgenza in ospedale per le cure del caso<\/p>\n","protected":false},"author":43,"featured_media":106666,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[595],"class_list":["post-106665","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza","tag-incidente"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/106665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=106665"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/106665\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/106666"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=106665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=106665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=106665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}