{"id":106706,"date":"2019-03-08T17:55:36","date_gmt":"2019-03-08T16:55:36","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/una-strada-per-calipari\/"},"modified":"2023-01-16T18:23:58","modified_gmt":"2023-01-16T17:23:58","slug":"281706-una-strada-per-calipari","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/281706-una-strada-per-calipari\/","title":{"rendered":"Una strada per Calipari"},"content":{"rendered":"<h4>L&#8217;intitolazione da parte dell\u2019Amministrazione comunale, di una strada che porta ad abitazioni della Polizia di Stato e si innesta su viale dell\u2019Agricoltura, nella zona nord e di espansione di Castrovillari, al dirigente del Sismi Nicola Calipari<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>CASTROVILLARI &#8211; <strong>Castrovillari<\/strong> si lega al ricordo di<strong> Nicola Calipari<\/strong> attraverso il riconoscimento dovuto, ad un impareggiabile servitore dello Stato: \u00abEsempio per tutti, per l\u2019impegno assoluto per la dignit\u00e0 umana che abbraccia anche il ricordo di una donna, <strong>Giuliana Sgrena<\/strong>, l\u00ec come inviata di guerra a servizio del diritto d\u2019informare i cittadini.<\/p>\n<p>Calipari, originario di Reggio Calabria, ucciso in Iraq nel marzo 2005, al termine di un\u2019operazione, per liberare degli ostaggi dai terroristi di quel Paese, e mentre faceva scudo con la sua persona alla giornalista Giuliana Sgrena, mentre in macchina, raggiungevano l\u2019aeroporto di Baghdad.<\/p>\n<p>La richiesta dell\u2019intitolazione era partita anche dal Siulp, Sindacato italiano unitario lavoratori Polizia Cosenza, che ha posto, a pochi metri dalla targa dell\u2019amministrazione, uno stele, scoperto durante la celebrazione -, rappresentato nella manifestazione dagli aderenti a partire dai segretari provinciale e locale, Luciano Lupo e Ruggero Altimari, ha osservato momenti di commozione e particolare riflessione nella consapevolezza comune che tendere la mano \u00e8 sempre stata la connotazione forte, per Cultura, del paese Italia nel Mondo e l\u00e0 dove veniva richiesto il coinvolgimento.<\/p>\n<p>Presenti numerosi esponenti delle Forze dell\u2019Ordine, dell\u2019Esercito, del Comune e della societ\u00e0 civile, con gli scout, espressione del cammino educativo giovanile di Calipari, importanti i messaggi del Prefetto e Questore di Cosenza, del Sindaco, Domenico Lo Polito, della vedova di Calipari, Rosa Villecco, del Vescovo di Cassano all\u2019Ionio, monsignor Francesco Savino, moderati dal giornalista Vincenzo Alvaro.<\/p>\n<p>\u00abEcco perch\u00e9 &#8211; ha dichiarato il Sindaco, Domenico Lo Polito &#8211; l\u2019importanza di rendere onore ad un figlio illustre della Calabria che con il suo sacrificio riscatta, con tanti altri, capacit\u00e0 e anima anche della nostra gente, fatta di uomini e donne che hanno sempre riposto nel loro cuore l\u2019amore per la propria terra, certi che in questo assunto, dilatato da una vera esperienza personale dedita alla verit\u00e0, si possano costruire le condizioni che consentono di vivere esperienze autenticamente umane\u00bb.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;intitolazione da parte dell\u2019Amministrazione comunale, di una strada che porta ad abitazioni della Polizia di Stato e si innesta su viale dell\u2019Agricoltura, nella zona nord e di espansione di Castrovillari, al dirigente del Sismi Nicola Calipari<\/p>\n","protected":false},"author":47,"featured_media":106707,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-106706","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/106706","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/47"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=106706"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/106706\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/106707"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=106706"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=106706"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=106706"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}