{"id":106734,"date":"2019-03-09T15:22:52","date_gmt":"2019-03-09T14:22:52","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/piattaforma-viale-mancini-esenzione-tasse-per-i-commercianti\/"},"modified":"2023-01-16T18:24:00","modified_gmt":"2023-01-16T17:24:00","slug":"281835-piattaforma-viale-mancini-esenzione-tasse-per-i-commercianti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/281835-piattaforma-viale-mancini-esenzione-tasse-per-i-commercianti\/","title":{"rendered":"Piattaforma, viale Mancini: \u00abEsenzione tasse per i commercianti\u00bb"},"content":{"rendered":"<h4>I consiglieri comunali del Gruppo Piattaforma chiedono al sindaco Occhiuto di alleviare i disagi dei commercianti di Viale Parco<\/h4>\n<h4><!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; I lavori che stanno interessando viale Mancini per la realizzazione del Parco del Benessere, stanno arrecando qualche disagio oltre che alla viabilit\u00e0 anche alle attivit\u00e0 commerciali che insistono su questa importante arteria stradale. Per questo motivo, i Consiglieri Comunali aderenti alla Piattaforma, intendono chiedere all&#8217;Amministrazione Comunale un provvedimento di esenzione dalle tasse e dai tributi comunali, per le attivit\u00e0 commerciali che hanno la propria sede su viale Mancini.<\/p>\n<p>Pasquale Sconosciuto, Francesco Spadafora, Giovanni Cipparrone, Francesco De Cicco, Marco Ambrogio e Francesco Cito auspicano che lo stesso provvedimento che fu adottato a favore delle attivit\u00e0 commerciali di piazza Bilotti, oggi possa essere replicato per quelle di viale Mancini. Sarebbe un gesto e un segnale di attenzione nei confronti di chi oggi accusa qualche disagio in pi\u00f9, a causa della presenza di un cantiere che vede la realizzazione di un&#8217;importante opera pubblica.<\/p>\n<p>E a proposito di cantieri, i sei della Piattaforma ritengono non pi\u00f9 procrastinabile l&#8217;avvio dei lavori per la celere realizzazione della nuova strada parallela a via Popilia, che collegher\u00e0 il Ponte di Calatrava alla Sopraelevata, permettendo di smaltire buona parte del traffico che oggi congestiona via Popilia e via XXIV Maggio.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>I consiglieri comunali del Gruppo Piattaforma chiedono al sindaco Occhiuto di alleviare i disagi dei commercianti di Viale Parco<\/p>\n","protected":false},"author":44,"featured_media":106735,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-106734","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/106734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=106734"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/106734\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/106735"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=106734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=106734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=106734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}