{"id":106911,"date":"2019-03-13T14:08:56","date_gmt":"2019-03-13T13:08:56","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cinquantenne-operata-di-tumore-allannunziata-asportate-21-metastasi\/"},"modified":"2023-01-16T18:24:12","modified_gmt":"2023-01-16T17:24:12","slug":"282589-cinquantenne-operata-di-tumore-allannunziata-asportate-21-metastasi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/282589-cinquantenne-operata-di-tumore-allannunziata-asportate-21-metastasi\/","title":{"rendered":"Cinquantenne operata di tumore all&#8217;Annunziata, asportate 21 metastasi"},"content":{"rendered":"<h4>La donna che ha subito anche la resezione del colon \u00e8 stata stomizzata, ma i medici garantiscono che la soluzione del &#8216;sacchetto&#8217; \u00e8 solo temporanea<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Un importante intervento di chirurgia oncologica \u00e8 stato eseguito all\u2019Ospedale Annunziata di Cosenza dall\u2019equipe di Chirurgia Epato-Bilio-Pancreatica e Trapianti, diretta da Sebastiano Vaccarisi in collaborazione con i dottori Vincenzo Pellegrino, Massimo Canonaco, Silvano Rizzuti e Giuseppina Fusilli e dall\u2019equipe di Anestesia e Rianimazione diretta da Pino Pasqua con i dottori Cosimo Stefano e Valeria Gambardella, su una<strong> paziente di 50 anni, affetta da multiple metastasi epatiche bilobari da tumore del colon, sono state asportate 21 (ventuno) metastasi<\/strong> da tutti i segmenti del fegato ad eccezione del primo, l\u2019unico indenne da localizzazioni metastatiche. L\u2019intervento, svolto in un\u2019 unica seduta, \u00e8 durato poco meno di sette ore e ha comportato la resezione di alcune parti del fegato, la resezione del colon sinistro, l\u2019 asportazione della colecisti e l\u2019ileostomia temporanea di protezione.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Non \u00e8 stata necessaria alcuna trasfusione, per la paziente, proveniente dal Centro di Oncologia Medica del Policlinico Universitario Mater Domini di Catanzaro<\/strong>, poich\u00e8 ha perso pochissimo sangue: la donna \u00e8 stata dimessa e non presenta residui di malattia, come evidenziato dalla TC eseguita prima delle dimissioni. Il fegato rappresenta la sede pi\u00f9 frequente di metastasi da carcinoma colorettale e, nella maggioranza dei casi, l\u2019interessamento epatico determina la durata e la qualit\u00e0 di vita del paziente. I notevoli progressi nelle tecniche chirurgiche e farmacologiche e una pi\u00f9 approfondita conoscenza della patologia, hanno reso il tumore metastatico del fegato sempre pi\u00f9 curabile, anche nella nostra realt\u00e0 locale, grazie alla presenza di un gruppo di professionisti che, ormai da tempo, ha raggiunto un elevato livello di conoscenza scientifica e di competenza specifica, apprezzate anche a livello nazionale.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Di recente l\u2019ASL TO 3 ha richiesto la collaborazione di Pellegrino, per l\u2019esecuzione di un intervento di elevata complessit\u00e0 sul pancreas.\u00a0 L\u2019Equipe di Chirurgia Epatobiliopancreatica e Trapianti diretta da Vaccarisi, dal 1\u00b0 Gennaio 2015 a tutt\u2019oggi, ha eseguito oltre 170 resezioni epatiche per tumori primitivi e secondari del fegato, alcune delle quali effettuate anche con tecnica laparoscopica; oltre 30 resezioni pancreatiche per tumori del pancreas; 10 resezioni delle Vie Biliari per Tumori primitivi ed oltre 50 Trapianti di Rene su pazienti molto spesso \u201c difficili\u201d, che complessivamente pochissime complicanze. \u201cUn lavoro di squadra &#8211; ha dichiarato soddisfatto il Commissario Achille Gentile &#8211; che ha visto in campo chirurghi, oncologi, radiologi e anestesisti.<strong> Un altro intervento importante che porta la chirurgia dell\u2019Annunziata a collocarsi tra le migliori d\u2019Italia.<\/strong> Gli investimenti in nuove tecnologie e l\u2019impegno e la professionalit\u00e0 dei medici, hanno contribuito a costruire una realt\u00e0 sanitaria competitiva con gli standard del resto del Paese che diventa giorno dopo giorno polo di riferimento in grado di ridurre la migrazione sanitaria\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La donna che ha subito anche la resezione del colon \u00e8 stata stomizzata, ma i medici garantiscono che la soluzione del &#8216;sacchetto&#8217; \u00e8 solo temporanea<\/p>\n","protected":false},"author":43,"featured_media":106912,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[538],"class_list":["post-106911","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza","tag-sanita"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/106911","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=106911"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/106911\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/106912"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=106911"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=106911"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=106911"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}