{"id":107111,"date":"2019-03-17T14:00:39","date_gmt":"2019-03-17T13:00:39","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/casa-e-auto-in-fiamme-scoperti-i-due-incendiari\/"},"modified":"2023-01-16T18:24:25","modified_gmt":"2023-01-16T17:24:25","slug":"283233-casa-e-auto-in-fiamme-scoperti-i-due-incendiari","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/283233-casa-e-auto-in-fiamme-scoperti-i-due-incendiari\/","title":{"rendered":"Casa e auto in fiamme, scoperti i due incendiari"},"content":{"rendered":"<h4>Due le abitazioni date al fuoco con lo spargimento di liquido infiammabile e una automobile presa di mira nelle successive 24 ore<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>TAURIANIVA (RC) &#8211; I Carabinieri della Compagnia di Taurianova hanno dato esecuzione alla misura cautelare personale del divieto di dimora nel Comune di Polistena, con la prescrizione di non allontanarsi dall\u2019abitazione in orario notturno, emessa dal G.I.P. del Tribunale di Palmi su richiesta della locale Procura nei confronti di <strong>Boeti Davide<\/strong>, 27 enne, e <strong>Mombelli Roberto<\/strong> 38enne, entrambi di Polistena, e gi\u00e0 gravati da numerosi precedenti di polizia, in quanto ritenuti responsabili del reato di incendio in concorso.<\/p>\n<p>Il provvedimento cautelare conclude un\u2019attivit\u00e0 investigativa avviata dalla Stazione Carabinieri di Polistena a seguito di alcuni incendi dolosi verificatisi nella cittadina nel settembre scorso, che avevano causato il danneggiamento di due immobili disabitati e di una autovettura.<\/p>\n<p>In particolare nella notte tra il 6 e il 7 settembre i Carabinieri e i Vigili del Fuoco di Polistena sono intervenuti in un immobile disabitato nel centro della cittadina, \u00a0in quanto ignoti, poco prima, \u00a0avevano appiccato il fuoco utilizzando del liquido infiammabile alla struttura, causandone il grave danneggiamento. Durante le operazioni di spegnimento veniva segnalato un principio di incendio anche in un altro contiguo immobile, sempre disabitato, che \u00e8 stato prontamente domato dal personale. Gli edifici si trovavano in ristrette vie, con ancora presente l\u2019impianto elettrico, e quindi vi era il concreto pericolo che le fiamme potessero propagarsi e lambire anche le abitazioni vicine. La notte successiva, tra il 7 e l\u20198 settembre, ignoti hanno appiccato il fuoco ad una autovettura privata, parcheggiata nella pubblica via, che veniva completamente distrutta dalle fiamme.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-283235\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/03\/Foto-4.jpg\" alt=\"\" width=\"886\" height=\"1280\" title=\"\"><\/p>\n<p>&nbsp;<\/p>\n<p>Gli eventi cos\u00ec ravvicinata hanno fatto ipotizzare ai Carabinieri della Compagnia di Taurianova che la matrice e gli autori fossero comuni. I primi sospetti sugli odierni indagati sono iniziati proprio la sera del primo incendio quando una pattuglia della Stazione Carabinieri di Polistena intervenuta sul posto, ha notato e identificato nelle vicinanze dei luoghi i due soggetti che, con atteggiamento sospetto, erano particolarmente interessati alle operazioni svolte dai Vigili del Fuoco.<\/p>\n<p>La successiva attivit\u00e0 investigativa svolta dai Carabinieri, sotto il costante coordinamento della Procura della Repubblica di Palmi, mediante escussione di testimoni e attenta e ampia analisi dei sistemi di videosorveglianza, ha consentito di raccogliere gravi indizi di colpevolezza a carico dei due polistenesi, ritenuti responsabili di tutte e tre gli incendi, commessi a puro scopo di vandalismo. Tali azioni potevano creare un grave pericolo per l\u2019incolumit\u00e0 pubblica, nel caso di sviluppo ed estensione delle fiamme, evitato grazie al pronto intervento dei militari e dei Vigili del Fuoco.<\/p>\n<p>Il BOETI e il MOMBELLI dovranno rispondere quindi del reato di incendio e dei danneggiamenti causati e non potranno dimorare nel Comune di Polistena, n\u00e9 allontanarsi dalle loro abitazioni tra le ore 22 e le ore 6.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Due le abitazioni date al fuoco con lo spargimento di liquido infiammabile e una automobile presa di mira nelle successive 24 ore<\/p>\n","protected":false},"author":44,"featured_media":107112,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-107111","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/107111","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=107111"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/107111\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/107112"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=107111"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=107111"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=107111"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}