{"id":107193,"date":"2019-03-18T18:48:03","date_gmt":"2019-03-18T17:48:03","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/serra-spiga-lo-gullo-periferia-abbandonata\/"},"modified":"2023-01-16T18:24:30","modified_gmt":"2023-01-16T17:24:30","slug":"283505-serra-spiga-lo-gullo-periferia-abbandonata","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/283505-serra-spiga-lo-gullo-periferia-abbandonata\/","title":{"rendered":"Serra Spiga, Lo Gullo: \u00abPeriferia abbandonata\u00bb"},"content":{"rendered":"<h4>A scrivere \u00e8 il consigliere Massimo Lo Gullo che rimprovera al sindaco Occhiuto lo scarso interesse per i cosentini di San Vito Alto,\u00a0Serra Spiga, Via Accattatis e Via F.lli Cervi<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; \u00abA nome dei cittadini di<span style=\"color: #0000ff;\"><strong> <a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/6361\" target=\"_blank\" rel=\"noopener\">San Vito Alto<\/a><\/strong><\/span> &#8211; Serra Spiga \u2013 Via Accattatis e Via F.lli Cervi, esprimo disappunto nei confronti del Sindaco, che continua a fare solo promesse per questa periferia abbandonata della citt\u00e0 (vedi problema case), perch\u00e9 quanto di tratta di assumere anche semplici atti amministrativi, dimostra scarso interesse e poca disponibilit\u00e0\u00bb. A scrivere una nota \u00e8 il consigliere Massimo Lo Gullo<\/p>\n<p>\u00abUltima in ordine di tempo \u00e8 stata la mancata firma dell\u2019ordinanza per accogliere la richiesta di chiusura al traffico e di pulizia straordinaria della strada di Via Michele De Marco per il giorno 16 marzo per un tempo limitato, dalla ore 16 alle ore 19,30, da parte della Comunit\u00e0 Parrocchiale San Giuseppe Sposo di Maria, in occasione della festivit\u00e0 in onore di San Giuseppe, cos\u00ec com\u2019era stato promesso, per consentire il rito religioso nella prima \u201c Vecchia Chiesa\u201d che coinvolgeva in parte l\u2019asse stradale.<\/p>\n<p>Non \u00e8 bastato il mio impegno ed interessamento a fare protocollare il 7 marzo corrente e cio\u00e8 molto prima del giorno interessato alla richiesta dei tanti parrocchiani ed abitanti del quartiere, proprio per consentire ai preposti del comune di avere tutto il tempo necessario per attivare gli atti utili e rendere il tutto possibile. Eppure a tante altre similari manifestazioni che si effettuano in altre parti della citt\u00e0 \u00e8 stato sempre risposto positivamente. Mi erano state date assicurazioni da parte della segreteria del Sindaco, che l\u2019ordinanza era pronta. Ma tutto ci\u00f2 non \u00e8 stato.<\/p>\n<p>Non si comprende se si \u00e8 trattato di un disguido provocato da qualche funzionario incaricato o se c\u2019\u00e8 stata una vera \u00e8 propria volont\u00e0 del Sindaco \u201cdi mortificare\u201d questi cittadini. Ritengo che non sia nello stile del Sindaco negare un\u2019ordinanza che serviva solo a fare svolgere senza problemi l\u2019iniziativa religiosa che nel quartiere si svolge regolarmente ogni anno, ma cos\u00ec \u00e8 stato.<\/p>\n<p>Va un plauso a tutti quei cittadini che vanno ringraziati per la loro sensibilit\u00e0 e collaborazione nello spostare le autovetture in sosta, per rendere comunque possibile lo svolgimento del rito religioso.<\/p>\n<p>Ritengo che i cittadini di San Vito- Serra Spiga, abbiamo tutto il diritto ad avere una risposta che faccia chiarezza sull\u2018increscioso e spiacevole \u201cdisguido?\u201d e che la comunit\u00e0 religiosa abbia il diritto a ricevere le scuse per la mancata ordinanza\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<p>https:\/\/quicosenza.it\/news\/6361<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A scrivere \u00e8 il consigliere Massimo Lo Gullo che rimprovera al sindaco Occhiuto lo scarso interesse per i cosentini di San Vito Alto,\u00a0Serra Spiga, Via Accattatis e Via F.lli Cervi<\/p>\n","protected":false},"author":44,"featured_media":107194,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-107193","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/107193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=107193"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/107193\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/107194"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=107193"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=107193"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=107193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}