{"id":107221,"date":"2019-03-19T13:29:40","date_gmt":"2019-03-19T12:29:40","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/salvini-blocca-nave-ong-e-dei-centri-sociali-la-bossio-basta-propaganda-della-lega\/"},"modified":"2023-01-16T18:24:33","modified_gmt":"2023-01-16T17:24:33","slug":"283589-salvini-blocca-nave-ong-e-dei-centri-sociali-la-bossio-basta-propaganda-della-lega","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/283589-salvini-blocca-nave-ong-e-dei-centri-sociali-la-bossio-basta-propaganda-della-lega\/","title":{"rendered":"Salvini blocca nave Ong: &#8220;\u00e8 dei centri sociali&#8221;, la Bossio: &#8220;basta propaganda della Lega&#8221;"},"content":{"rendered":"<h4 class=\"article-page__header-title selectionShareable\">La Mare Jonio \u00e8 davanti a Lampedusa. Il secco no di Salvini allo sbarco che attacca la presenza di Luca Casarini: &#8220;\u00e8 una nave dei centri sociali&#8221;. La nota della Bruno Bossio &#8220;basta con propaganda Salvini e inerzia Cinque Stelle&#8221;<\/h4>\n<p><!--more--><\/p>\n<p style=\"font-weight: 400;\">La nave dell&#8217;<strong>ONG &#8220;Mare Ionio&#8221;<\/strong>, battente bandiera italiana si trova a circa un miglio e mezzo da Lampedusa con<strong> a bordo 49 migranti, tra cui 12 minori<\/strong>, soccorsi ieri sera davanti alle coste libiche.\u00a0 Circondata dalle motovedette, della Guardia di Finanza e della Guardia Costiera non ha avuto l&#8217;autorizzazione allo sbarco. Un nuovo caso diciotti anche se questa volta, ad inasprire le polemiche, le dichiarazioni del Ministro dell&#8217;Interno Matteo Salvini che ha parlato senza giri di parole di\u00a0<strong>favoreggiamento dell&#8217;immigrazione clandestina. &#8220;<\/strong><em>Questa <strong>\u00e8 la nave dei centri sociali, perch\u00e9 a nome della nave sta parlando Luca Casarini<\/strong>: vedete i precedenti penali del signore che era noto per essere leader dei centri sociali del nord est, con precedenti penali vari. A<strong> bordo si trovano altri esponenti di sinistra e ultrasinistra<\/strong>, che stanno a mio parere commettendo un reato di favoreggiamento dell&#8217;immigrazione clandestina perch\u00e9<strong> hanno raccolto questi migranti in acque libiche proprio mentre stava intervento una motovedetta libica<\/strong>. Non hanno obbedito a nessuna indicazione, decidendo autonomamente di dirigersi verso l&#8217;Italia per motivi evidentemente ed esclusivamente politic<\/em>i&#8221;.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/6370\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-283592\" src=\"https:\/\/quicosenza.it\/news\/6370\" alt=\"\" width=\"594\" height=\"311\" title=\"\"><\/a><\/p>\n<p>&nbsp;<\/p>\n<h4>Bruno Bossio &#8220;Campagna elettorale di Salvini sulle spalle della povera gente&#8221;<\/h4>\n<p>Dichiarazioni che hanno scatenato la reazione delle opposizioni. <strong>Sulla vicenda \u00e8 intervenuta anche la parlamentare cosentina del PD Enza Bruno Bossio<\/strong>, che ha attaccato sia Salvini, <strong>definendo le sue parole pura propaganda<\/strong>, che i<strong>l Movimento 5 Stelle accusato di\u00a0inerzia.\u00a0<\/strong>&#8220;C<em>i risiamo. Ancora una volta il governo tiene in ostaggio 49 persone che scappano dalla guerra, dalla violenza, dalla fame. Con l&#8217;aggravante del fatto che questa volta stiamo parlando di una nave italiana che sta cercando di entrare in un porto italiano. Se della Sea Watch che batteva bandiera olandese sarebbe dovuto occuparsene il governo olandese, chi si deve occupare di una nave che batte bandiera italiana? Si sta ripetendo &#8211; <\/em>si legge nella nota della Bossio <em>&#8211; ancora una volta il caso Diciotti. Lo diciamo per l&#8217;ennesima volta: i porti devono essere aperti. Basta con la propaganda di Salvini e della Lega, basta con l&#8217;inerzia di Di Maio e dei Cinque Stelle. Tutti devono fare la propria parte, dal governo italiano all&#8217;Unione europea. Ma \u00e8 inaccettabile &#8211; <\/em>conclude Bruno Bossio<em> &#8211; che ancora una volta Salvini faccia campagna elettorale sulle pelle della povera gente<\/em>&#8220;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Mare Jonio \u00e8 davanti a Lampedusa. Il secco no di Salvini allo sbarco che attacca la presenza di Luca Casarini: &#8220;\u00e8 una nave dei centri sociali&#8221;. La nota della Bruno Bossio &#8220;basta con propaganda Salvini e inerzia Cinque Stelle&#8221;<\/p>\n","protected":false},"author":46,"featured_media":107222,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[],"class_list":["post-107221","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/107221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=107221"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/107221\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/107222"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=107221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=107221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=107221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}