{"id":107498,"date":"2019-03-25T09:41:17","date_gmt":"2019-03-25T08:41:17","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/le-vetrate-dei-bocs-art-di-cosenza-diventano-dei-quadri\/"},"modified":"2023-01-16T18:24:51","modified_gmt":"2023-01-16T17:24:51","slug":"284521-le-vetrate-dei-bocs-art-di-cosenza-diventano-dei-quadri","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/284521-le-vetrate-dei-bocs-art-di-cosenza-diventano-dei-quadri\/","title":{"rendered":"Le vetrate dei BoCs art di Cosenza diventano dei quadri"},"content":{"rendered":"<h4>Immagini di grandi dimensioni trasformano le casette in legno in degli &#8216;occhi&#8217; che guardano la citt\u00e0<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; &#8220;I <span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/6430\" target=\"_blank\" rel=\"noopener\"><em><strong>BoCs Art<\/strong><\/em><\/a> <\/span>di Cosenza dal 2018 sono curati da Giacinto Di Pietrantonio che ha sviluppato il programma con una nuova prospettiva interdisciplinare, invitando artisti, scrittori, registi, giornalisti, designer, fumettisti, curatori. Da giugno a novembre dello scorso anno le residenze artistiche si sono qualificate nell&#8217;ambito dell&#8217;idea di &#8216;Pi\u00f9 Arti pi\u00f9 Liberi'&#8221;. E&#8217; quanto si afferma in una nota del Comune di Cosenza. &#8220;Come ogni anno il programma di residenza, nel periodo invernale &#8211; \u00e8 detto nella nota &#8211; viene temporaneamente sospeso, cos\u00ec dallo scorso anno, il nuovo curatore ha individuato nella particolare forma delle architetture la possibilit\u00e0 di una nuova progettualit\u00e0 d&#8217;arte pubblica. Data la presenza di grandi finestre-vetrate incorniciate in una architettura di legno si \u00e8 pensato a renderle come delle grandi vetrine o, meglio, dei grandi quadri, &#8216;occhi&#8217; creativi che guardano i visitatori e la citt\u00e0. <strong>Per questo nei 18 BoCs con la facciata fronte strada sono state installate altrettante opere progettate appositamente per tale scopo. Si tratta di opere-immagini di grandi dimensioni, 470 x 245 centimetri<\/strong>, che parlano alla citt\u00e0, proposte dai seguenti artisti: Giancarlo Cauteruccio, Gialuigi Colin, Giuseppe Gallo, Alberto Garutti, Marcello Iori, Ugo La Pietra, Luigi Magli, Alessandro Mendini, Fulvia Mendini, Maurizio Orrico, Gianni Pettena, Tommaso Pincio, Alfredo Pirri, Pietro Roccasalva, Giulio Telarico, Salvo, Vedovamazzei, Giuseppe Stampone&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right;\">Immagine di repertorio<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Immagini di grandi dimensioni trasformano le casette in legno in degli &#8216;occhi&#8217; che guardano la citt\u00e0<\/p>\n","protected":false},"author":43,"featured_media":107499,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[610],"class_list":["post-107498","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza","tag-bocs-art"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/107498","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=107498"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/107498\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/107499"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=107498"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=107498"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=107498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}