{"id":107502,"date":"2019-03-25T10:33:31","date_gmt":"2019-03-25T09:33:31","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/elettrosmog-nel-centro-della-citta-di-cosenza-nessun-pericolo-per-la-salute\/"},"modified":"2023-01-16T18:24:52","modified_gmt":"2023-01-16T17:24:52","slug":"284534-elettrosmog-nel-centro-della-citta-di-cosenza-nessun-pericolo-per-la-salute","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/284534-elettrosmog-nel-centro-della-citta-di-cosenza-nessun-pericolo-per-la-salute\/","title":{"rendered":"Elettrosmog nel centro della citt\u00e0 di Cosenza, nessun pericolo per la salute"},"content":{"rendered":"<h4>Misurazioni effettuate tra febbraio e marzo per monitorare l&#8217;intensit\u00e0 dei campi elettromagnetici<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Il Dipartimento provinciale Arpacal di Cosenza ha trasmesso nei giorni scorsi al Comando di Polizia municipale della Citt\u00e0 di Cosenza il report sulle misurazioni dell&#8217;intensit\u00e0 dei campi elettromagnetici emessi da alcune stazioni radio base presenti nel centralissimo Viale degli Alimena. <strong>La misurazione \u00e8 stata realizzata dal Servizio Radiazioni e Rumore del Dipartimento provinciale Arpacal di Cosenza<\/strong>, diretto da Francesca Tarsia, alla presenza di personale del Comando di Polizia Municipale. Le misurazioni effettuate tra febbraio e marzo nel rispetto delle norme tecniche di riferimento, che non escludono eventuali nuovi controlli nella medesima area, sono state svolte utilizzando un sensore a larga banda. Nel corso del sopralluogo sono state effettuate delle misurazioni di intensit\u00e0 dei campi elettromagnetici su alcune postazioni, ritenute pi\u00f9 significative ai fini della corretta valutazione dei presunti effetti sanitari connessi alla esposizione umana alle onde elettromagnetiche non ionizzanti. &#8220;Dai valori misurati si evince il non superamento dei valori fissati dalle disposizioni legislative di riferimento&#8221;; \u00e8 quanto afferma il Dipartimento Arpacal di Cosenza a conclusione del rapporto tecnico.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-284539 size-full\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/03\/elettrosmog-cosenza.jpg\" alt=\"\" width=\"1377\" height=\"1475\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Misurazioni effettuate tra febbraio e marzo per monitorare l&#8217;intensit\u00e0 dei campi elettromagnetici<\/p>\n","protected":false},"author":43,"featured_media":107503,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-107502","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/107502","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=107502"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/107502\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/107503"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=107502"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=107502"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=107502"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}