{"id":107590,"date":"2019-03-27T05:42:44","date_gmt":"2019-03-27T04:42:44","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/nas-in-ospedale-carenze-igienico-strutturali-e-medicinali-sequestrati\/"},"modified":"2023-01-16T18:24:57","modified_gmt":"2023-01-16T17:24:57","slug":"284818-nas-in-ospedale-carenze-igienico-strutturali-e-medicinali-sequestrati","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/284818-nas-in-ospedale-carenze-igienico-strutturali-e-medicinali-sequestrati\/","title":{"rendered":"Nas in ospedale, carenze igienico strutturali e medicinali sequestrati"},"content":{"rendered":"<h4>Il controllo ispettivo \u00e8 scattato dopo il caso di un <span style=\"color: #0000ff;\"><strong><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/6440\" target=\"_blank\" rel=\"noopener\">paziente deceduto<\/a><\/strong><\/span> in reparto che non era stato possibile trasferire in obitorio a causa dell&#8217;ascensore guasto<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>SERRA SAN BRUNO (VV) &#8211; Controlli mirati dei Carabinieri del <strong><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/6454\" target=\"_blank\" rel=\"noopener\">Nas<\/a><\/span><\/strong>, il Nucleo Antisofisticazione di Catanzaro, insieme ai colleghi della Compagnia locale, ieri all\u2019ospedale di Serra San Bruno che hanno interessato l\u2019intera struttura: dai servizi ai reparti di degenza, l&#8217;impiantistica, la sicurezza sui luoghi di lavoro e l&#8217;utilizzo di presidi medici e sanitari. Le carenze igienico strutturali emerse sarebbero diverse e saranno segnalate alle Autorit\u00e0 cos\u00ec come dirigenti, funzionari e medici, ognuno per le rispettive competenze.<\/p>\n<p>Un immobile vetusto, un solo ascensore sia per l&#8217;utenza che per l&#8217;espletamento dei servizi e criticit\u00e0 nei locali del pronto soccorso. I Nas avrebbero accertato anche anomalie sulla gestione delle specialit\u00e0 medicinali e dei presidi medico chirurgici all\u2019interno dei vari reparti che sono stati posti sotto sequestro. In totale si tratta di 4.000 presidi medico-chirurgici e 300 specialit\u00e0 medicinali, ad uso di stupefacenti, entrambi scaduti. Solo nei reparti di lunga degenza le condizioni generali sono state definite sufficienti.<\/p>\n<h4 style=\"text-align: center;\"><strong>Verifiche Impiantistiche: l\u2019intervento di Arpacal<br \/>\ncon i Carabinieri nell\u2019ospedale di Serra San Bruno<\/strong><\/h4>\n<p>Anche il servizio verifiche impiantistiche del Dipartimento provinciale di Cosenza dell\u2019Arpacal ha partecipato attivamente con l\u2019Ing. Aldo Tripicchio, dirigente del Servizio, alle delicate ispezioni ieri, presso il nosocomio di Serra San Bruno effettuate dai NAS volte a constatare le condizioni igienico-sanitarie e tecnico-strutturali del presidio dell\u2019ASP vibonese.<\/p>\n<p>L\u2019Ing. Tripicchio ha rivolto particolare attenzione alla sicurezza impiantistica e, in particolare, ha svolto un\u2019approfondita valutazione delle condizioni dei tre ascensori esistenti, della centrale termica, della cabina elettrica, dell\u2019impianto elettrico e di tutte le attrezzature ivi collegate, come l\u2019apparecchiatura per la sterilizzazione e le altre strumentazioni elettromedicali.<\/p>\n<p>\u201cNel porre in essere le osservazioni del caso, debitamente comunicate alla preposta Autorit\u00e0 &#8211; fanno sapere dal Servizio Verifiche Impiantistiche &#8211; si \u00e8 evidenziata la necessit\u00e0 di mantenere regolarmente gli impianti in condizioni di perfetta funzionalit\u00e0 e sicurezza, essendo una condizione di primaria importanza negli ambiti pubblici e, ancor di pi\u00f9, nei luoghi dove si deve garantire salute\u201d.<\/p>\n<p>https:\/\/quicosenza.it\/news\/6454<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il controllo ispettivo \u00e8 scattato dopo il caso di un paziente deceduto in reparto che non era stato possibile trasferire in obitorio a causa dell&#8217;ascensore guasto<\/p>\n","protected":false},"author":42,"featured_media":107591,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-107590","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/107590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=107590"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/107590\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/107591"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=107590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=107590"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=107590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}