{"id":107677,"date":"2019-03-29T05:17:27","date_gmt":"2019-03-29T04:17:27","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/brunei-shock-pene-corporali-per-i-gay\/"},"modified":"2023-01-16T18:25:03","modified_gmt":"2023-01-16T17:25:03","slug":"285256-brunei-shock-pene-corporali-per-i-gay","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/285256-brunei-shock-pene-corporali-per-i-gay\/","title":{"rendered":"Brunei shock: pene corporali per i gay"},"content":{"rendered":"<h4>La notizia arriva dal Brunei ed \u00e8 confermata dal Guardian. Questo piccolo Stato islamico ha introdotto una nuova serie di leggi come parte dell&#8217;attuazione di un nuovo codice penale basato sulla Sharia.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Brunei shock: pene corporali per i gay. Le nuove leggi, che comprendono la lapidazione per omosessuali e adulteri e l&#8217;amputazione di un piede o una mano per coloro i quali saranno accusati di furto, saranno in vigore dal 3 aprile e si applicheranno soltanto ai musulmani, che costituiscono comunque la maggior parte della popolazione, stimata intorno ai due terzi. La notizia dell&#8217;introduzione della Sharia ha sollevato grande indignazione nei gruppi per la difesa dei diritti umani e l&#8217;immediata attivazione per fermare l&#8217;attuazione di questo tipo di sanzioni. Amnesty International \u00e8 infatti intervenuta per sottolineare che alcune delle fattispecie, come i rapporti omosessuali, non dovrebbero nemmeno essere considerati reati. Gi\u00e0 nel 2014 una direttiva del sultano del Brunei aveva annunciato di voler introdurre la Sharia, una forma rigida dell&#8217;islam che impone severe pene corporali.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La notizia arriva dal Brunei ed \u00e8 confermata dal Guardian. Questo piccolo Stato islamico ha introdotto una nuova serie di leggi come parte dell&#8217;attuazione di un nuovo codice penale basato sulla Sharia.<\/p>\n","protected":false},"author":20,"featured_media":107678,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[22],"tags":[],"class_list":["post-107677","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-dal-mondo"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/107677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=107677"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/107677\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/107678"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=107677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=107677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=107677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}