{"id":107708,"date":"2019-03-29T09:49:52","date_gmt":"2019-03-29T08:49:52","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/carenze-e-disagi-allasp-di-cosenza-protestano-i-lavoratori-mercoledi-assemblea\/"},"modified":"2023-01-16T18:25:05","modified_gmt":"2023-01-16T17:25:05","slug":"285346-carenze-e-disagi-allasp-di-cosenza-protestano-i-lavoratori-mercoledi-assemblea","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/285346-carenze-e-disagi-allasp-di-cosenza-protestano-i-lavoratori-mercoledi-assemblea\/","title":{"rendered":"Carenze e disagi all&#8217;Asp di Cosenza, protestano i lavoratori. Mercoled\u00ec assemblea"},"content":{"rendered":"<h4>\u00c8 stata indetta per il prossimo 3 aprile dalle ore 08:00 alle 14:00, l\u2019Assemblea di tutti i lavoratori del Comparto Sanit\u00e0, dipendenti dell\u2019Azienda Sanitaria Provinciale di Cosenza<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; L&#8217;assemblea si terr\u00e0 dinanzi la sede dell\u2019Ente in via Alimena a Cosenza e ad annunciarlo sono stati i sindacati, dopo un lungo confronto con i lavoratori, dal quale ne \u00e8 scaturito un documento indirizzato all\u2019Ente Sanitario, al Prefetto e al Questore di Cosenza. Il documento a firma di Susanna De Marco &#8211; Uil Fpl Cosenza, Teodora Gagliardi \u2013 FP Cgil Cosenza, Vincenzo Casciaro \u2013 FP Cgil Castrovillari, Pierpaolo Lanciano \u2013 FP Cisl, Antonio Caccuri \u2013 Fials, Onofrio Sommario &#8211; Nursing Up, riporta i motivi che hanno indotto i lavoratori ad intraprendere tale <strong>forma di protesta<\/strong>.<\/p>\n<h3>I motivi<\/h3>\n<p>&#8220;Tra i motivi sicuramente c&#8217;\u00e8 quello della carenza di personale medico, infermieristico, OSS, ausiliario, tecnico e amministrativo, che inevitabilmente lascia intuire quali gravi disservizi possano presentarsi, come ad esempio, l\u2019espletamento di un <strong>servizio scadente nei confronti di chi richiede assistenza<\/strong>, a causa di un <strong>carico<\/strong> eccessivamente elevato per gli operatori sanitari che si ritrovano ad operare in situazioni in cui sarebbe meglio possedere il dono dell\u2019ubiquit\u00e0. Successivamente &#8211; riporta la nota dei sindacati &#8211; la mancata attivazione delle Progressioni (Fasce economiche) gi\u00e0 concordate lo scorso 19\/12\/2018. Poi la <strong>parziale applicazione della Riforma Madia<\/strong> in merito alle riqualificazioni di tutto il Personale avente diritto (OSS, Infermieri, Amministrativi, Tecnici). In fine la mancata stabilizzazione del Personale a tempo determinato e mancata trasformazione dei rapporti di lavoro da part time a full time&#8221;.<\/p>\n<p>&#8220;Si evince pertanto che l\u2019Asp di Cosenza, da un po\u2019 di tempo, sia artefice di numerose mancanze, dimostrandosi sorda alle <strong>richieste provenienti dai sindacati:<\/strong>\u00a0l&#8217;Azienda Sanitaria, infatti, poco o nulla ha fatto per quanto riguarda l\u2019applicazione dei provvedimenti atti a valorizzare la professionalit\u00e0 dei dipendenti.\u00a0Pi\u00f9 volte abbiamo\u00a0 attivato gli uffici legali &#8211; spiegano le sigle sindacali &#8211; denunciando il <strong>mancato rispetto degli accordi sottoscritti,<\/strong> ma neanche di fronte a queste prese di posizione rigorose abbiamo registrato un minimo di attenzione che facesse intravedere un cambio di rotta&#8221;.<\/p>\n<p>&#8220;Il sindacato non pu\u00f2 rimanere inerte di fronte ad una situazione cos\u00ec desolante, dove l\u2019arroganza supera ogni limite di tollerabilit\u00e0, occorre un sindacato forte che faccia rispettare le norme contrattuali e che faccia riconquistare centralit\u00e0 al ruolo del Dipendenti. E a tal proposito, non servono i documenti di qualche \u201csigla sindacale fai da te\u201d, finalizzati a <strong>discreditare chi da anni si batte contro gli sprechi.\u00a0<\/strong>Cos\u00ec come non serve tirarsi indietro nella lotta a difesa dei lavoratori, altrimenti si dimostra di voler difendere e mantenere quelle piccole rendite di posizione che hanno contribuito a portare la Sanit\u00e0 della nostra Provincia al degrado attuale.<br \/>\nPer i motivi sopraesposti riteniamo giusta e puntuale questa prima azione di protesta che aprir\u00e0 una stagione d\u2019iniziative sempre pi\u00f9 incisive, fino ad arrivare allo Sciopero Generale dei lavoratori della Sanit\u00e0 Pubblica della Provincia di Cosenza&#8221;.<\/p>\n<p>&#8220;L\u2019Asp si dia una regolata; &#8211; conclude la nota &#8211; i lavoratori non possono pi\u00f9 essere mortificati, n\u00e9 condannati al precariato a vita. E se ne faccia una ragione anche il sindacato fai da te, invece di decidere di rinunciare ad unirsi a questa battaglia di civilt\u00e0 e di difesa dei dipendenti della Sanit\u00e0&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c8 stata indetta per il prossimo 3 aprile dalle ore 08:00 alle 14:00, l\u2019Assemblea di tutti i lavoratori del Comparto Sanit\u00e0, dipendenti dell\u2019Azienda Sanitaria Provinciale di Cosenza<\/p>\n","protected":false},"author":42,"featured_media":107709,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[538],"class_list":["post-107708","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza","tag-sanita"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/107708","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=107708"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/107708\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/107709"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=107708"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=107708"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=107708"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}