{"id":107827,"date":"2019-03-31T10:22:00","date_gmt":"2019-03-31T08:22:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/filandari-intimidazione-contro-assessore-comunale\/"},"modified":"2023-01-16T18:25:13","modified_gmt":"2023-01-16T17:25:13","slug":"285716-filandari-intimidazione-contro-assessore-comunale","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/285716-filandari-intimidazione-contro-assessore-comunale\/","title":{"rendered":"Filandari, intimidazione contro assessore comunale"},"content":{"rendered":"<h4>Esplosi colpi di arma da fuoco contro garage. Data alle fiamme l&#8217;auto parcheggiata nelle vicinanze<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>FILANDARI (VV) &#8211; Grave intimidazione, la notte appena trascorsa, ai danni di un amministratore comunale del Vibonese. Ignoti hanno infatti esploso alcuni colpi d&#8217;arma da fuoco contro la saracinesca del garage di un assessore comunale del comune di Filandari, Giuseppe Antonio Artusa, 61 anni, danneggiando la macchina che si trovava all&#8217;interno. E una seconda vettura che si trovava nelle vicinanze \u00e8 stata, invece, data alle fiamme. A domare il rogo ci hanno pensato i vigili del fuoco del Comando provinciale di Vibo Valentia. I carabinieri indagano sulla possibile matrice del gesto che non si esclude possa essere riconducibile anche all&#8217;attivit\u00e0 politica di Artusa, espressione della maggioranza che fa capo a Rita Fuduli, sindaco del piccolo centro della provincia di Vibo Valentia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Esplosi colpi di arma da fuoco contro garage. Data alle fiamme l&#8217;auto parcheggiata nelle vicinanze<\/p>\n","protected":false},"author":44,"featured_media":107828,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-107827","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/107827","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=107827"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/107827\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/107828"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=107827"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=107827"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=107827"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}