{"id":107875,"date":"2019-04-01T14:12:04","date_gmt":"2019-04-01T12:12:04","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-arrivano-le-telecamere-negli-asili\/"},"modified":"2023-01-16T18:25:16","modified_gmt":"2023-01-16T17:25:16","slug":"285855-cosenza-arrivano-le-telecamere-negli-asili","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/285855-cosenza-arrivano-le-telecamere-negli-asili\/","title":{"rendered":"Cosenza, arrivano le telecamere negli asili"},"content":{"rendered":"<h4><strong>La citt\u00e0 di Cosenza installa le telecamere negli asili. Sabato 6 aprile l&#8217;inaugurazione<\/strong><!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; E&#8217; in programma <strong>sabato 6 aprile<\/strong>, alle <strong>ore 11,30<\/strong>, all&#8217;asilo nido di via Livatino, l&#8217;inaugurazione dei sistemi di videosorveglianza attivati dal settore educazione del comune di Cosenza in tutti e tre gli asili comunali (gli altri due sono ubicati in via Riccardo Misasi e Largo Vergini).<\/p>\n<p>\u201cGrazie allo straordinario impegno del Vice Sindaco Jole Santelli e dell&#8217;Assessore alla scuola Matilde Spadafora Lanzino\u00a0 &#8211;\u00a0 sottolinea il Sindaco Mario Occhiuto &#8211; Cosenza \u00e8 tra le primissime citt\u00e0 italiane ad attivare il sistema di videosorveglianza nei nidi di sua diretta pertinenza.<\/p>\n<p>Determinante \u2013 ha aggiunto Occhiuto \u2013 \u00e8 stato il contributo del Vice Sindaco Jole Santelli che ci ha aiutati sia nella fase di reperimento delle risorse finanziarie, sia nei feedback necessari per gli adempimenti relativi alla privacy. Cosenza anticipa cos\u00ec le attivit\u00e0 messe in campo dal Parlamento. Vogliamo trasmettere serenit\u00e0 all&#8217;utenza \u2013 ha detto ancora il Sindaco Occhiuto &#8211; e lo scopo dell&#8217;impegno profuso dal Comune e dal Settore Educazione, attraverso il suo dirigente Mario Campanella,\u00a0 \u00e8 proprio quello di rendere sicura la permanenza dei tanti bambini ospitati nei tre nidi\u201d.<\/p>\n<p>La cooperativa che gestisce i nidi, l&#8217;Adiss, ha acquisito per legge il consenso dell&#8217;organizzazione sindacale pi\u00f9 rappresentativa e l&#8217;autorizzazione di tutti i genitori dei 129 bambini ospitati. Il protocollo approvato con determinazione comunale prevede, in ossequio alla legge 675\/96 e successive modifiche e integrazioni, il divieto di utilizzo delle immagini per fini diversi da quelli relativi alla sicurezza dei bambini e del personale, oltre che dei luoghi pi\u00f9 volte oggetto di furti da parte di ignoti.<\/p>\n<p>\u201cCon l&#8217;installazione dei sistemi di videosorveglianza negli asili della citt\u00e0 \u2013 ha concluso il Sindaco Occhiuto &#8211; si d\u00e0 un seguito concreto all&#8217;aspettativa di molte famiglie dopo gli ultimi casi registrati dalla cronaca nazionale, avendo ben presente il superiore interesse del minore e contemperando la tutela dell\u2019incolumit\u00e0 fisica dei bambini con la loro riservatezza, diritto quest&#8217;ultimo ampiamente garantito dal fatto che le immagini non potranno essere utilizzate per fini diversi da quelli che riguardano la loro sicurezza\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La citt\u00e0 di Cosenza installa le telecamere negli asili. Sabato 6 aprile l&#8217;inaugurazione<\/p>\n","protected":false},"author":44,"featured_media":107876,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-107875","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/107875","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=107875"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/107875\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/107876"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=107875"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=107875"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=107875"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}