{"id":107903,"date":"2019-04-02T09:00:07","date_gmt":"2019-04-02T07:00:07","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/linfluenza-di-social-network-e-internet-nei-rapporti-familiari-incontro-dellami\/"},"modified":"2023-01-16T18:25:19","modified_gmt":"2023-01-16T17:25:19","slug":"285904-linfluenza-di-social-network-e-internet-nei-rapporti-familiari-incontro-dellami","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/285904-linfluenza-di-social-network-e-internet-nei-rapporti-familiari-incontro-dellami\/","title":{"rendered":"l&#8217;influenza di social network e internet nei rapporti familiari, incontro dell&#8217;AMI"},"content":{"rendered":"<h4>L\u2019AMI, l&#8217;associazione degli Avvocati Matrimonialisti Italiani &#8211; Sezione Distrettuale Catanzaro-Cosenza, parla dell\u2019influenza e delle conseguenze di social e internet nei rapporti familiari<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Oggi, internet e i social sono diventati gli strumenti attraverso i quali avviene la <strong>violazione del dovere di fedelt\u00e0,<\/strong> che rappresenta uno dei principali doveri derivanti dal vincolo matrimoniale. L\u2019impatto del web e dei nuovi media, come i <strong>social network<\/strong> nelle relazioni di famiglia, sar\u00e0 il tema principale del nuovo evento info-formativo dell\u2019associazione degli Avvocati Matrimonialisti Italiani &#8211; Sezione Distrettuale Catanzaro-Cosenza, che si svolger\u00e0 presso il Palazzo di Giustizia di Cosenza il <strong>prossimo venerd\u00ec 5 aprile<\/strong>, a partire dalle <strong>ore 15.30.<\/strong><\/p>\n<p>\u201cI linguaggi dei social network e l\u2019influenza del mondo virtuale nei rapporti familiari e sociali: aspetti legali, sociali e psicologici\u201d \u00e8 il titolo del convegno a cui interverranno: il presidente del Consiglio dell\u2019Ordine degli Avvocati di Cosenza, Vittorio Gallucci; la presidente dell\u2019AMI Sezione Distrettuale di Catanzaro-Cosenza, Margherita Corriere; lo psicologo e psicoterapeuta Marco Pingitore; la sociologa Debora Cilio; la segretaria del distretto AMI di Catanzaro, Brunella Tassone.<\/p>\n<p>L\u2019avvocato Margherita Corriere, nell\u2019anticipare alcuni degli elementi di approfondimento del tema, mette in evidenza come la giurisprudenza di legittimit\u00e0 indica \u201ccome una relazione instaurata da uno dei coniugi sul web non \u00e8 elemento sufficiente per addebitare a questi la fine del matrimonio, qualora manchi la prova che la storia virtuale sia stata la causa del fallimento del matrimonio\u201d.\u00a0Ovviamente, nell\u2019ipotesi di <strong>relazione virtuale<\/strong> non pu\u00f2 comunque \u201cescludersi la possibilit\u00e0 che siffatto legame sentimentale abbia leso i diritti fondamentali dell\u2019altro coniuge quali <strong>la salute e l\u2019onore<\/strong>\u201c.<\/p>\n<h4>Uso della rete da parte dei minori<\/h4>\n<p>Una problematica ancora pi\u00f9 grave risulta essere, invece, quella connessa <strong>all\u2019uso inappropriato della rete da parte dei minori<\/strong>, in particolare se si parla di cyberbullismo, che \u00e8 una grave forma di aggressione realizzata attraverso l\u2019uso delle rete telematica e principalmente per mezzo di internet. Purtroppo, quello che emerge rispetto a questa devianza \u00e8 che le condotte aggressive e le molestie poste in essere da un minore attraverso i mezzi offerti della moderna tecnologia denotano una scarsa vigilanza da parte dei genitori.<\/p>\n<p>L\u2019incontro dell\u2019AMI vuole proprio mettere in risalto come sia fondamentale <strong>un\u2019idonea educazione alle nuove tecnologie<\/strong> da parte delle nuove generazioni, che devono tenere nel dovuto conto certi principi che prima di essere giuridici sono etici, tra cui il dovere di rispettare i propri simili, di attenzionare il diverso, di tutelare i diritti all\u2019immagine e alla privacy delle persone che ci vivono attorno. La crisi del nucleo familiare costituisce sicuramente un evento negativo per i figli, specie in tenera et\u00e0, non avendo questi ultimi raggiunto quella maturit\u00e0 idonea a fornire loro gli strumenti per affrontare tale situazione. Oggi si valuta la possibilit\u00e0 per le moderne tecnologie di contribuire a valorizzare le relazioni familiari tra il minore e il genitore non pi\u00f9 convivente con lui.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-231997 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/08\/dipendenza-da-cellulare.jpg\" alt=\"\" width=\"540\" height=\"272\" title=\"\"><\/p>\n<p>Diverse sentenze, per cercare di avvicinare il <strong>genitore<\/strong> non convivente alla prole, hanno stabilito che il padre possa coltivare il rapporto relazionale con i propri figli anche <strong>mediante l\u2019utilizzo di webcam<\/strong>. Certamente, il diritto di visita online e il collegamento per via telematica non potranno mai sostituire la presenza fisica del genitore, ma costituisce una modalit\u00e0 attraverso la quale \u00e8 possibile dare attuazione al diritto del minore di mantenere in maniera pi\u00f9 ampia, a seguito della crisi familiare, rapporti continuativi e significativi con il genitore non collocatario.<\/p>\n<p>Infatti, la comunicazione attraverso la rete telematica costituisce senz\u2019altro uno strumento di supporto per il mantenimento del legame affettivo-relazionale tra il genitore e il figlio, ma sicuramente non \u00e8 ammissibile la sostituzione del rapporto virtuale agli incontri periodici tra genitore e figlio, che sono invece essenziali per potersi relazionare in maniera autentica. Si auspica che dalle tante connessioni virtuali in cui oggi si relaziona la famiglia e la societ\u00e0 si realizzino delle relazioni interpersonali nella concretezza della quotidianit\u00e0 che sfocino in una nuova societ\u00e0 pi\u00f9 ricca di autentici rapporti umani, nei quali vengano privilegiati la solidariet\u00e0, la collaborazione e il rispetto per gli altri.<\/p>\n<p>L\u2019evento \u00e8 <strong>accreditato<\/strong> presso l\u2019Ordine degli Avvocati di Cosenza e la partecipazione d\u00e0 diritto a n. 3 crediti formativi per gli avvocati. L\u2019ingresso \u00e8 libero e gratuito. A concludere i lavori, moderati dalla giornalista Giulia Fresca, sar\u00e0 lo scrittore e giornalista Attilio Sabato che, in occasione del convegno, presenter\u00e0 la sua ultima opera \u201cFacce da Facebook\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019AMI, l&#8217;associazione degli Avvocati Matrimonialisti Italiani &#8211; Sezione Distrettuale Catanzaro-Cosenza, parla dell\u2019influenza e delle conseguenze di social e internet nei rapporti familiari<\/p>\n","protected":false},"author":42,"featured_media":107904,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-107903","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/107903","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=107903"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/107903\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/107904"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=107903"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=107903"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=107903"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}