{"id":107917,"date":"2019-04-02T12:45:02","date_gmt":"2019-04-02T10:45:02","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-convenzioni-scadute-protestano-gli-operatori-di-supporto-al-118\/"},"modified":"2023-01-16T18:25:19","modified_gmt":"2023-01-16T17:25:19","slug":"285955-cosenza-convenzioni-scadute-protestano-gli-operatori-di-supporto-al-118","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/285955-cosenza-convenzioni-scadute-protestano-gli-operatori-di-supporto-al-118\/","title":{"rendered":"Cosenza, convenzioni scadute. Protestano gli operatori di supporto al 118"},"content":{"rendered":"<h4>Una protesta pacifica per chiedere che si faccia chiarezza sul futuro delle associazioni che si occupano del servizio di supporto al 118. Il responsabile della confraternita della Misericordia di Cosenza Luigi Solbaro &#8220;cos\u00ec non possiamo pi\u00f9 lavorare&#8221;<!--more--><\/h4>\n<p>.<\/p>\n<p>COSENZA &#8211; Hanno parcheggiato i loro mezzi di soccorsi davanti la sede dell&#8217;<strong>Asp di Cosenza, in via Alimena<\/strong>, per <strong>protestare in modo pacifico<\/strong> ma ottenere risposte certe. La Misericordia di Cosenza, Amantea e Trebisacce, la Nuova Croce Azzurra di Cosenza, la Montalto Soccorso ONLUS, l&#8217;Avas Presila, la Croce di Mira di Lungro, Papa Giovanni XIII Spezzano Sila, Life Soccorso Luzzi e l&#8217;Avam di Cosenza.\u00a0<strong>Nove asssociazioni<\/strong> che si ritrovano tutte nella stessa situazione:\u00a0<strong>convezioni scadute<\/strong> e <strong>mancanza dei rimborsi<\/strong> <strong>spesa del 2018 e dei primi 3 mesi del 2019.<\/strong>\u00a0Eppure, <strong>il loro supporto alle operazioni di soccorso \u00e8 vitale<\/strong> per non mandare all&#8217;aria tutto il sistema vista la carenza di mezzi del 118 ed un territorio\u00a0da gestire vasto come quello della provincia di Cosenza.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Luigi Solbaro<\/strong>,\u00a0responsabile della <strong>Confraternita della Misericordia di Cosenza<\/strong>, chiarisce i motivi della loro protesta &#8220;<em>ci tengo a precisare che <strong>la nostra \u00e8 una protesta pacifica ed educata<\/strong>. Abbiamo chiesto da tempo un incontro per il<strong> rinnovo della convezione del 118 scaduto 21 dicembre<\/strong> dello scorso anno. Ad oggi <strong>si va avanti solo con rinnovi<\/strong>, perch\u00e9 ad ogni scadenza succede che <strong>vengono puntualmente cambiati i vertici dell&#8217;Asp provinciale<\/strong> e quindi si riparte sempre daccapo. In pi\u00f9 questa volta <strong>non \u00e8 stato nemmeno stabilito l&#8217;impegno di spesa per il 2019<\/strong> e ci ritroviamo a marzo senza aver ricevuto i rimborsi dei mesi precedenti. Abbiamo dovuto sollecitare per prima cosa l&#8217;impegno di spesa del 2018 e dei primi 3 mesi del 2019 per il supporto 118. Poi, abbiamo sollecitato il rinnovo della convezione perch\u00e9 <strong>cos\u00ec non possiamo lavorare<\/strong><\/em>&#8220;.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/6500\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-285964\" src=\"https:\/\/quicosenza.it\/news\/6500\" alt=\"\" width=\"590\" height=\"297\" title=\"\"><\/a><\/p>\n<p><strong>Le risposte avute dall&#8217;Asp nell&#8217;incontro?<\/strong> &#8220;<em>l&#8217;impegno di spesa per i rimborsi dei soli primi 3 mesi del 2019, mentre sulla convezione ci \u00e8 stato ribadito che loro sono di transito e non possono fare nulla finch\u00e9 non verranno nominati i nuovi vertici dell&#8217;azienda provinciale. Dunque, rimaniamo ancora una volta senza convezione ma ci hanno comunque chiesto di non bloccare il servizio di supporto, visto che la maggior parte dei soccorsi a Cosenza e in provincia viene fatta proprio da noi\u00a0<strong>considerando che il 118 su Cosenza ha due sole macchine mentre una terza \u00e8 all&#8217;UNICAL<\/strong>. E senza dimenticare che <strong>i punti di emergenza territoriale <\/strong><\/em>(<em>le cosiddette P.E.T)\u00a0<strong>hanno sempre a supporto un&#8217;associazione<\/strong>\u00a0se pensiamo a comuni come Cassano, Castrovillari, Corigliano, Trebisacce, Cariati e cos\u00ec via, altrimenti non si riuscirebbe assolutamente\u00a0a soddisfare la richiesta di intervento&#8221;.<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una protesta pacifica per chiedere che si faccia chiarezza sul futuro delle associazioni che si occupano del servizio di supporto al 118. Il responsabile della confraternita della Misericordia di Cosenza Luigi Solbaro &#8220;cos\u00ec non possiamo pi\u00f9 lavorare&#8221;<\/p>\n","protected":false},"author":46,"featured_media":107918,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-107917","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/107917","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=107917"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/107917\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/107918"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=107917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=107917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=107917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}