{"id":107971,"date":"2019-04-03T10:30:22","date_gmt":"2019-04-03T08:30:22","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/unical-link-studenti-indipendenti-sulla-tassazione-tu-da-me-volevi-solo-soldi\/"},"modified":"2023-01-16T18:25:23","modified_gmt":"2023-01-16T17:25:23","slug":"286088-unical-link-studenti-indipendenti-sulla-tassazione-tu-da-me-volevi-solo-soldi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/286088-unical-link-studenti-indipendenti-sulla-tassazione-tu-da-me-volevi-solo-soldi\/","title":{"rendered":"Unical, Link-Studenti Indipendenti sulla tassazione: \u00abTu da me, volevi solo soldi\u00bb"},"content":{"rendered":"<h4>Non \u00e8 solo la frase di una canzone molto popolare ma l\u2019attuale modello di gestione del sistema universitario italiano.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>RENDE &#8211; Sempre meno studentesse e studenti hanno la possibilit\u00e0 oggi, di permettersi gli studi universitari a causa della crescente tassazione. L\u2019Universit\u00e0 della Calabria in particolare &#8211; riporta una nota a firma di Link- Studenti Indipendenti &#8211; ha visto per questo motivo una notevole diminuzione della popolazione studentesca. Un paradosso per un Ateneo nato per essere totalmente gratuito e permettere cos\u00ec alle giovani e ai giovani calabresi di avere le stesse possibilit\u00e0 di chiunque sia nato in un\u2019altra regione d\u2019Italia&#8221;.<\/p>\n<p>&#8220;Partiamo oggi, in tutti gli Atenei d\u2019Italia, con una campagna sulla tassazione universitaria. Prima che sia troppo tardi, facciamoci sentire. Davanti a noi abbiamo la discussione del nuovo bando tasse e, soprattutto, la richiesta di alcune regioni del Nord Italia di accedere a maggiore autonomia. Questo comporter\u00e0 sempre meno fondi per i cittadini del sud Italia, in particolare per le universit\u00e0.<strong> L\u2019Italia \u00e8 l\u2019ultimo Paese dell\u2019Unione Europea per spesa nella scuola, universit\u00e0 e ricerca.<\/strong> Crediamo sia arrivato il momento di invertire la rotta.<\/p>\n<p>Tenendo presente come orizzonte la totale gratuiti\u00e0 del sistema universitario, riteniamo ora fondamentale proporre:<\/p>\n<p>-maggiore progressivit\u00e0 della tassazione universitaria, introducendo pi\u00f9 scaglioni andando cos\u00ec ad allegerire il peso della contribuzione sui ceti medi;<br \/>\n-allargamento no tax area;<br \/>\n-eliminazione della figura dell\u2019idoneo non beneficiario attraverso l\u2019aumento dei fondi statali e regionali per il diritto allo studio, per garantire la copertura totale di tutte le borse di studio;<br \/>\n-pagamento delle borse di studio ad inizio anno;<br \/>\n-pagamento di tutti i premi di laurea;<br \/>\n-ripensamento delle modalit\u00e0 di calcolo ISEE, a causa della sua illogicit\u00e0 per il quale risulta ricco chi ricco non \u00e8.<\/p>\n<p style=\"text-align: right;\"><strong>Link- Studenti Indipendenti<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Non \u00e8 solo la frase di una canzone molto popolare ma l\u2019attuale modello di gestione del sistema universitario italiano.<\/p>\n","protected":false},"author":21,"featured_media":107972,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[],"class_list":["post-107971","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-universita"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/107971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=107971"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/107971\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/107972"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=107971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=107971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=107971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}