{"id":108041,"date":"2019-04-04T11:38:53","date_gmt":"2019-04-04T09:38:53","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/formaggi-e-ricotte-pieni-di-muffa-e-avariati-i-nas-sequestrano-1-tonnellata-di-merce\/"},"modified":"2023-01-16T18:25:27","modified_gmt":"2023-01-16T17:25:27","slug":"286321-formaggi-e-ricotte-pieni-di-muffa-e-avariati-i-nas-sequestrano-1-tonnellata-di-merce","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/286321-formaggi-e-ricotte-pieni-di-muffa-e-avariati-i-nas-sequestrano-1-tonnellata-di-merce\/","title":{"rendered":"Formaggi e ricotte pieni di muffa e avariati. I NAS sequestrano 1 tonnellata di merce"},"content":{"rendered":"<h4>L&#8217;intervento in un caseificio di una cooperativa agricola nel comune di Joppolo nel Vibonese. Formaggi e ricotte,\u00a0in cattivo stato di conservazione, erano destinati anche a catene di supermercati nazionali. Denunciato il legale rappresentante dell&#8217;azienda<!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>JOPPOLO (VV) &#8211;\u00a0 <strong>Mille forme di formaggio e ricotta<\/strong>, per un peso complessivo di <strong>1.000 chilogrammi<\/strong>, in cattivo stato di conservazione dovuto alla presenza di muffa ed in avanzato stato di deterioramento sono stati posti sotto sequestro dai Carabinieri del Nas di Catanzaro che, unitamente ai militari della Stazione di Joppolo e in collaborazione con il personale veterinario dell&#8217;Asp di Vibo Valentia, hanno proceduto al sequestro della merce in un c<strong>aseificio di una cooperativa agricola<\/strong> ubicato nella frazione Caroniti del comune di Joppolo, nel Vibonese. Il formaggio era riposto in locali per la stagionatura in<strong> carenti condizioni igienico-strutturali<\/strong>.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/6526\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-286323\" src=\"https:\/\/quicosenza.it\/news\/6526\" alt=\"Formaggi e ricotte sequestro\" width=\"598\" height=\"342\" title=\"\"><\/a><\/p>\n<p>I formaggi erano anche privi delle<strong> indicazioni di legge sulla tracciabilit\u00e0 degli alimenti<\/strong> e pronti per la commercializzazione I (d<strong>estinati anche a catene di supermercati di livello nazionale<\/strong>) per un importo complessivo di <strong>150mila euro<\/strong>. I militari hanno pertanto disposto la chiusura-sospensione dei locali nei quali sono state riscontrate le anomalie igienico-strutturale mentre e\u00a0<strong>denunciato alla Procura di Vibo Valentia<\/strong> per la detenzione del formaggio in cattivo stato di conservazione il legale rappresentante dell&#8217;azienda, P.Z., 49 anni, di Joppolo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&#8217;intervento in un caseificio di una cooperativa agricola nel comune di Joppolo nel Vibonese. Formaggi e ricotte,\u00a0in cattivo stato di conservazione, erano destinati anche a catene di supermercati nazionali. Denunciato il legale rappresentante dell&#8217;azienda<\/p>\n","protected":false},"author":46,"featured_media":108042,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-108041","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/108041","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=108041"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/108041\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/108042"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=108041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=108041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=108041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}