{"id":108163,"date":"2019-04-06T14:45:38","date_gmt":"2019-04-06T12:45:38","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/de-franco-a-pochi-mesi-dal-voto-manna-assume-dirigenti-a-tempo-determinato\/"},"modified":"2023-01-16T18:25:35","modified_gmt":"2023-01-16T17:25:35","slug":"286719-de-franco-a-pochi-mesi-dal-voto-manna-assume-dirigenti-a-tempo-determinato","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/286719-de-franco-a-pochi-mesi-dal-voto-manna-assume-dirigenti-a-tempo-determinato\/","title":{"rendered":"De Franco: &#8220;a pochi mesi dal voto, Manna assume dirigenti a tempo determinato&#8221;"},"content":{"rendered":"<h4>Secondo Gianfranco De Franco, a meno di 2 mesi dal voto, il sindaco Manna e Infantino deliberano di assumere dirigenti a tempo determinato oltre il limite del mandato: &#8220;deplorevole&#8221;.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>RENDE &#8211; La segnalazione arriva dal segretario di &#8220;Insieme per Rende&#8221; che parla di &#8220;una strana delibera di giunta (la numero 94 del 1 aprile 2019) con la quale si chiede alla Cosfel (l\u2019organo che vigila sulla sostenibilit\u00e0 dei costi relativi al personale comunale) l\u2019assunzione a tempo determinato di ben <strong>4 dirigenti, alcuni per 2 anni, altri per 3&#8243;.<\/strong><\/p>\n<p>&#8220;La conseguenza dell\u2019approvazione di questa richiesta da parte della Cosfel &#8211; spiega De Franco &#8211; sarebbe il prolungamento del contratto per <strong>4 dirigenti oltre i limiti del mandato di Manna,<\/strong> che sono esattamente uguali al numero di dirigenti di cui l\u2019amministrazione ha bloccato il concorso pubblico. In altre parole, Manna blocca le assunzioni regolari tramite concorso e sblocca quelle che pu\u00f2 manovrare a suo piacimento&#8221;.<\/p>\n<p>&#8220;In questo modo aggira un&#8217;ordinanza (quella relativa al ricorso dei concorrenti al predetto concorso) del Tar che si pronuncer\u00e0 nel merito a fine maggio 2019 con sentenza.<strong> Il tutto avviene a meno di 2 mesi dalla scadenza del mandato e prima che il Tar si pronunci sul ricorso<\/strong>. Ove il Tar dovesse accogliere le ragioni dei ricorrenti, il Comune si troverebbe, da una parte, obbligato a concludere le procedure concorsuali e, dall&#8217;altra, a mantenere in servizio i dirigenti incaricati con il rischio concreto di trovarsi a gestire un contenzioso per risarcimento danni agli uni piuttosto che agli altri, con conseguente danno erariale per le casse comunali&#8221;.<\/p>\n<p>&#8220;Questo tipo di giochetti, se dovessimo essere noi i vincitori delle elezioni, non si verificheranno pi\u00f9. I veri protagonisti della gestione del personale &#8211; scrive De Franco &#8211; saranno gli stessi dipendenti e i dirigenti non potranno essere nominati senza un\u2019adeguata e trasparente valutazione e il gradimento a scrutinio segreto da parte dei lavoratori&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Secondo Gianfranco De Franco, a meno di 2 mesi dal voto, il sindaco Manna e Infantino deliberano di assumere dirigenti a tempo determinato oltre il limite del mandato: &#8220;deplorevole&#8221;.<\/p>\n","protected":false},"author":21,"featured_media":108164,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[44],"tags":[],"class_list":["post-108163","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/108163","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/21"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=108163"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/108163\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/108164"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=108163"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=108163"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=108163"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}