{"id":108240,"date":"2019-04-08T15:25:10","date_gmt":"2019-04-08T13:25:10","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/omicidio-paterno-calabro-un-litigio-tra-zio-e-nipote\/"},"modified":"2023-01-16T18:25:40","modified_gmt":"2023-01-16T17:25:40","slug":"287067-omicidio-paterno-calabro-un-litigio-tra-zio-e-nipote","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/287067-omicidio-paterno-calabro-un-litigio-tra-zio-e-nipote\/","title":{"rendered":"Omicidio Paterno Calabro: un litigio tra zio e nipote"},"content":{"rendered":"<h4>Una lite furiosa e poi la morte. Il nipote uccide lo zio a colpi di pistola e si costituisce<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>PATERNO CALABRO (CS) &#8211; L&#8217;omicidio \u00e8 avvenuto nel comune di Paterno Calabro, in localit\u00e0 Pugliano, in una zona di periferia, in campagna, al culmine di una lite tra zio e nipote. Sul posto i militari dell&#8217;Arma della compagnia di Cosenza. Presente il capitano Merola, i carabinieri del Ris, il medico legale e i sanitari del 118.<\/p>\n<p>Ad essere rimasto ucciso a colpi di arma da fuoco <strong>Angelo Presta, di<\/strong> 54 anni risultante essere lo zio di <strong>Salvatore Presta, 35 anni<\/strong>. Il nipote si \u00e8 immediatamente costituito. Attualmente il giovane \u00e8 in stato di fermo presso la stazione dei carabinieri di Dipignano dove \u00e8 stato posto ad interrogatorio dal magistrato di turno della Procura della Repubblica di Cosenza. I rapporti tra zio e nipote erano tesi da tempo.<\/p>\n<p>Dalle dichiarazioni autoaccusatorie rilasciate dal nipote della vittima sono state pertanto ricostruite le sue responsabilit\u00e0 penali dello stesso. Il diverbio sarebbe iniziato nella mattinata, scatenato da futili motivi, quando Salvatore ha impugnato la pistola, regolarmente detenuto per uso sportivo da suo zio, e ha esploso colpi di arma da fuoco contro la vittima.\u00a0Il magistrato di turno presso la Procura della Repubblica di Cosenza, informato dell\u2019accaduto, ha raggiunto il luogo del delitto cos\u00ec come i carabinieri che hanno avviato una minuziosa attivit\u00e0 di sopralluogo volta all\u2019esatta ricostruzione dei fatti nonch\u00e9 all\u2019accertamento del movente. Il trentacinquenne \u00e8 stato dichiarato in arresto\u00a0per il reato di omicidio volontario aggravato.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Una lite furiosa e poi la morte. Il nipote uccide lo zio a colpi di pistola e si costituisce<\/p>\n","protected":false},"author":44,"featured_media":108241,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-108240","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/108240","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=108240"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/108240\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/108241"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=108240"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=108240"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=108240"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}