{"id":108384,"date":"2019-04-11T13:12:47","date_gmt":"2019-04-11T11:12:47","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/blitz-dei-nas-di-cosenza-nelle-mense-scolastiche-accertate-diverse-irregolarita\/"},"modified":"2023-01-16T18:25:50","modified_gmt":"2023-01-16T17:25:50","slug":"287599-blitz-dei-nas-di-cosenza-nelle-mense-scolastiche-accertate-diverse-irregolarita","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/287599-blitz-dei-nas-di-cosenza-nelle-mense-scolastiche-accertate-diverse-irregolarita\/","title":{"rendered":"Blitz dei Nas di Cosenza nelle mense scolastiche. Accertate diverse irregolarit\u00e0"},"content":{"rendered":"<h4>Da alcuni locali non idonei nei quali i bambini mangiavano alle apparecchiature obsolete per la preparazione dei cibi. Diverse le irregolarit\u00e0 riscontrare e segnalate all&#8217;Autorit\u00e0 Sanitaria.\u00a0 Alcuni\u00a0operatori senza i titoli professionali necessari al confezionamento dei pasti<!--more--><\/h4>\n<p>.<\/p>\n<p>COSENZA &#8211; Sono diverse le irregolarit\u00e0 riscontrate dai carabinieri del NAS durante i controlli effettuati in varie mense scolastiche. A tutela della salute dei pi\u00f9 piccoli, sono stati passati al\u00a0setaccio dei militari i servizi di ristorazione di diversi istituti scolastici cosentini.\u00a0Pi\u00f9 in dettaglio, dalle verifiche effettuate dai Carabinieri delle Compagnie di Cosenza e Rende congiuntamente ai militari del NAS di Cosenza \u00e8 emerso che, in alcuni casi, i <strong>pasti venissero consumati dai bambini in locali non idonei allo scopo e privi dei prescritti requisiti igienico-sanitari<\/strong>, che le apparecchiature destinate alla preparazione degli alimenti fossero in molti caso<strong> obsolete<\/strong> e che non tutti gli operatori impiegati fossero<strong> in possesso dei titoli professionali <\/strong>necessari al confezionamento dei pasti.\u00a0Le infrazioni riscontrate, oltre a prevedere l\u2019irrogazione delle previste sanzioni pecuniarie, sono state oggetto di <strong>comunicazione all\u2019Autorit\u00e0 Sanitaria che ha intimato ai gestori del servizio l\u2019immediato adeguamento ai requisiti di legge<\/strong> a pena della sospensione del servizio.<\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<h4>Correttamente segnalata nei cibi\u00a0<strong>la presenza di allergeni<\/strong><\/h4>\n<p>Durante i sopralluoghi, inoltre, i Carabinieri del NAS hanno integrato le verifiche con la raccolta di informazioni sulla tipologia dei men\u00f9 predisposti in relazione alle possibili esigenze nutrizionali connesse a situazioni di intolleranze alimentari ed esigenze etniche rappresentate dai familiari dei frequentatori delle scuole focalizzando l\u2019attenzione anche sulla <strong>corretta applicazione dell\u2019obbligo di indicare la presenza di allergeni nelle pietanze<\/strong>, accertando una generale <strong>aderenza alle disposizioni da parte delle ditte di catering<\/strong>.\u00a0La tutela della salute a favore delle fasce pi\u00f9 deboli e sensibili della popolazione \u00e8 da sempre un obiettivo prioritario nelle attivit\u00e0 istituzionali svolte dai Carabinieri, assumendo particolare valore sociale soprattutto per i bambini e gli adolescenti. Ecco perch\u00e9 analoghi controlli <strong>saranno condotti con il medesimo scrupolo fino alla fine dell\u2019anno scolastico<\/strong>.<\/p>\n<p>Il Comando Provinciale Carabinieri di Cosenza, d\u2019intesa con il Comando Carabinieri per la Tutela della Salute, fin dall&#8217;inizio dell\u2019attuale anno scolastico ha avviato un\u2019articolata c<strong>ampagna di controllo sui servizi di ristorazione nelle scuole di ogni ordine e livello della provincia<\/strong>.\u00a0L\u2019obiettivo \u00e8 accertare le condizioni d\u2019igiene dei locali di preparazione e di somministrazione dei pasti, la rispondenza dei men\u00f9 ai capitolati d\u2019appalto, la corretta gestione degli alimenti utilizzati, tenendo in considerazione le esigenze nutrizionali e salutistiche dei ragazzi.\u00a0I risultati conseguiti sono di assoluto rilievo poich\u00e9 hanno richiamato l\u2019attenzione di tutte le parti, i gestori dei servizi, gli operatori scolastici e le famiglie, su tematiche particolarmente delicate, quali igiene, correttezza nella conservazione e <b>lavorazione degli alimenti e tranciabilit\u00e0\u00a0delle materie prime<\/b>, aspetti che divengono ancora pi\u00f9 rilevanti quando in gioco \u00e8 la salute dei pi\u00f9 piccoli.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da alcuni locali non idonei nei quali i bambini mangiavano alle apparecchiature obsolete per la preparazione dei cibi. Diverse le irregolarit\u00e0 riscontrare e segnalate all&#8217;Autorit\u00e0 Sanitaria.\u00a0 Alcuni\u00a0operatori senza i titoli professionali necessari al confezionamento dei pasti<\/p>\n","protected":false},"author":46,"featured_media":108385,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-108384","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/108384","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=108384"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/108384\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/108385"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=108384"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=108384"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=108384"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}