{"id":108484,"date":"2019-04-13T14:00:10","date_gmt":"2019-04-13T12:00:10","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/parte-da-civita-la-marathon-degli-aragonesi\/"},"modified":"2023-01-16T18:25:56","modified_gmt":"2023-01-16T17:25:56","slug":"287918-parte-da-civita-la-marathon-degli-aragonesi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/287918-parte-da-civita-la-marathon-degli-aragonesi\/","title":{"rendered":"Parte da Civita la Marathon degli Aragonesi"},"content":{"rendered":"<h4>Ritorna la gran fondo che quest\u2019anno partir\u00e0 da Civita, lo splendido borgo del Pollino affacciato sulle gole del Raganello<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>CASTROVILLARI \u2013 Parte da Civita la Marathon degli Aragonesi. La nuova tappa di partenza partenza ridisegna il percorso che porta all\u2019imperticata, la pi\u00f9 temuta salita della gara che si \u00e8 contraddistinta negli anni come segno identitario ed \u00e8 il momento di vera selezione per gli atleti che vogliono arrivare primi al traguardo. La Marathon vuole anche valorizzare il territorio e le comunit\u00e0 che accolgono l\u2019evento, che \u00e8 una delle prerogative che l\u2019associazione sportiva, che l\u2019ha inserita nel circuito nazionale del Trofeo dei Parchi Naturali.<\/p>\n<p>\u00abLa sfida di gambe e sudore, sulle ripide pendenze dell&#8217;imperticata, \u00e8 pronta ad emozionare ancora i bikers del sud Italia ed i tanti appassionati che hanno a cuore questo grande appuntamento di sport e promozione del territorio. La Marathon degli Aragonesi, organizzata dall&#8217;Asd Ciclistica Castrovillari, per l\u2019edizione 2019 in programma il 2 giugno ha di fatto aperto le iscrizioni della gara per ruote grasse che quest\u2019anno partir\u00e0 dal borgo di Civita, la splendida localit\u00e0 arb\u00ebreshe che domina la valle del Raganello nel contesto naturalistico del Parco nazionale del Pollino che come ente patrocina e sostiene l\u2019evento\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ritorna la gran fondo che quest\u2019anno partir\u00e0 da Civita, lo splendido borgo del Pollino affacciato sulle gole del Raganello<\/p>\n","protected":false},"author":48,"featured_media":108485,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-108484","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/108484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/48"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=108484"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/108484\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/108485"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=108484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=108484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=108484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}