{"id":108581,"date":"2019-04-15T18:14:06","date_gmt":"2019-04-15T16:14:06","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/catanzaro-118-mancano-ambulanze-niente-soccorsi\/"},"modified":"2023-01-16T18:26:03","modified_gmt":"2023-01-16T17:26:03","slug":"288282-catanzaro-118-mancano-ambulanze-niente-soccorsi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/288282-catanzaro-118-mancano-ambulanze-niente-soccorsi\/","title":{"rendered":"Catanzaro, 118: &#8220;mancano ambulanze&#8221;, niente soccorsi"},"content":{"rendered":"<h4>Per il presidente nazionale del Sis 118 Balzanelli un gravissimo deficit di Sistema che evidenzia la necessit\u00e0 di una riforma legislativa nazionale<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>ROMA &#8211; Ieri, domenica delle Palme, un&#8217;anziana donna perde i sensi durante la celebrazione della messa nel quartiere San Leonardo di Catanzaro. Immediata la telefonata al 118, ma la risposta lascia sconcertati: &#8220;Al momento non ci sono ambulanze&#8221;. La donna \u00e8 stata soccorsa da un medico che si trovava in chiesa. A commentare il caso, il presidente nazionale del Sis 118 Mario Balzanelli, che attacca: &#8220;Assolutamente impensabile che nella necessit\u00e0 di gestire un codice rosso, situazione clinica caratterizzata da un pericolo imminente di perdere la vita, la Centrale Operativa di un Sistema 118 possa trovarsi nella pi\u00f9 totale impossibilit\u00e0 di fornire una risposta adeguata di soccorso.<\/p>\n<p>Motivando, peraltro a pi\u00f9 riprese la momentanea incapacit\u00e0 funzionale con la mancanza dei mezzi da inviare sulla scena dell&#8217;evento&#8221; &#8220;Impensabile, inaccettabile, irricevibile&#8221;, ripete Balzanelli, &#8220;una situazione che oltre a configurare chiaramente un lampante gravissimo deficit di Sistema, evidenzia la necessit\u00e0 ormai improcrastinabile di una riforma legislativa nazionale del Sistema dell&#8217;Emergenza Territoriale 118&#8221;. Per il presidente del 118, la riforma deve portare a un &#8220;netto potenziamento rispetto allo stato attuale, peraltro cos\u00ec assurdamente smantellato da politiche precedenti e cos\u00ec disomogeneo tra le regioni, in quanto a concezione globale di Sistema, al numero delle Centrali Operative, al personale sanitario medico-infermieristico dedicato, al personale autista-soccorritore dedicato, ai mezzi di soccorso&#8221;. &#8220;Invoco ancora una volta conclude &#8211; l&#8217;azione riformatrice del ministro Grillo perch\u00e9 il Sistema 118 nazionale merita di essere valorizzato e sostenuto in modo appropriato dal governo e dal legislatore&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<h2 style=\"text-align: center;\"><span style=\"color: #0000ff;\">LEGGI ANCHE<\/span><\/h2>\n<p>https:\/\/quicosenza.it\/news\/calabria\/288130-sanita-codacons-mancano-ambulanze-e-si-rischia-di-morire<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per il presidente nazionale del Sis 118 Balzanelli un gravissimo deficit di Sistema che evidenzia la necessit\u00e0 di una riforma legislativa nazionale<\/p>\n","protected":false},"author":44,"featured_media":108582,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-108581","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/108581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/44"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=108581"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/108581\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/108582"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=108581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=108581"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=108581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}