{"id":108673,"date":"2019-04-17T18:45:48","date_gmt":"2019-04-17T16:45:48","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/continua-a-tremare-la-terra-tra-bisignano-acri-e-santa-sofia-due-scosse-in-15-minuti\/"},"modified":"2023-01-16T18:26:09","modified_gmt":"2023-01-16T17:26:09","slug":"288643-continua-a-tremare-la-terra-tra-bisignano-acri-e-santa-sofia-due-scosse-in-15-minuti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/288643-continua-a-tremare-la-terra-tra-bisignano-acri-e-santa-sofia-due-scosse-in-15-minuti\/","title":{"rendered":"Continua a tremare la terra tra Bisignano, Acri e Santa Sofia. Due scosse in 15 minuti"},"content":{"rendered":"<h4>Continuano le scosse tra Santa Sofia D&#8217;Epiro, Bisignano e Acri. Tra le 20:03 e le 20:17 due terremoti di magnitudo 2.6 e 2.7, sono stati registrati e avvertiti dalla popolazione<!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>SANTA SOFIA D&#8217;EPIRO (CS) &#8211;\u00a0<strong>Due nuove scosse di terremoto<\/strong> (\u00e8 il quarto evento in poco pi\u00f9 di una settimana) sono state registrate questa sera dai sismologi dell\u2019Istituto Nazionale di Geofisica e Vulcanologia in provincia di Cosenza. Ancora una volta, <a href=\"https:\/\/quicosenza.it\/news\/6666\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\"><strong>come capitato nelle precedenti scosse<\/strong><\/span><\/a>, l&#8217;epicentro \u00e8 stato localizzato tra le zone di<strong>\u00a0Santa Sofia D&#8217;Epiro, San Demetrio Corone, Acri e Bisignano <\/strong>e ancora una volta ad una\u00a0profondit\u00e0 <strong>di 11 Km<\/strong>.<\/p>\n<p>La magnitudo della scossa \u00e8 stata di\u00a0<strong>2.6 sulla<\/strong>\u00a0<b>scala Richter alle ore 20:03, seguita da una seconda scossa registrata alle 20:17 e di magnitudo 2.7.\u00a0<\/b>Il sisma \u00e8 stato nitidamente avvertito dalla popolazione anche nei vicini comuni di Rose, Tarsia, Luzzi, San Cosmo Albanese e Vaccarizzo Albanese. Non si segnalano danni a cose o persone.<\/p>\n<h4><span style=\"color: #ff0000;\">Comuni entro 20 km dall&#8217;epicentro<\/span><\/h4>\n<table width=\"301\">\n<thead>\n<tr>\n<td><strong>Comune<\/strong><\/td>\n<td><strong>Provincia<\/strong><\/td>\n<td width=\"110\"><strong>Distanza KM<\/strong><\/td>\n<\/tr>\n<\/thead>\n<tbody>\n<tr>\n<td>Santa Sofia d&#8217;Epiro<\/td>\n<td>CS<\/td>\n<td width=\"110\">2<\/td>\n<\/tr>\n<tr>\n<td>San Demetrio Corone<\/td>\n<td>CS<\/td>\n<td width=\"110\">5<\/td>\n<\/tr>\n<tr>\n<td>Bisignano<\/td>\n<td>CS<\/td>\n<td width=\"110\">5<\/td>\n<\/tr>\n<tr>\n<td>Acri<\/td>\n<td>CS<\/td>\n<td width=\"110\">6<\/td>\n<\/tr>\n<tr>\n<td>San Cosmo Albanese<\/td>\n<td>CS<\/td>\n<td width=\"110\">9<\/td>\n<\/tr>\n<tr>\n<td>Luzzi<\/td>\n<td>CS<\/td>\n<td width=\"110\">10<\/td>\n<\/tr>\n<tr>\n<td>Vaccarizzo Albanese<\/td>\n<td>CS<\/td>\n<td width=\"110\">10<\/td>\n<\/tr>\n<tr>\n<td>Tarsia<\/td>\n<td>CS<\/td>\n<td width=\"110\">11<\/td>\n<\/tr>\n<tr>\n<td>San Giorgio Albanese<\/td>\n<td>CS<\/td>\n<td width=\"110\">12<\/td>\n<\/tr>\n<tr>\n<td>Terranova da Sibari<\/td>\n<td>CS<\/td>\n<td width=\"110\">14<\/td>\n<\/tr>\n<tr>\n<td>Spezzano Albanese<\/td>\n<td>CS<\/td>\n<td width=\"110\">15<\/td>\n<\/tr>\n<tr>\n<td>Rose<\/td>\n<td>CS<\/td>\n<td width=\"110\">15<\/td>\n<\/tr>\n<tr>\n<td>San Lorenzo del Vallo<\/td>\n<td>CS<\/td>\n<td width=\"110\">15<\/td>\n<\/tr>\n<tr>\n<td>Torano Castello<\/td>\n<td>CS<\/td>\n<td width=\"110\">17<\/td>\n<\/tr>\n<tr>\n<td>Corigliano Calabro<\/td>\n<td>CS<\/td>\n<td width=\"110\">18<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Continuano le scosse tra Santa Sofia D&#8217;Epiro, Bisignano e Acri. Tra le 20:03 e le 20:17 due terremoti di magnitudo 2.6 e 2.7, sono stati registrati e avvertiti dalla popolazione<\/p>\n","protected":false},"author":46,"featured_media":108674,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-108673","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/108673","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=108673"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/108673\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/108674"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=108673"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=108673"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=108673"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}