{"id":108715,"date":"2019-04-18T17:42:30","date_gmt":"2019-04-18T15:42:30","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/precari-di-maio-vogliamo-lavoro-non-reddito-lui-risolveremo-tutto-dateci-tempo\/"},"modified":"2023-01-16T18:26:11","modified_gmt":"2023-01-16T17:26:11","slug":"288805-precari-di-maio-vogliamo-lavoro-non-reddito-lui-risolveremo-tutto-dateci-tempo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/288805-precari-di-maio-vogliamo-lavoro-non-reddito-lui-risolveremo-tutto-dateci-tempo\/","title":{"rendered":"Precari a Di Maio &#8220;vogliamo lavoro non reddito. Lui &#8220;risolveremo tutto, dateci tempo&#8221;"},"content":{"rendered":"<h4>Atteso e reclamato a gran voce, Luigi Di Maio ha parlato ai tanti lavoratori calabresi scesi in piazza davanti alla Prefettura di Reggio Calabria chiedendo lavoro e stabilit\u00e0 &#8220;ascolto tutto e sono qui. Sappiamo bene che dobbiamo risolvere ancora tante questioni, ma dateci tempo&#8221;<!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>REGGIO CALABRIA &#8211; Un&#8217;attesa senza alcun cenno di contestazione, ma di speranza per una possibile soluzione alle loro vicende. E&#8217; quella di <strong>decine di lavoratori, appartenenti alle pi\u00f9 svariate categorie di precari<\/strong> di cui \u00e8 costellata la galassia del lavoro, soprattutto al sud.\u00a0Hanno atteso il Ministro Di Maio <strong>per sollecitare un suo intervento e quello del Governo per porre fine al loro stato di perenne precariato<\/strong> nel quale vivono da decenni.<\/p>\n<p>E luigi Di Maio, prima che iniziasse la conferenza stampa finale, <strong>\u00e8 andato ad incontrare i tanti cittadini che lo aspettavano<\/strong>. &#8220;<strong>R<\/strong><em>isolveremo tutto, dateci tempo<\/em>&#8221; ha risposto a chi, da pi\u00f9 parti, gli ha esposto la situazione che riguarda diverse categorie di lavoratori: <strong>i discontinui dei Vigili del fuoco, i tirocinanti di vari Ministeri, i precari Lsu-Lpu che in Calabria sono ancora migliaia<\/strong> e che da vent&#8217;anni lavorano negli Enti locali con un salario di 800 euro mensili. E poi il <strong>Coordinamento dei lavoratori psichiatrici<\/strong> che raggruppa centinaia di lavoratori delle cooperative sociali, quelli che assistono i malati psichiatrici, precari e spesso pagati con insopportabile ritardo dalle Asp.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/6676\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-288837\" src=\"https:\/\/quicosenza.it\/news\/6676\" alt=\"\" width=\"567\" height=\"340\" title=\"\"><\/a><\/p>\n<p><strong>Tutti chiedono lavoro stabile e sicuro e sono contro il <a href=\"https:\/\/quicosenza.it\/news\/6677\"><span style=\"color: #0000ff;\">reddito di cittadinanza<\/span><\/a><\/strong>.&#8221;n<em>oi qui in Calabria non vogliamo l&#8217;elemosina, vogliamo che si facciano investimenti e si crei lavoro<\/em>&#8220;, hanno detto al Ministro. Un<em> reddito che altri, nella stessa piazza esaltano, ringraziando il Ministro ed il Movimento 5 Stelle per questa misura&#8221;<\/em>. <strong>Di Maio ha ascoltato tutti con pazienza<\/strong>. &#8220;<em>sappiamo bene che dobbiamo risolvere ancora tante questioni. Nei Decreti che stiamo discutendo cercheremo di inserire le norme che servono per risolvere i vostri problemi. <strong>Ad altri ha detto di &#8220;scrivere al Ministero<\/strong><\/em>. <em>Ho sempre incontrato tutti, scrivetemi e ci incontriamo a Roma &#8211;<\/em> ha detto il Ministro &#8211; e<strong> molte sono vertenze che si trascinano da oltre vent&#8217;anni<\/strong>.<em> Pretendere che in otto mesi, da quando ci siamo insediati, si facesse tutto, mi sembra considerarci onnipotenti<\/em>&#8220;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Atteso e reclamato a gran voce, Luigi Di Maio ha parlato ai tanti lavoratori calabresi scesi in piazza davanti alla Prefettura di Reggio Calabria chiedendo lavoro e stabilit\u00e0 &#8220;ascolto tutto e sono qui. Sappiamo bene che dobbiamo risolvere ancora tante questioni, ma dateci tempo&#8221;<\/p>\n","protected":false},"author":46,"featured_media":108716,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-108715","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/108715","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=108715"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/108715\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/108716"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=108715"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=108715"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=108715"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}