{"id":108717,"date":"2019-04-18T18:52:18","date_gmt":"2019-04-18T16:52:18","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/cosenza-diventa-un-modello-per-la-sicurezza-durante-concerti-ed-eventi-pubblici\/"},"modified":"2023-01-16T18:26:12","modified_gmt":"2023-01-16T17:26:12","slug":"288850-cosenza-diventa-un-modello-per-la-sicurezza-durante-concerti-ed-eventi-pubblici","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/288850-cosenza-diventa-un-modello-per-la-sicurezza-durante-concerti-ed-eventi-pubblici\/","title":{"rendered":"Cosenza diventa un modello per la sicurezza durante concerti ed eventi pubblici"},"content":{"rendered":"<h4>Premiato in Consiglio regionale il Comandante della Polizia Municipale di Cosenza Giovanni De Rose<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Importante riconoscimento per il Comandante della Polizia Municipale di Cosenza, Giovanni De Rose, premiato oggi pomeriggio nella sala \u201cFederica Monteleone\u201d di Palazzo Campanella, sede del Consiglio Regionale calabrese, dal Presidente del Consiglio Regionale Nicola Irto e dal consigliere regionale Franco Sergio, durante la cerimonia \u201cEccellenze Calabresi &#8211; La Calabria che lavora, si muove e si afferma\u201d. Si tratta della manifestazione promossa dall\u2019associazione Socialmente, con il partenariato del Consiglio regionale, della Citt\u00e0 Metropolitana di Reggio Calabria e della Camera di Commercio di Reggio Calabria. <strong>Il riconoscimento al Comandante della Polizia Municipale di Cosenza Giovanni De Rose, \u00e8 stato attribuito nella sua qualit\u00e0 di Responsabile della Sicurezza degli eventi pubblici.<\/strong> Con questo importante riconoscimento le buone pratiche della Polizia Municipale cosentina, relativamente ai temi di safety e security nei grandi eventi pubblici, oltrepassano, dunque, i confini cittadini e diventano modello organizzativo di riferimento. Un premio che assume un valore ancora pi\u00f9 significativo, attese le numerose manifestazioni pubbliche organizzate dall\u2019amministrazione Comunale, che hanno richiamato in citt\u00e0 centinaia di migliaia di persone. Sui temi oggetto del premio \u201cEccellenze calabresi\u201d, l&#8217;esperienza accumulata dalla Polizia Municipale di Cosenza ha fatto s\u00ec che gli eventi venissero accompagnati da ogni cautela e fossero agevolmente fruibili, pur in presenza di una serie di precise e rigorose prescrizioni a tutela della pubblica incolumit\u00e0.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-288852 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/04\/la-premiazione-del-Comandante-della-Polizia-Municipale-Giovanni-De-Rose-158x280.jpg\" alt=\"\" width=\"371\" height=\"653\" title=\"\">&#8212;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Premiato in Consiglio regionale il Comandante della Polizia Municipale di Cosenza Giovanni De Rose<\/p>\n","protected":false},"author":43,"featured_media":108718,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[],"class_list":["post-108717","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/108717","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=108717"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/108717\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/108718"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=108717"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=108717"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=108717"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}