{"id":108939,"date":"2019-04-24T08:18:44","date_gmt":"2019-04-24T06:18:44","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/paola-il-programma-del-v-centenario-della-canonizzazione-di-san-francesco\/"},"modified":"2023-01-16T18:26:27","modified_gmt":"2023-01-16T17:26:27","slug":"289576-paola-il-programma-del-v-centenario-della-canonizzazione-di-san-francesco","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/289576-paola-il-programma-del-v-centenario-della-canonizzazione-di-san-francesco\/","title":{"rendered":"Paola, il programma del V Centenario della canonizzazione di San Francesco"},"content":{"rendered":"<h4>Un programma religioso con appuntamenti di preghiere e di riflessione nel cammino della fede e sui passi di San Francesco di Paola, quello che interesser\u00e0 l\u2019intera Comunit\u00e0 dei Minimi e dei fedeli nella ricorrenza del V centenario della sua Canonizzazione avvenuta il Primo Maggio del 1519.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>PAOLA (CS) &#8211; Inizieranno <strong>oggi<\/strong>, dalle 18.30, presso la Chiesa della Madonna del Carmine di Sotterra con la visita della Reliquia del Sacro Mantello e la Santa Messa i festeggiamenti patronali dedicati a San Franceso.<\/p>\n<p><strong>Venerd\u00ec 26 aprile<\/strong> alle 17.00 la Reliquia del Sacro Mantello giunger\u00e0 presso la Chiesa di Santa Maria degli Angeli a Sant\u2019Agata. Dopo i Vespri il Sacro Mantello in processione raggiunger\u00e0 la Chiesa di S. Maria di Portosalvo sita in rione Colonne. Seguir\u00e0 la S. Messa.<\/p>\n<p><strong>Luned\u00ec 29 aprile<\/strong> \u00e8 previsto il Pellegrinaggio al Santuario della Forania Marina con l\u2019arrivo dei pellegrini alle 17.15. A seguire la preghiera del S. Rosario. Alle 18.00 la Solenne Concelebrazione Eucaristica verr\u00e0 presieduta da Don Mauro Fratucci, Vicario Foraneo della Zona Marina.<\/p>\n<p><strong>Mercoled\u00ec 1 maggio<\/strong>, in occasione della ricorrenza del V Centenario della Canonizzazione di San Francesco (1 maggio 1519-2019), alle 11.30 la Solenne Concelebrazione Eucaristica presso il Santuario di San Francesco verr\u00e0 presieduta da S. Ecc. Mons. Francesco Nol\u00e8, Arcivescovo Metropolita di Cosenza \u2013 Bisignano.<\/p>\n<p><strong>Gioved\u00ec 2 maggio<\/strong> \u2013 Patronato sulla Regione Calabria &#8211; Alle ore 10.00 a Catanzaro (Germaneto) verr\u00e0 tenuta la Cerimonia dell\u2019Intitolazione della Piazza antistante la Cittadella Regionale a S. Francesco di Paola. Alle 16.30 presso il Piazzale del Santuario verranno ricevuti i sindaci e le rappresentanze comunali ed a seguire sar\u00e0 tenuta la cerimonia dell\u2019offerta dell\u2019olio da parte dei sindaci di Acri (Cs), Montalto Uffugo (Cs), Paterno Calabro (Cs). A seguire alle 17.30 la Solenne Concelebrazione Eucaristica sar\u00e0 presieduta dal Rev.mo P. Gregorio Colatorti, Correttore Generale dell\u2019Ordine dei Minimi che vedr\u00e0, come da tradizione, l\u2019Accensione della Lampada votiva da parte del Presidente della Giunta Regionale della Calabria On. Mario Oliverio.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-213717 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2018\/04\/San_Francesco_di_Paola_1.jpg\" alt=\"\" width=\"482\" height=\"430\" title=\"\"><\/p>\n<p>Molto articolato il programma di <strong>Venerd\u00ec 3 maggio<\/strong> in occasione del Patronato sulla Gente di Mare d\u2019Italia; alle 09.00 il simulacro del Santo visiter\u00e0 la Casa Circondariale di Paola con a seguire la Santa Messa. Alle 10.30 il simulacro del Santo si sposter\u00e0 verso l\u2019Ospedale San Francesco di Paola dove verr\u00e0 celebrata la Santa Messa. Alle 15.45 arrivo del Sacro Mantello nel Porto di Cetraro e celebrazione della Santa Messa. Alle 16.30 il Sacro Mantello verr\u00e0 imbarcato sulla motovedetta della Capitaneria di Porto ed il corteo di barche con processione a mare raggiunger\u00e0 le acque di Paola verso le 18.00.<\/p>\n<p>Seguir\u00e0 la Celebrazione della Parola, la Benedizione del mare e il lancio della corona di alloro in memoria dei marittimi. Al termine della cerimonia il Sacro Mantello verr\u00e0 sbarcato e verr\u00e0 ripresa la processione verso Piazza IV Novembre. Qui verranno declamati alcuni brani tratti dagli scritti di san Francesco di Paola e dalla Bolla di Canonizzazione \u201cExcelsus Dominus\u201d. Seguir\u00e0 il Messaggio da parte di S. Em. Card. Beniamino Stella, prefetto per la Congregazione per il Clero. Verr\u00e0, quindi, ripresa la processione fino alla Chiesa di Montevergine con la Venerazione del Sacro Mantello e la preghiera personale fino alle ore 23.30.<\/p>\n<p>In caso di pioggia o di avverse condizione del mare, il S. Mantello si recher\u00e0 in forma privata nella Chiesa di S. Maria di Portosalvo sita in Rione Colonne con arrivo alle ore 18.00. Alle 18.30 Canto dei Vespri e inizio della processione secondo il programma previsto.<\/p>\n<p><strong>Sabato 4 maggio<\/strong> alle 9.30 giornata che segna il Patronato sulla citt\u00e0 di Paola, la Solenne concelebrazione Eucaristica sar\u00e0 presieduta da S. Em. Card. Beniamino Stella, prefetto per la Congregazione per il Clero.<\/p>\n<p>Alle 11.00 inizier\u00e0 la <strong>Processione<\/strong> del simulacro del Santo che si snoder\u00e0 seguendo il seguente percorso: Via San Francesco, Via Baracche, Via Motta. Alle 12.00 in Piazza Pizzini verr\u00e0 tenuta la tradizionale cerimonia della Consegna delle chiavi della Citt\u00e0 al Santo da parte del Sindaco di Paola. La processione proseguir\u00e0 per Corso C. Colombo, Via San Francesco, Via Duomo, Via Mulino, Via IV Maggio con Sosta a Montevergine. Alle 17.00 la processione riprender\u00e0 seguendo il percorso: Piazza IV Novembre, Via Nazionale, Viale della Libert\u00e0, Viale Stazione, strada nuova del Porto (proseguir\u00e0 per il mare solo il simulacro del Santo con le autorit\u00e0 civili e religiose \u2013 Benedizione del mare) &#8211; Ripresa della processione: Via Capo Spartivento, Via San Leonardo, Via dei Pignatari, Salita G. Gissing, Corso Roma, Piazza IV novembre, Corso Garibaldi, Via Nazionale, Corso C. Colombo, Via San Francesco, Santuario.<\/p>\n<p>La processione verr\u00e0, infine, accolta presso il Santuario di San Francesco di Paola e le cerimonie di concluderanno con il canto solenne del Te Deum di ringraziamento.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un programma religioso con appuntamenti di preghiere e di riflessione nel cammino della fede e sui passi di San Francesco di Paola, quello che interesser\u00e0 l\u2019intera Comunit\u00e0 dei Minimi e dei fedeli nella ricorrenza del V centenario della sua Canonizzazione avvenuta il Primo Maggio del 1519.<\/p>\n","protected":false},"author":42,"featured_media":108940,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28,576],"tags":[],"class_list":["post-108939","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","category-tirreno"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/108939","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=108939"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/108939\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/108940"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=108939"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=108939"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=108939"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}