{"id":108950,"date":"2019-04-24T13:29:48","date_gmt":"2019-04-24T11:29:48","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/liberiamoci-dagli-abbandoni-domani-ecologia-oggi-in-piazza-schettini\/"},"modified":"2023-01-16T18:26:27","modified_gmt":"2023-01-16T17:26:27","slug":"289610-liberiamoci-dagli-abbandoni-domani-ecologia-oggi-in-piazza-schettini","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/289610-liberiamoci-dagli-abbandoni-domani-ecologia-oggi-in-piazza-schettini\/","title":{"rendered":"Liberiamoci dagli abbandoni. Domani Ecologia Oggi in &#8220;Piazza Schettini\u200b&#8221;"},"content":{"rendered":"<h4><strong>Continuano le\u00a0<\/strong><strong>giornate in piazza dedicate all&#8217;informazione sulle buone pratiche ambientali e sui nuovi\u00a0<\/strong><strong>ecocalendari. Nella stessa giornata e sulla stessa piazza verr\u00e0 effettuata una raccolta straordinaria dell&#8217;olio vegetale esausto<\/strong><!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>COSENZA &#8211;\u00a0Gioved\u00ec 25\u00a0Aprile,\u00a0in occasione della Festa della Liberazione, a partire dalle ore 10.\u00a0<strong>Ecologia Oggi<\/strong> sar\u00e0 presente presso &#8220;Piazza Schettini&#8221; a Cosenza per incontrare l&#8217;utenza del quartiere via Popilia e distribuire le nuove brochure informative che in questa prima fase riguardano le utenze non domestiche (UND). Continua il progetto dell&#8217;azienda che per l&#8217;occasione \u00e8 stato denominato\u00a0<strong>&#8220;<\/strong><strong>liberiamoci\u00a0<\/strong><strong>dagli abbandoni&#8221;,\u00a0<\/strong>volto alla salvaguardia dell&#8217;ambiente, alla diffusione della cultura del non abbandono ed all&#8217;apprendimento del concetto di economia circolare, basata sul riciclo e riutilizzo dei materiali.<\/p>\n<p>Dagli episodi reiterati di abbandono illegale nasce il desiderio di\u00a0<strong>intervenire attivamente, diventando attori\u00a0<\/strong><strong>del\u00a0<\/strong><strong>cambiamento<\/strong>, per evitare che il degrado trasformi la citt\u00e0 di Cosenza in una discarica a cielo aperto.\u00a0Un&#8217;attivit\u00e0 importante per\u00a0<strong>promuovere la salvaguardia dell&#8217;ambiente e contrastare il fenomeno dell&#8217;abbandono dei rifiuti<\/strong>, che mortifica i luoghi della convivenza e offende la maggioranza dei cittadini che rispetta la natura e le buone pratiche ambientali: &#8220;<strong>liberiamoci\u00a0<\/strong><strong>dai rifiuti abbandonati e\u00a0<\/strong><strong>dalle cattive abitudini&#8221;<\/strong>\u00a0\u00e8 il messaggio con il quale si intende sensibilizzare l&#8217;utenza tutta sull&#8217;importanza di tenere pulita la nostra citt\u00e0.<\/p>\n<p><strong>Gioved\u00ec 25 Aprile 2019, dalle ore 10:00 alle ore 12:00 <\/strong>Ecologia oggi\u00a0sar\u00e0 presente in &#8220;Piazza Schettini&#8221; per illustrare il nuovo eco-calendario e le buone pratiche ambientali e chiedere ai cittadini, attraverso un questionario che potr\u00e0 essere redatto anche in forma anonima, il loro grado di soddisfazione. <strong>Nella stessa giornata e sulla stessa piazza verr\u00e0 effettuata una raccolta straordinaria dell&#8217;olio vegetale esausto<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Continuano le\u00a0giornate in piazza dedicate all&#8217;informazione sulle buone pratiche ambientali e sui nuovi\u00a0ecocalendari. Nella stessa giornata e sulla stessa piazza verr\u00e0 effettuata una raccolta straordinaria dell&#8217;olio vegetale esausto<\/p>\n","protected":false},"author":46,"featured_media":108951,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42,34,13,70],"tags":[],"class_list":["post-108950","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza","category-magazine","category-qui-green","category-quiecologia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/108950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=108950"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/108950\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/108951"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=108950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=108950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=108950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}