{"id":109030,"date":"2019-04-26T10:45:54","date_gmt":"2019-04-26T08:45:54","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/jole-santelli-calabria-commissariata-e-dimenticata-un-isolamento-senza-precedenti\/"},"modified":"2023-01-16T18:26:33","modified_gmt":"2023-01-16T17:26:33","slug":"289868-jole-santelli-calabria-commissariata-e-dimenticata-un-isolamento-senza-precedenti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/289868-jole-santelli-calabria-commissariata-e-dimenticata-un-isolamento-senza-precedenti\/","title":{"rendered":"Jole Santelli: &#8220;Calabria commissariata e dimenticata. Un isolamento senza precedenti&#8221;"},"content":{"rendered":"<h4 dir=\"auto\">La Coordinatrice regionale di Forza Italia &#8220;Calabria dimenticata dal Governo, abbandonata a se stessa e mal amministrata dal PD.\u00a0Per questo chiediamo un voto alle europee per Forza Italia&#8221;<\/h4>\n<p><!--more--><\/p>\n<div dir=\"auto\"><span style=\"color: #ffffff;\">.<\/span><\/div>\n<div dir=\"auto\">COSENZA &#8211; &#8220;<em><strong>La Calabria sta vivendo un isolamento senza precedenti<\/strong>. Il governo Conte in dieci mesi non ha avviato lo straccio di un cantiere in Calabria. La statale 106 \u00e8 sparita dall&#8217;agenda, i collegamenti jonici sono una vergogna. Nessun accenno all&#8217;alta velocit\u00e0 fino a Reggio Calabria e nessuna concreta attenzione verso i porti, da Gioia Tauro a Corigliano, giunge da Roma&#8221;<\/em>.<\/div>\n<div dir=\"auto\"><\/div>\n<div dir=\"auto\">Lo afferma con una nota J<strong>ole Santelli, coordinatrice regionale di Forza Italia,<\/strong> che chiede ai calabresi per le prossime elezioni europee un voto d&#8217;identit\u00e0\u00a0&#8220;<em><strong>Forza Italia si candida apertamente ad essere forza politica nazionale di tutela di un Sud<\/strong><\/em> <em>che \u00e8 considerato solo colonia da conquistare e non risorsa da valorizzare.\u00a0Ci danno una quantit\u00e0 di risorse\u00a0 nettamente inferiori rispetto al Nord e ci considerano quasi un ingombro, anche grazie alla insipienza di una giunta regionale che non \u00e8 stata in grado di muovere un dito contro le dimenticanze dei governi Renzi e Gentiloni prima e Conte oggi.\u00a0I<strong> calabresi non possono che votare per forze politiche che hanno sempre difeso e tutelato la loro regione<\/strong>, che sanno amministrare bene citt\u00e0 e comuni pur nella solitudine istituzionale in cui si trovano.\u00a0Per questo il 26 maggio chiediamo un voto<\/em> &#8211; conclude Santelli &#8211;\u00a0 <em>che mandi <strong>un segnale forte al potere centrale, che ha cancellato la Calabria dalla sua agenda<\/strong><\/em>&#8220;.<\/div>\n<div dir=\"auto\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La Coordinatrice regionale di Forza Italia &#8220;Calabria dimenticata dal Governo, abbandonata a se stessa e mal amministrata dal PD.\u00a0Per questo chiediamo un voto alle europee per Forza Italia&#8221;<\/p>\n","protected":false},"author":46,"featured_media":109031,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-109030","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/109030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=109030"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/109030\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/109031"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=109030"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=109030"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=109030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}