{"id":109070,"date":"2019-05-01T05:07:07","date_gmt":"2019-05-01T03:07:07","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/torna-in-citta-la-tre-giorni-del-cosenza-comics-and-games\/"},"modified":"2023-01-16T18:26:35","modified_gmt":"2023-01-16T17:26:35","slug":"290025-torna-in-citta-la-tre-giorni-del-cosenza-comics-and-games","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/290025-torna-in-citta-la-tre-giorni-del-cosenza-comics-and-games\/","title":{"rendered":"Cosenza Comics and Games. Torna in citt\u00e0 la &#8220;tre giorni&#8221; dedicata al fumetto &#8211; AUDIO"},"content":{"rendered":"<h4>Nuovi nomi e nuove divertenti attivit\u00e0 per la tre giorni del Cosenza Comics and Games, la grande fiera dedicata al mondo del fumetto, del gioco e della cultura pop che si tiene nella citt\u00e0 dei bruzi da cinque edizioni.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Torna in citt\u00e0 la &#8220;tre giorni&#8221; del Cosenza Comics and Games. <strong>Venerd\u00ec 10, sabato 11 e domenica 12 maggio<\/strong>, la Citt\u00e0 dei Ragazzi ospita questa quinta edizione che ha per<strong> tema \u201cRevolution\u201d<\/strong> per celebrare le importanti novit\u00e0 di questo amato settore.<\/p>\n<p>Rivoluzione anche nell\u2019allestimento del <strong>Cosenza Comics<\/strong> and Games: lo Scrigno Azzurro sar\u00e0 dedicato alle action figures e ai gadget del mondo pop; lo <strong>Scrigno Rosso<\/strong> ai fumetti, all\u2019arte e alle mostre; lo <strong>Scrigno Giallo<\/strong> all&#8217;area videogame e alle conferenze mentre l\u2019area verde esterna alle strutture ospiter\u00e0 attivit\u00e0 e giochi aperti a tutti: corse di \u201ccrazy kart\u201d, giochi di ruolo dal vivo, escape room e paintball. Sar\u00e0 presente una vasta sezione dedicata al mondo <strong>Pok\u00e9mon<\/strong> e uno spazio gestito dalla divisione italiana di Nintendo. Ci sar\u00e0, inoltre, il concerto, <strong>sabato 11<\/strong> maggio alle <strong>19.00<\/strong>, ispirato dalle colonne sonore del cinema, dei videogiochi e delle serie televisive fantasy con le <strong>Maidens of the Forest.<\/strong><\/p>\n<p>Tutti i dettagli sono stati illustrati ai microfoni di <strong>RLB da Sante Mazzei e Federico Formica<\/strong> che hanno organizzato l&#8217;evento<\/p>\n<h4><span style=\"color: #ff0000;\">ASCOLTA<\/span><br \/>\n<iframe loading=\"lazy\" src=\"https:\/\/w.soundcloud.com\/player\/?url=https%3A\/\/api.soundcloud.com\/tracks\/616385778&amp;color=%23ff5500&amp;auto_play=true&amp;hide_related=false&amp;show_comments=true&amp;show_user=true&amp;show_reposts=false&amp;show_teaser=true\" width=\"100%\" height=\"166\" frameborder=\"no\" scrolling=\"no\"><\/iframe><\/h4>\n<p><strong>Rob Di Salvo<\/strong>, disegnatore Marvel e Disney; gli autori di \u201cOlimpo: Gioie e Disagi\u201d, webcomic ironica sulle divinit\u00e0 dell&#8217;Olimpo e sulle loro disavventure; Laura Guglielmo di Attaccapanni Press sono i nuovi nomi che si aggiungono a quelli gi\u00e0 annunciati di Alessio Fortunato, autore di fumetti e disegnatore nell&#8217;attuale team di \u201cDampyr\u201d per Sergio Bonelli Editore; Elena Vitagliano, disegnatrice italiana che vive a Londra ed \u00e8 la prima donna europea a vincere il Silent Manga Audition; gli autori della casa editrice di settore Edizioni Npe. Ci saranno poi<strong> altri autori della Attaccapanni Press<\/strong>, label specializzata in autoproduzioni. In pi\u00f9 saranno coinvolti numerosi autori del territorio, tra fumettisti e illustratori, incluse giovani promesse del settore. Ma non \u00e8 ancora tutto. Per la prima volta a Cosenza sar\u00e0 presente un&#8217;importante esposizione di<strong> diorami Lego a tema Marvel, Star Wars<\/strong> e molto altro. Tutto grazie a ItLug, l\u2019Italian Lego Users Group, nato nel 1999 come comunit\u00e0 indipendente di appassionati Lego e divenuto associazione riconosciuta da <strong>\u201cThe Lego Group\u201d<\/strong>. ItLug partecipa al Cosenza Comics and Games, con un\u2019area espositiva costituita da opere realizzate da Afol (Adult Fan Of Lego), i quali esporranno oltre a set Lego ufficiali (delle linee Technic, Ideas, Brickheadz, Ninjago, Star Wars, Bionicle, Hero Factory e altro), anche diorami dedicati ai supereroi della Marvel, al mondo dei pirati, alle ambientazioni fantascientifiche, scenari cittadini, rievocazioni cinematografiche e televisive.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-290038\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/04\/Comics-cs2.jpg\" alt=\"\" width=\"600\" height=\"343\" title=\"\"><\/p>\n<p>Come sempre al Cosenza Comics and Games ci sar\u00e0 <strong>grande spazio per i cosplay<\/strong>. A gestire la gara cosplay di domenica 12 maggio sar\u00e0 il celebre gruppo \u201cEpicos\u201d. I concorrenti sfileranno sul palco proponendo performance, combattimenti, balletti, canzoni, monologhi e scene riguardanti il tema da loro scelto. Il Cosenza Comics and Games, proprio in collaborazione con Epicos, ospiter\u00e0 la prima tappa calabrese del Campionato nazionale cosplay 2019 che avr\u00e0 la sua finalissima al Lucca Comics &amp; Games.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-290570 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/04\/cosplay-2-711x400.jpg\" alt=\"\" width=\"599\" height=\"356\" title=\"\"><\/p>\n<p>La locandina di questa edizione \u00e8 stata realizzata da <strong>Valentina Brancati,<\/strong> insegnante di character design di Animazione e fumetto francese per il corso di Fumetto presso la Scuola internazionale di Comics di Roma. La Brancati ha realizzato la locandina del festival ritraendo i due lupi mascotte della fiera Alariko e Kepler come due giovani ribelli e rivoluzionari, in onore del tema di quest\u2019anno. Cosenza Comics and Games (che per l\u2019edizione 2019 vede come main sponsor il Cinema multisala Andromeda River di Zumpano; il birrificio artigianale Gladium gi\u00e0 premiata come la birra pi\u00f9 buona d&#8217;Italia; Adap &#8211; Accademia delle arti e delle professioni; Baboon &#8211; laboratorio di scenografia e scultura; Officine Chiodo e Genio in 21 giorni), in questi cinque anni, sta ripercorrendo ci\u00f2 che \u00e8 avvenuto per consolidate realt\u00e0 del fumetto italiano come avvenuto a Lucca, Roma e Napoli con l\u2019obiettivo di promuovere grandi novit\u00e0 rispetto alle \u201csemplici\u201d fiere comics and games.<\/p>\n<p><strong>Non solo fumetti, tornei e cinema,<\/strong> insomma, ma anche <strong>scienza, spettacolo, musica, grandi ospiti<\/strong> ed anteprime esclusive. Ogni anno il Cosenza Comics and Games \u00e8 fra gli <strong>eventi pi\u00f9 attesi di tutto il Sud Italia con i suoi 15mila visitatori<\/strong> che affollano la Citt\u00e0 dei Ragazzi grazie ai <strong>30 ospiti che partecipano alla tre giorni insieme ai circa 50 spettacoli, alle conferenze, incontri con gli autori e altro.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-290571 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/04\/01_pokemon_layout-k1JB-835x437@IlSole24Ore-Web-735x385.jpg\" alt=\"\" width=\"735\" height=\"385\" title=\"\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nuovi nomi e nuove divertenti attivit\u00e0 per la tre giorni del Cosenza Comics and Games, la grande fiera dedicata al mondo del fumetto, del gioco e della cultura pop che si tiene nella citt\u00e0 dei bruzi da cinque edizioni.<\/p>\n","protected":false},"author":42,"featured_media":109071,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[40],"tags":[],"class_list":["post-109070","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura-spettacolo"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/109070","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=109070"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/109070\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/109071"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=109070"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=109070"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=109070"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}