{"id":109138,"date":"2019-04-29T13:34:51","date_gmt":"2019-04-29T11:34:51","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/marion-le-pen-a-san-marco-argentano-altomonte-guardia-piemontese-e-paola\/"},"modified":"2023-01-16T18:26:40","modified_gmt":"2023-01-16T17:26:40","slug":"290317-marion-le-pen-a-san-marco-argentano-altomonte-guardia-piemontese-e-paola","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/290317-marion-le-pen-a-san-marco-argentano-altomonte-guardia-piemontese-e-paola\/","title":{"rendered":"Marion Le Pen domani a San Marco A., Altomonte, Guardia Piemontese e Paola"},"content":{"rendered":"<h4>La visita in Calabria di Marion, nipote di Marine Le Pen, domani in quattro comuni della provincia di Cosenza e l&#8217;omaggio a San Francesco di Paola<!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>COSENZA &#8211;\u00a0<strong>Marion Le Pen<\/strong>, nipote di Marine, storico leader dell&#8217;ultradestra francese,\u00a0sar\u00e0 domani in visita in Calabria esattamente nella provincia di Cosenza. <strong>La visita inizier\u00e0 alle 11:00 a San Marco Argentano<\/strong> e proseguir\u00e0 ad <strong>Altomonte<\/strong> e <strong>Guardia Piemontese<\/strong>. L&#8217;ultima tappa in Calabria di Marion Le Pen sar\u00e0 <strong>a Paola, dove visiter\u00e0 il santuario di San Francesco<\/strong>, che fu consigliere dei sovrani Luigi XI e Luigi XII e che \u00e8 sepolto a Tours, dove il fondatore dell&#8217;Ordine dei Minimi mor\u00ec nel 1507. Marion Le Pen<strong> render\u00e0 omaggio San Francesco di Paola<\/strong>, che fu molto legato alla Francia in occasione del 5<strong>00\/mo anniversario della sua canonizzazione<\/strong>.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/6825\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-290327\" src=\"https:\/\/quicosenza.it\/news\/6825\" alt=\"Marion Le Pen\" width=\"602\" height=\"401\" title=\"\"><\/a><\/p>\n<p>Marion Le Pen negli ultimi anni \u00e8 stata uno dei volti principali del <strong>Front National<\/strong>, partito che ha molti punti in comune con la Lega di Matteo Salvini. <strong>Fidanzata con Vincenzo Sofo<\/strong>, classe 1986, milanese figlio di calabresi, fondatore del blog &#8220;Il Talebano&#8221; \u00a0uno dei siti di riferimento della Lega.<strong> Sofo \u00e8 candidato con il partito del carroccio nella circoscrizione sud<\/strong> alle prossime<span style=\"color: #0000ff;\"> <a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/6737\" target=\"_blank\" rel=\"noopener\"><strong>elezioni europee<\/strong><\/a><\/span>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La visita in Calabria di Marion, nipote di Marine Le Pen, domani in quattro comuni della provincia di Cosenza e l&#8217;omaggio a San Francesco di Paola<\/p>\n","protected":false},"author":46,"featured_media":109139,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-109138","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/109138","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=109138"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/109138\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/109139"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=109138"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=109138"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=109138"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}