{"id":109276,"date":"2019-05-02T16:45:08","date_gmt":"2019-05-02T14:45:08","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/manda-sms-di-insulti-alla-ex-lei-non-lo-blocca-trentenne-assolto\/"},"modified":"2023-01-16T18:26:49","modified_gmt":"2023-01-16T17:26:49","slug":"290936-manda-sms-di-insulti-alla-ex-lei-non-lo-blocca-trentenne-assolto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/290936-manda-sms-di-insulti-alla-ex-lei-non-lo-blocca-trentenne-assolto\/","title":{"rendered":"Manda sms di insulti alla ex, lei non lo blocca: trentenne assolto"},"content":{"rendered":"<h4>Per la Cassazione non c&#8217;\u00e8 reato. Il ragazzo avrebbe agito in modo &#8221;ingenuo e maldestro&#8221; per riconquistare la sua ex fidanzata<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>ROMA\u00a0&#8211; Sentenza su un caso molestie in Calabria definisce quanti messaggi si possono inviare al proprio ex senza incorrere nel reato. Se l&#8217;altro non stoppa la comunicazione, attivando il blocco sul proprio telefono \u00e8 difficile capire quando il troppo \u00e8 troppo, e questo pu\u00f2 evitare una condanna. E&#8217; stato cos\u00ec per un trentenne di Catanzaro, assolto dalla Cassazione dall&#8217;accusa di molestie &#8220;perch\u00e9 il fatto non costituisce reato&#8221;. Dopo la fine della storia con la ex, <strong>non aveva interrotto la comunicazione, come chiesto invece da lei e ogni tanto si faceva vivo con un sms: 15 in due mesi e mezzo, un paio anche dal contenuto offensivo.<\/strong> Per questo era stato condannato a una multa per il reato di &#8220;molestia o disturbo alle persone&#8221;, previsto dall&#8217;articolo 660 del codice penale. Secondo la difesa dell&#8217;uomo che ha presentato ricorso in Cassazione, nel suo comportamento non vi era alcun motivo &#8220;biasimevole&#8221;, come prescrive la legge, semmai lo sforzo di riconciliazione lo aveva portato ad agire in modo &#8220;ingenuo e maldestro&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Il numero dei messaggi, poi, non era tale da poterlo considerare molesto e petulante: i<strong>l ragazzo, \u00e8 la scusante al suo agire, fa parte di una generazione che ha mutato il modo di intendere &#8220;la misura delle comunicazioni&#8221; e con quel comportamento non poteva &#8220;turbare o ledere la sfera della persona offesa&#8221;<\/strong>. Una spiegazione che ha convinto anche i giudici. La Cassazione ricorda che il reato di molestie contempla una condotta che non solo interferisca con la quiete altrui, ma che si caratterizzi per &#8220;petulanza o altro biasimevole motivo&#8221;: significa che va punito il comportamento &#8220;intollerabile e incivile verso la persona molestata&#8221; e &#8220;il modo di agire arrogante o vessatorio, privo di riguardo per la libert\u00e0 o la quiete altrui&#8221;, \u00e8 richiesta inoltre la volontariet\u00e0 della condotta.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Nel caso di questa coppia (sentenza n. 18216 della prima penale) invece la suprema Corte non ravvisa il dolo. &#8220;Assume certamente rilievo &#8211; secondo i giudici &#8211; il fatto oggettivo evidenziato dalla difesa dell&#8217;imputato che<strong> sul telefono della persona offesa non sia stato attivato il blocco<\/strong>&#8220;. E il tribunale non ha riscontrato &#8220;il dolo di petulanza dei messaggi, ma solo i tratti della possibile molestia degli stessi&#8221;: la storia era finita per decisione unilaterale di lei e i 15 messaggi &#8220;esprimevano essenzialmente amarezza provocata dalla interruzione del rapporto, gelosia e volont\u00e0 di incontrare di nuovo l&#8217;ex fidanzata per riallacciare la relazione&#8221;. Ma dalle motivazioni della sentenza non vi \u00e8 modo di ravvisare &#8220;il tipico atteggiamento psicologico inerente alla petulanza del comportamento&#8221; nei confronti dell&#8217;altro &#8220;fino al punto di determinarlo ad invocare aiuto&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Per la Cassazione non c&#8217;\u00e8 reato. Il ragazzo avrebbe agito in modo &#8221;ingenuo e maldestro&#8221; per riconquistare la sua ex fidanzata<\/p>\n","protected":false},"author":43,"featured_media":109277,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-109276","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/109276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=109276"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/109276\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/109277"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=109276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=109276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=109276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}