{"id":109278,"date":"2019-05-02T17:15:04","date_gmt":"2019-05-02T15:15:04","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/commerciati-tassati-con-cartelle-pazze-imposte-annullate\/"},"modified":"2023-01-16T18:26:49","modified_gmt":"2023-01-16T17:26:49","slug":"290938-commerciati-tassati-con-cartelle-pazze-imposte-annullate","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/290938-commerciati-tassati-con-cartelle-pazze-imposte-annullate\/","title":{"rendered":"\u00abEra un errore\u00bb, il Comune annulla le &#8216;tasse pazze&#8217; di 2.650 commercianti"},"content":{"rendered":"<h4>Annullati gli avvisi bonari, erroneamente inviati, per il pagamento dell&#8217;imposta sulle insegne inferiori ai 5 metri quadrati<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; E&#8217; stato un errore informatico a generare l&#8217;invio di avvisi bonari a 2.650 contribuenti per il pagamento di insegne inferiori ai 5 metri quadrati le quali, per norma nazionale, sono esenti dall&#8217;imposta. La commissione consiliare attivit\u00e0 economiche e produttive, presieduta da Annalisa Apicella, ha inteso fare chiarezza sulla vicenda che ha creato inevitabile scompiglio. A chiarire la natura dell&#8217;errore \u00e8 intervenuto Stefano Aquino, funzionario responsabile della concessionaria Municipia che gestisce la riscossione dei tributi per conto del Comune. Il tecnico ha partecipato alla Commissione insieme agli assessori Lino di Nardo e Loredana Pastore, rispettivamente delegati ai tributi e alle attivit\u00e0 economiche e produttive, e al dirigente del settore Tributi Giampiero Scaramuzzo. \u201cL&#8217;Amministrazione comunale \u2013 ha precisato l&#8217;assessore Di Nardo &#8211; \u00e8 <strong>prontamente intervenuta sulla societ\u00e0 Municipia, quegli avvisi sono da ritenersi annullati e le comunicazioni formali dell&#8217;avvenuto annullamento sono gi\u00e0 state spedite ai contribuenti interessati<\/strong>, senza aggravio di spese per il Comune\u201d. In commissione consiliare \u00e8 stato anche chiarito che eventuali pagamenti gi\u00e0 effettuati saranno rimborsati. Operatori di Municipia sono a disposizione per eventuali chiarimenti anche presso l&#8217;Ufficio tributi del Comune, nei giorni di ricevimento pubblico.<\/p>\n<p>&nbsp;<\/p>\n<p>https:\/\/quicosenza.it\/news\/le-notizie-dell-area-urbana-di-cosenza\/cosenza\/290520-bianca-rende-tassa-sullinsegna-cartelle-pazze-ai-commercianti-cosentini<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Annullati gli avvisi bonari, erroneamente inviati, per il pagamento dell&#8217;imposta sulle insegne inferiori ai 5 metri quadrati<\/p>\n","protected":false},"author":43,"featured_media":109279,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[42],"tags":[606],"class_list":["post-109278","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cosenza","tag-evasione-fiscale"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/109278","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=109278"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/109278\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/109279"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=109278"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=109278"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=109278"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}