{"id":109292,"date":"2019-05-03T10:38:03","date_gmt":"2019-05-03T08:38:03","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/dolce-biscotto-cerca-vera-famiglia-cane-e-padrone-sordi-comunicano-con-i-segni\/"},"modified":"2023-01-16T18:26:49","modified_gmt":"2023-01-16T17:26:49","slug":"290968-dolce-biscotto-cerca-vera-famiglia-cane-e-padrone-sordi-comunicano-con-i-segni","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/290968-dolce-biscotto-cerca-vera-famiglia-cane-e-padrone-sordi-comunicano-con-i-segni\/","title":{"rendered":"&#8220;Biscotto&#8221; cerca una famiglia vera. Cane e padrone sordi comunicano con i segni"},"content":{"rendered":"<h4>Il nome \u00e8 davvero azzeccato: Biscotto \u00e8 un cagnolino dolce che viveva in condizioni non idonee ed ora \u00e8 in attesa di una nuova famiglia. Poi la storia di amicizia e condivisione che arriva dagli USA<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<h3>Biscotto<\/h3>\n<p>Le volontarie conoscono il suo passato, ma \u00e8 necessario ora, scrivere il suo futuro perch\u00e8 biscotto, ha 5 anni ed \u00e8 un cagnolino educato, va al guinzaglio, conosce il rapporto con gli umani, ed \u00e8 simpatico e gioioso. E&#8217; compatibile con le femminucce. Ha avuto una vita difficile ma oggi \u00e8 pronto per andare da chi vorr\u00e0 accoglierlo a braccia aperte.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-291010 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/05\/biscotto.jpg\" alt=\"\" width=\"505\" height=\"639\" title=\"\"><\/p>\n<h4><span style=\"color: #ff0000;\">ASCOLTA la rubrica di questa settimana<\/span><br \/>\n[audio_mp3 url=&#8221;https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/05\/Quilazampa-biscotto-.mp3&#8243;]<\/h4>\n<h3 style=\"text-align: center;\">Cane e padrone non udenti, ma comunicano con la lingua dei segni<\/h3>\n<p>Nick ha 31 anni, ed ha adottato Emerson. I due condividono l&#8217;amore l&#8217;uno per l&#8217;altro ma soprattutto la stessa disabilit\u00e0 ovvero la sordit\u00e0. Ma la lingua dei segni ha abbattuto ogni barriera in questa storia che arriva dagli Stati Uniti, dal Maine.\u00a0Emerson \u00e8 un cucciolo di labrador, che \u00e8 stato proprio abbandonato a sole 6 settimane per la sua disabilit\u00e0. Portato\u00a0 in un rifugio in Florida \u00e8 stato messo in adozione da una volontaria.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-291011 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/05\/C_2_fotogallery_3097976_2_image.png\" alt=\"\" width=\"430\" height=\"501\" title=\"\"><\/p>\n<p>Quando Nick Abbott, 31enne ha visto il post su Facebook dalla volontaria ha risposto: &#8220;Sono sordo anch&#8217;io e sento che avremo un buon feeling&#8221;. E cos\u00ec ha deciso di adottarlo e per comunicare con lui, al piccolo labrador \u00e8 stato insegnato a comprendere gli ordini impartiti con la lingua dei segni.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\">Se vuoi scriverci per chiedere informazioni sui cani da adottare: <strong>redazione@quicosenza.it<\/strong> (nell\u2019oggetto indicare \u201c<strong>Qui la Zampa<\/strong>\u201c); Se invece vuoi adottare i cani, il giorno delle adozioni in canile a <strong>Donnici<\/strong> \u00e8 il<span style=\"color: #ff0000;\"><strong>\u00a0GIOVEDI&#8217;<\/strong><\/span>. Le adozioni al canile sanitario in contrada Acquafredda di <strong>Mendicino<\/strong> (Cs) invece, si possono effettuare di <span style=\"color: #ff0000;\"><strong>LUNED\u00cc<\/strong> <\/span>dalle 9:30 alle 12:30<\/p>\n<h3 style=\"text-align: center;\">Numeri utili per informazioni e\/o adozioni<\/h3>\n<p style=\"text-align: center;\">Letizia 327 636 2179<br \/>\nMaria Giulia 334 354 2780<br \/>\nTeresa 348 134 3975<br \/>\nNadia 389 051 7756<br \/>\nMaria Francesca 3917348381<\/p>\n<h4 style=\"text-align: center;\"><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/5314\" target=\"_blank\" rel=\"noopener\">\u00a0LEGGI TUTTI GLI ARTICOLI della rubrica &#8220;Qui la Zampa&#8221;<\/a><\/span><\/h4>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il nome \u00e8 davvero azzeccato: Biscotto \u00e8 un cagnolino dolce che viveva in condizioni non idonee ed ora \u00e8 in attesa di una nuova famiglia. Poi la storia di amicizia e condivisione che arriva dagli USA<\/p>\n","protected":false},"author":42,"featured_media":109293,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[47],"tags":[19],"class_list":["post-109292","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-qui-la-zampa","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/109292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=109292"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/109292\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/109293"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=109292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=109292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=109292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}