{"id":109311,"date":"2019-05-04T06:00:14","date_gmt":"2019-05-04T04:00:14","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/gougeres-la-ricetta-dei-bigne-salati-francesi\/"},"modified":"2023-01-16T18:26:51","modified_gmt":"2023-01-16T17:26:51","slug":"291039-gougeres-la-ricetta-dei-bigne-salati-francesi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/291039-gougeres-la-ricetta-dei-bigne-salati-francesi\/","title":{"rendered":"Goug\u00e8res: la facilissima ricetta dei bign\u00e8 salati francesi"},"content":{"rendered":"<h4>Da gustare semplici o da farcire con crema al formaggio\u00a0<!--more--><\/h4>\n<p>COSENZA &#8211; Goug\u00e8res: la ricetta pi\u00f9 facile. Ottimi con il gruy\u00e8re: in alternativa, sostituitelo con il parmigiano o un altro formaggio stagionato. I goug\u00e8res sono<strong> bign\u00e8 salati di origine francese<\/strong> da gustare semplici o da farcire con crema al formaggio. Una vera e propria delizia, ottima anche come antipasto.<\/p>\n<h3>Ingredienti<\/h3>\n<p>75 gr di gruy\u00e8re grattugiato<br \/>\n75 gr di burro<br \/>\n150 gr di farina<br \/>\n\u00bd litro di acqua<br \/>\n4 uova<br \/>\nPoco sale<\/p>\n<p>Tempo di preparazione: 15 minuti + 10 minuti di riposo. Tempo di cottura: 30 minuti<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-291042 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/05\/ham-stuffed-cheese-puffs-recipe-660x400.jpg\" alt=\"\" width=\"660\" height=\"400\" title=\"\"><\/p>\n<h3>Preparazione<\/h3>\n<p>In un pentolino capiente versare l\u2019acqua, aggiungere il burro, un pizzico di sale, e portare a ebollizione Appena il tutto bolle, togliere dal fuoco e aggiungere la farina tutta in una volta Farla assorbire mescolando energicamente con un cucchiaio di legno o una spatola Rimettere la pentola sul fuoco e fare addensare il composto: \u00e8 pronto quando si stacca dai bordi lasciandoli puliti Togliere dal fuoco e far raffreddare l\u2019impasto per dieci minuti circa. Aggiungere le uova, uno alla volta e facendo assorbire bene il precedente prima del successivo. Terminare con il gruy\u00e8re grattugiato Accendere il forno statico a 200 gradi. Foderare la placca del forno con la carta Con l\u2019aiuto della sac-a-poche, o semplicemente con due cucchiai, formare le goug\u00e8res, avendo cura di lasciare qualche centimetro di spazio tra una e l\u2019altra. Eventualmente prevedere di cuocerne un po\u2019 alla volta Infornare. Dopo circa 20 minuti controllare la cottura: devono presentarsi ben gonfie e dorate. Servirle subito, calde.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Da gustare semplici o da farcire con crema al formaggio\u00a0<\/p>\n","protected":false},"author":20,"featured_media":109312,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[63],"tags":[],"class_list":["post-109311","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gusto"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/109311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=109311"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/109311\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/109312"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=109311"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=109311"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=109311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}