{"id":109629,"date":"2019-05-10T06:53:56","date_gmt":"2019-05-10T04:53:56","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/maxi-confisca-di-beni-per-215-milioni-ad-un-imprenditore-legato-alla-ndrangheta\/"},"modified":"2023-01-16T18:27:13","modified_gmt":"2023-01-16T17:27:13","slug":"292171-maxi-confisca-di-beni-per-215-milioni-ad-un-imprenditore-legato-alla-ndrangheta","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/292171-maxi-confisca-di-beni-per-215-milioni-ad-un-imprenditore-legato-alla-ndrangheta\/","title":{"rendered":"Maxi confisca di beni per 215 milioni ad un imprenditore legato alla &#8216;ndrangheta"},"content":{"rendered":"<h4>La confisca ha riguarda un noto imprenditore ritenuto affiliato alla &#8216;ndrangheta. La Guardia di Finanza sta eseguendo la confisca in Calabria e in Campania<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>REGGIO CALABRIA &#8211; La Guardia di Finanza nelle sue componenti specialistiche e investigative del Servizio Centrale Investigazione Criminalit\u00e0 Organizzata, del Nucleo Speciale Polizia Valutaria e del Comando Provinciale Reggio Calabria, sotto il coordinamento della procura reggina, sta eseguendo un provvedimento del Tribunale di Reggio Calabria con cui \u00e8 stata disposta nei confronti di un noto <strong>imprenditore legato alla &#8216;ndrangheta<\/strong>.<\/p>\n<p>In particolare oltre all\u2019applicazione di misure di prevenzione, personali e patrimoniali, viene eseguita la confisca dell\u2019ingente patrimonio a lui riconducibile, per un valore complessivo stimato in circa <strong>215 milioni di euro.<\/strong> In sede giudiziaria \u00e8 emersa infatti <em>\u201cl\u2019esistenza di un indissolubile rapporto di cointeressenza economico-criminale tra l\u2019imprenditore e una cosca di \u2018ndrangheta, risalente alla prima met\u00e0 degli anni \u201980\u201d. <\/em><\/p>\n<h4>Alfonso Annunziata, cuore imprenditoriale del clan Piromalli<\/h4>\n<p>E&#8217; considerato il &#8220;cuore imprenditoriale&#8221; della cosca Piromalli di Gioia Tauro, Alfonso Annunziata, l&#8217;imprenditore reggino al quale la Guardia di finanza ha confiscato beni per 215 milioni di euro. In particolare, i finanzieri dello Scico, del Nucleo speciale polizia valutaria e del Comando provinciale Reggio Calabria, col coordinamento della Procura reggina diretta da Giovanni Bombardieri, hanno confiscato, in esecuzione di un provvedimento del Tribunale il compendio aziendale di due imprese, quote di 4 societ\u00e0 di capitali e di una societ\u00e0 di persone, 85 unit\u00e0 immobiliari, 46 rapporti finanziari personali e aziendali nonch\u00e9 denaro contante per quasi un milione di euro. All&#8217;imprenditore, inoltre, \u00e8 stata imposta la sorveglianza speciale di Ps per tre anni, con obbligo di soggiorno nel Comune di residenza. Il provvedimento si fonda sulle risultanze acquisite nell&#8217;operazione &#8220;Bucefalo&#8221; condotta dalla Guardia di finanza, nell&#8217;ambito della quale Annunziata, nel marzo 2015, fu arrestato.<\/p>\n<p>In questi giorni, al tribunale di Palmi, sono in corso le fasi finali del processo che lo vede imputato, tra l&#8217;altro, di associazione mafiosa. Secondo gli inquirenti Annunziata &#8220;non \u00e8 un imprenditore vittima, non \u00e8 stato e non \u00e8 costretto a favorire la cosca. Al contrario, \u00e8 un soggetto storicamente legato ai componenti di vertice della famiglia Piromalli ed \u00e8, dunque, un soggetto intraneo che si presta da oltre venti anni, volontariamente e consapevolmente, al perseguimento degli scopi imprenditoriali ed economici della cosca, cos\u00ec creando e sviluppando, nel tempo, solide cointeressenze economiche, accompagnate da ingenti investimenti commerciali nel territorio di Gioia Tauro&#8221;. Secondo gli inquirenti, il rapporto di cointeressenza economico-criminale tra Annunziata e i Piromalli sarebbe nato sin dalla prima met\u00e0 degli anni &#8217;80 e si sarebbe definitivamente sviluppato tra la fine del medesimo decennio e i primi anni &#8217;90.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La confisca ha riguarda un noto imprenditore ritenuto affiliato alla &#8216;ndrangheta. La Guardia di Finanza sta eseguendo la confisca in Calabria e in Campania<\/p>\n","protected":false},"author":42,"featured_media":109630,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-109629","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/109629","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=109629"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/109629\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/109630"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=109629"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=109629"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=109629"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}