{"id":109856,"date":"2019-05-15T12:48:41","date_gmt":"2019-05-15T10:48:41","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/maledetta-primavera-ancora-pioggia-e-freddo-allerta-meteo-della-protezione-civile\/"},"modified":"2023-01-16T18:27:29","modified_gmt":"2023-01-16T17:27:29","slug":"292888-maledetta-primavera-ancora-pioggia-e-freddo-allerta-meteo-della-protezione-civile","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/292888-maledetta-primavera-ancora-pioggia-e-freddo-allerta-meteo-della-protezione-civile\/","title":{"rendered":"Maledetta primavera: ancora pioggia e freddo. Allerta meteo della Protezione Civile"},"content":{"rendered":"<h4>Continua la fase perturbata su tutta la Calabria, in un contesto climatico particolarmente fresco per il periodo.\u00a0Una nuova discesa di aria fredda dar\u00e0 vigore al maltempo degli ultimi giorni. Allerta gialla e arancione della Protezione civile per oggi\u00a0 pomeriggio e domani<!--more--><\/h4>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p>COSENZA &#8211;<strong> Continua l&#8217;anomalia climatica su tutta l&#8217;Italia<\/strong> con un mese di maggio sempre pi\u00f9 vestito da fine inverno che da &#8220;mite&#8221; primavera. L&#8217;alta pressione rimane lontana dal nostro Paese, esponendoci cos\u00ec ad\u00a0<strong>una serie di<span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"https:\/\/quicosenza.it\/news\/6961\" target=\"_blank\" rel=\"noopener\"> discese di aria fredda<\/a><\/span> dalla Scandinavia<\/strong> che non fanno altro che dare nuovo vigore al <strong>nucleo di bassa pressione<\/strong> presente da diversi giorni sul Mediterraneo e che in queste ultime ore si \u00e8 spostato sul basso Tirreno, portando un&#8217;<strong>ingente dose di maltempo<\/strong>\u00a0e instabilit\u00e0 diffusa con rovesci, temporali,<strong> grandinate <\/strong>(<strong>anche violente<\/strong>) e temperature decisamente al di sotto della media.<\/p>\n<h4>Ancora due giorni di piogge e temporali<\/h4>\n<p>Per i prossimi due giorni cambier\u00e0 poco visto che su tutta la Calabria avremo un <strong>clima\u00a0particolarmente perturbato<\/strong> e ancora\u00a0<strong>molto fresco<\/strong><em><strong>. <\/strong><\/em>Cieli molto nuvolosi o coperti per oggi pomeriggio con rovesci e locali temporali. Il maltempo si intensificher\u00e0 nel corso del pomeriggio-sera soprattutto sulla Calabria settentrionale e sui versanti tirrenici.\u00a0Domani non andr\u00e0 molto meglio: attesi ancora forti\u00a0<strong>rovesci e temporali diffusi, localmente anche intensi sulla Calabria meridionale<\/strong>\u00a0fino alle ore serali. Solo da venerd\u00ec mattina i cieli torneranno a rasserenarsi e le temperature tenderanno a risalire di qualche grado.<\/p>\n<h4>Allerta meteo della Protezione Civile<\/h4>\n<p>Sulla base dei fenomeni previsti il Centro Funzionale Multirischi dell&#8217;Arpacal, ha emesso il messaggio di allerta unificato di<strong> colore\u00a0giallo <\/strong>per rischio idrogeologico ed idraulico con temporali<strong> su tutto il territorio regionale<\/strong>\u00a0<strong>dalle 13:00 di oggi fino alla mezzanotte di\u00a0domani con<\/strong>\u00a0<strong>allerta arancione<\/strong>\u00a0<strong>sul reggino.<\/strong><\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/6962\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-292897\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/05\/allerta-meteo-283x400.jpg\" alt=\"arpacal allerta meteo\" width=\"348\" height=\"492\" title=\"\"><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Continua la fase perturbata su tutta la Calabria, in un contesto climatico particolarmente fresco per il periodo.\u00a0Una nuova discesa di aria fredda dar\u00e0 vigore al maltempo degli ultimi giorni. Allerta gialla e arancione della Protezione civile per oggi\u00a0 pomeriggio e domani<\/p>\n","protected":false},"author":46,"featured_media":109857,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[],"class_list":["post-109856","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/109856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=109856"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/109856\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/109857"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=109856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=109856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=109856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}