{"id":109970,"date":"2019-05-19T06:08:41","date_gmt":"2019-05-19T04:08:41","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/freddo-allarme-nazionale-per-rondini-e-rondoni-come-aiutarli\/"},"modified":"2023-01-16T18:27:37","modified_gmt":"2023-01-16T17:27:37","slug":"293323-freddo-allarme-nazionale-per-rondini-e-rondoni-come-aiutarli","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/293323-freddo-allarme-nazionale-per-rondini-e-rondoni-come-aiutarli\/","title":{"rendered":"Freddo: allarme nazionale per rondini e rondoni. Come aiutarli"},"content":{"rendered":"<h4>Il freddo anomalo che ha caratterizzato la prima met\u00e0 di maggio ha sorpreso anche gli uccelli migratori che proprio in questo periodo fanno ritorno nel nostro Paese.<!--more--><\/h4>\n<p>&nbsp;<\/p>\n<p>COSENZA &#8211; Freddo: sono tantissimi i volatili, in particolare rondini e rondoni, che tentano di trovare riparo sui terrazzi o addirittura all&#8217;interno delle abitazioni. Storditi dal freddo, stremati dalla fame e dal vento, per\u00f2, moltissimi non sopravvivono.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-293332 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/05\/rondini_765-617x400.jpg\" alt=\"\" width=\"617\" height=\"400\" title=\"\"><\/p>\n<p><strong>Ma cosa fare?<\/strong> Se si trova un uccello privo di sensi sul terrazzo o in casa, la Lipu consiglia di non mandarlo via, ma di proteggerlo in una scatola di cartone bucata e di non toccarli troppo. A\u00a0rondini e rondoni bisogna dare da mangiare piccoli pezzi di carne cruda, mentre dovrebbero bere acqua zuccherata per recuperare le forze e rimanere idratati. Dopo queste semplici cure, gli uccelli potranno essere liberati.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il freddo anomalo che ha caratterizzato la prima met\u00e0 di maggio ha sorpreso anche gli uccelli migratori che proprio in questo periodo fanno ritorno nel nostro Paese.<\/p>\n","protected":false},"author":20,"featured_media":109971,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[34,13],"tags":[],"class_list":["post-109970","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-magazine","category-qui-green"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/109970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=109970"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/109970\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/109971"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=109970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=109970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=109970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}