{"id":110018,"date":"2019-05-19T17:24:05","date_gmt":"2019-05-19T15:24:05","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/senza-categoria\/il-parco-acquatico-di-rende-presentato-ai-cittadini-foto\/"},"modified":"2023-01-16T18:27:40","modified_gmt":"2023-01-16T17:27:40","slug":"293459-il-parco-acquatico-di-rende-presentato-ai-cittadini-foto","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/293459-il-parco-acquatico-di-rende-presentato-ai-cittadini-foto\/","title":{"rendered":"Il Parco Acquatico di Rende presentato ai cittadini (FOTO)"},"content":{"rendered":"<h4>La struttura a partire da oggi sar\u00e0 aperta al pubblico per attivit\u00e0 sportive e ludiche, mentre per la balneazione bisogner\u00e0 attendere il mese di giugno<\/h4>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>RENDE (CS) &#8211; Grande successo per la presentazione del\u00a0<a href=\"https:\/\/quicosenza.it\/news\/7001\" target=\"_blank\" rel=\"noopener\"><span style=\"color: #0000ff;\"><em><strong>Parco Acquatico Santa Chiara<\/strong><\/em><\/span><\/a> 4.0. Oggi pomeriggio le attivit\u00e0 della struttura sono state presentate alla cittadinanza. Decine di persone hanno affollato l&#8217;area tra i laghetti e l&#8217;edificio polifunzionale in vista dell&#8217;imminente apertura della stagione estiva. Una festa in grande stile con tanta musica, animazioni, spettacolo acquatico e fuochi pirotecnici . Un&#8217;anteprima fortemente voluta dagli imprenditori che si sono aggiudicati la gestione del parco cittadino destinato a diventare il luogo d&#8217;incontro, sport e benessere pi\u00f9 importante dell&#8217;intera area urbana. Il Parco Acquatico gi\u00e0 da oggi \u00e8<strong> in grado di accogliere i visitatori per le attivit\u00e0 sportive e culturali, mentre bisogner\u00e0 attendere giugno per usufruire dell&#8217;area balneabile e navigabile.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-293465 size-full\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/05\/parco-acquatico.jpg\" alt=\"\" width=\"1600\" height=\"777\" title=\"\"><\/p>\n<p>\u00abVogliamo investire in questa struttura e continuare a migliorarla. Abbiamo analizzato il bando pubblicato dal Comune di Rende per affidare la gestione della struttura &#8211; spiega Francesco Nasso del Consiglio di amministrazione del consorzio ConEdil Federimprese &#8211; e abbiamo valutato che <strong>nel nostro consorzio ci sono degli imprenditori che hanno i requisiti tecnici, economici e amministrativi per affrontare questa sfida.<\/strong> Siamo stati l&#8217;unico soggetto a proporre un&#8217;offerta dopo due gare andate deserte e ci siamo aggiudicati la gestione. Dopo l&#8217;aggiudicazione abbiamo costituito la societ\u00e0 di progetto un gruppo di aziende e professionisti chiamati a far funzionare la struttura. Tra queste vi sono oltre al ConEdilTST group che si occupa di efficientamento energetico e la ASC Calabria ente di promozione sportiva e sociale riconosciuto dal CONI\u00bb.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-293470 size-full\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/05\/WhatsApp-Image-2019-05-19-at-18.52.23.jpeg\" alt=\"\" width=\"1600\" height=\"777\" title=\"\"><\/p>\n<p>\u00ab<strong>Le attivit\u00e0 partiranno ufficialmente il 9 giugno in concomitanza con la chiusura delle scuole<\/strong> &#8211; spiega Ruggero Runco, uno dei gestori della struttura &#8211;\u00a0 quando inaugureremo la piscina all&#8217;aperto con tutte le offerte rivolte ad adulti e bambini. Il Parco si prefigge l&#8217;obiettivo di dare alla cittadinanza la possibilit\u00e0 di accedere in un luogo con una miriade di opzioni da scegliere per fare sport e divertirsi: campo di calcio polivalente, piscina coperta, palestra con moderne attrezzature, centro benessere, area giochi per i pi\u00f9 piccoli con giostre anche per disabili, campo da minigolf. Oltre a ci\u00f2 a partire da giugno saranno attivati baby parking, campi estivi e iniziative ludiche. Il lago navigabile prevede la possibilit\u00e0 di usare piccole imbarcazioni e di rifocillarsi all&#8217;interno del bar, ristorante, gelateria che si trova al suo centro\u00bb.<\/p>\n<h2><span style=\"color: #ff0000;\">FOTOGALLERY A CURA DI MARCO BELMONTE<\/span><\/h2>\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-293505\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/05\/parcoacquatico2101-440x244.jpg\" alt=\"\" width=\"440\" height=\"244\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-293504\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/05\/parcoacquatico2001-440x244.jpg\" alt=\"\" width=\"440\" height=\"244\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-293503\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/05\/parcoacquatico1901-440x244.jpg\" alt=\"\" width=\"440\" height=\"244\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-293502\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/05\/parcoacquatico1801-440x244.jpg\" alt=\"\" width=\"440\" height=\"244\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-293500\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/05\/parcoacquatico1701-440x244.jpg\" alt=\"\" width=\"440\" height=\"244\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-293495\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/05\/parcoacquatico1201-440x244.jpg\" alt=\"\" width=\"440\" height=\"244\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-293496\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/05\/parcoacquatico1301-440x244.jpg\" alt=\"\" width=\"440\" height=\"244\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-293497\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/05\/parcoacquatico1401-440x244.jpg\" alt=\"\" width=\"440\" height=\"244\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-293498\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/05\/parcoacquatico1501-440x244.jpg\" alt=\"\" width=\"440\" height=\"244\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-293499\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/05\/parcoacquatico1601-440x244.jpg\" alt=\"\" width=\"440\" height=\"244\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-293494\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/05\/parcoacquatico1101-440x244.jpg\" alt=\"\" width=\"440\" height=\"244\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-293493\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/05\/parcoacquatico1001-440x244.jpg\" alt=\"\" width=\"440\" height=\"244\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-293491\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/05\/parcoacquatico801-440x244.jpg\" alt=\"\" width=\"440\" height=\"244\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-293492\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/05\/parcoacquatico901-440x244.jpg\" alt=\"\" width=\"440\" height=\"244\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-293490\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/05\/parcoacquatico701-440x244.jpg\" alt=\"\" width=\"440\" height=\"244\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-293485\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/05\/parcoacquatico201-440x244.jpg\" alt=\"\" width=\"440\" height=\"244\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-293486\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/05\/parcoacquatico301-440x244.jpg\" alt=\"\" width=\"440\" height=\"244\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-293487\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/05\/parcoacquatico401-440x244.jpg\" alt=\"\" width=\"440\" height=\"244\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-293488\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/05\/parcoacquatico501-440x244.jpg\" alt=\"\" width=\"440\" height=\"244\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-293489\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/05\/parcoacquatico601-440x244.jpg\" alt=\"\" width=\"440\" height=\"244\" title=\"\"> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-293484\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2019\/05\/parcoacquatico101-440x244.jpg\" alt=\"\" width=\"440\" height=\"244\" title=\"\"><\/p>\n<p>https:\/\/quicosenza.it\/news\/le-notizie-dell-area-urbana-di-cosenza\/rende\/202089-rende-lacqua-del-parco-santa-chiara-e-limprenditore-fantasma<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>https:\/\/quicosenza.it\/news\/le-notizie-dell-area-urbana-di-cosenza\/rende\/82399-parco-acquatico-rende-cosenza-santa-chiara-piscina<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La struttura a partire da oggi sar\u00e0 aperta al pubblico per attivit\u00e0 sportive e ludiche, mentre per la balneazione bisogner\u00e0 attendere il mese di giugno<\/p>\n","protected":false},"author":43,"featured_media":110019,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[44],"tags":[],"class_list":["post-110018","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/110018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/43"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=110018"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/110018\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/110019"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=110018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=110018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=110018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}